{"id":2123,"date":"2018-08-06T07:50:25","date_gmt":"2018-08-06T05:50:25","guid":{"rendered":"https:\/\/lamostradevalencia.com\/el-festival\/seccions\/seccio-informativa\/"},"modified":"2019-10-04T13:25:26","modified_gmt":"2019-10-04T11:25:26","slug":"seccio-informativa","status":"publish","type":"page","link":"https:\/\/lamostradevalencia.com\/ca\/edicio-2019\/seccio-informativa\/","title":{"rendered":"Secci\u00f3 Informativa"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css=\u00bb.vc_custom_1538589096442{padding-top: 90px !important;padding-right: 40px !important;padding-left: 40px !important;}\u00bb][vc_column]<div class=\"edgtf-portfolio-list-holder edgtf-pl-masonry  edgtf-large-space edgtf-pl-three-columns edgtf-pl-standard-shader    edgtf-pl-pag-no-pagination     \"  data-type=masonry data-space-between-items=large data-number-of-items=-1 data-image-proportions=full data-enable-fixed-proportions=no data-enable-image-shadow=no data-category=seccio-informativa-2019 data-orderby=date data-order=ASC data-item-style=standard-shader data-enable-title=yes data-title-tag=h4 data-enable-category=yes data-enable-count-images=yes data-enable-excerpt=no data-excerpt-length=20 data-pagination-type=no-pagination data-filter=no data-filter-order-by=name data-enable-article-animation=no data-portfolio-slider-on=no data-enable-loop=yes data-enable-autoplay=yes data-slider-speed=5000 data-slider-speed-animation=600 data-enable-navigation=yes data-enable-pagination=yes data-max-num-pages=0 data-next-page=2>\n\t\t<div class=\"edgtf-pl-inner edgtf-outer-space clearfix\">\n\t\t<div class=\"edgtf-pl-grid-sizer\"><\/div>\n\t\t<div class=\"edgtf-pl-grid-gutter\"><\/div>\n\t\t<article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-default post-4083 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-festival-2019-ca portfolio-category-seccio-informativa-2019 portfolio-tag-ladj-ly-ca portfolio-tag-mostra-de-valencia-ca-2 portfolio-tag-seccion-informativa-ca\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1296\" height=\"730\" src=\"https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Los-Miserables.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Los-Miserables.jpg 1296w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Los-Miserables-300x169.jpg 300w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Los-Miserables-768x433.jpg 768w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Los-Miserables-1024x577.jpg 1024w\" sizes=\"auto, (max-width: 1296px) 100vw, 1296px\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" >\n\t\tLos miserables\t<\/h4>\n\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/lamostradevalencia.com\/ca\/categoria-portfolio-1\/festival-2019-ca\/\">Festival 2019<\/a>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/lamostradevalencia.com\/ca\/categoria-portfolio-1\/seccio-informativa-2019\/\">Secci\u00f3 Informativa 2019<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/lamostradevalencia.com\/ca\/peliculas\/los-miserables\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-default post-4082 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-festival-2019-ca portfolio-category-seccio-informativa-2019 portfolio-tag-documental-ca-2 portfolio-tag-futbol-ca portfolio-tag-mostra-de-valencia-ca-2 portfolio-tag-naziha-arebi-ca portfolio-tag-seccion-informativa-ca\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1239\" height=\"696\" src=\"https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Freedom-Fields.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Freedom-Fields.jpg 1239w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Freedom-Fields-300x169.jpg 300w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Freedom-Fields-768x431.jpg 768w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Freedom-Fields-1024x575.jpg 1024w\" sizes=\"auto, (max-width: 1239px) 100vw, 1239px\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" >\n\t\tFreedom Fields\t<\/h4>\n\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/lamostradevalencia.com\/ca\/categoria-portfolio-1\/festival-2019-ca\/\">Festival 2019<\/a>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/lamostradevalencia.com\/ca\/categoria-portfolio-1\/seccio-informativa-2019\/\">Secci\u00f3 Informativa 2019<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/lamostradevalencia.com\/ca\/peliculas\/freedom-fields\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-default post-4081 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-festival-2019-ca portfolio-category-seccio-informativa-2019 portfolio-tag-activisme portfolio-tag-animacio portfolio-tag-documental-ca-2 portfolio-tag-mostra-de-valencia-ca-2 portfolio-tag-seccion-informativa-ca\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"675\" src=\"https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Zero-Impunity.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Zero-Impunity.jpg 1200w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Zero-Impunity-300x169.jpg 300w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Zero-Impunity-768x432.jpg 768w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Zero-Impunity-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" >\n\t\tZero Impunity\t<\/h4>\n\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/lamostradevalencia.com\/ca\/categoria-portfolio-1\/festival-2019-ca\/\">Festival 2019<\/a>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/lamostradevalencia.com\/ca\/categoria-portfolio-1\/seccio-informativa-2019\/\">Secci\u00f3 Informativa 2019<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/lamostradevalencia.com\/ca\/peliculas\/zero-impunity\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-default post-4080 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-festival-2019-ca portfolio-category-seccio-informativa-2019 portfolio-tag-margarida-gil-ca portfolio-tag-maria-de-medeiros-ca portfolio-tag-mostra-de-valencia-ca-2 portfolio-tag-seccion-informativa-ca\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1088\" src=\"https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Mar.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Mar.jpg 1920w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Mar-300x170.jpg 300w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Mar-768x435.jpg 768w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Mar-1024x580.jpg 1024w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" >\n\t\tMar\t<\/h4>\n\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/lamostradevalencia.com\/ca\/categoria-portfolio-1\/festival-2019-ca\/\">Festival 2019<\/a>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/lamostradevalencia.com\/ca\/categoria-portfolio-1\/seccio-informativa-2019\/\">Secci\u00f3 Informativa 2019<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/lamostradevalencia.com\/ca\/peliculas\/mar\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-default post-4079 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-festival-2019-ca portfolio-category-seccio-informativa-2019 portfolio-tag-chema-cardena-ca portfolio-tag-cinema-valencia portfolio-tag-mostra-de-valencia-ca-2 portfolio-tag-seccion-informativa-ca portfolio-tag-vicente-monsonis-ca\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"3840\" height=\"2160\" src=\"https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Matar-al-Rey.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Matar-al-Rey.jpg 3840w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Matar-al-Rey-300x169.jpg 300w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Matar-al-Rey-768x432.jpg 768w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Matar-al-Rey-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 3840px) 100vw, 3840px\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" >\n\t\tMatar al rey\t<\/h4>\n\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/lamostradevalencia.com\/ca\/categoria-portfolio-1\/festival-2019-ca\/\">Festival 2019<\/a>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/lamostradevalencia.com\/ca\/categoria-portfolio-1\/seccio-informativa-2019\/\">Secci\u00f3 Informativa 2019<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/lamostradevalencia.com\/ca\/peliculas\/matar-al-rey\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-default post-4078 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-festival-2019-ca portfolio-category-seccio-informativa-2019 portfolio-tag-anais-demoustier-ca portfolio-tag-fabrice-luchini-ca portfolio-tag-mostra-de-valencia-ca-2 portfolio-tag-nicolas-pariser-ca portfolio-tag-seccion-informativa-ca\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1067\" src=\"https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Los-consejos-de-Alice.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Los-consejos-de-Alice.jpg 1600w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Los-consejos-de-Alice-300x200.jpg 300w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Los-consejos-de-Alice-768x512.jpg 768w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Los-consejos-de-Alice-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" >\n\t\tLos consejos de Alice\t<\/h4>\n\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/lamostradevalencia.com\/ca\/categoria-portfolio-1\/festival-2019-ca\/\">Festival 2019<\/a>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/lamostradevalencia.com\/ca\/categoria-portfolio-1\/seccio-informativa-2019\/\">Secci\u00f3 Informativa 2019<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/lamostradevalencia.com\/ca\/peliculas\/los-consejos-de-alice\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-default post-4077 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-festival-2019-ca portfolio-category-seccio-informativa-2019 portfolio-tag-mostra-de-valencia-ca-2 portfolio-tag-noor-gharzeddine-ca portfolio-tag-seccion-informativa-ca\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"675\" src=\"https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Are-You-Glad-Im-Here.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Are-You-Glad-Im-Here.jpg 1200w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Are-You-Glad-Im-Here-300x169.jpg 300w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Are-You-Glad-Im-Here-768x432.jpg 768w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Are-You-Glad-Im-Here-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" >\n\t\tAre you glad I&#8217;m here\t<\/h4>\n\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/lamostradevalencia.com\/ca\/categoria-portfolio-1\/festival-2019-ca\/\">Festival 2019<\/a>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/lamostradevalencia.com\/ca\/categoria-portfolio-1\/seccio-informativa-2019\/\">Secci\u00f3 Informativa 2019<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/lamostradevalencia.com\/ca\/peliculas\/are-you-glad-im-here\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-default post-4065 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-festival-2019-ca portfolio-category-seccio-informativa-2019 portfolio-tag-cinema-valencia portfolio-tag-lucia-alemany-ca portfolio-tag-mostra-de-valencia-ca-2 portfolio-tag-seccion-informativa-ca\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"900\" src=\"https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/La-inocencia.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/La-inocencia.jpg 1600w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/La-inocencia-300x169.jpg 300w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/La-inocencia-768x432.jpg 768w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/La-inocencia-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" >\n\t\tLa inocencia\t<\/h4>\n\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/lamostradevalencia.com\/ca\/categoria-portfolio-1\/festival-2019-ca\/\">Festival 2019<\/a>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/lamostradevalencia.com\/ca\/categoria-portfolio-1\/seccio-informativa-2019\/\">Secci\u00f3 Informativa 2019<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/lamostradevalencia.com\/ca\/peliculas\/la-inocencia\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-default post-4064 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-festival-2019-ca portfolio-category-seccio-informativa-2019 portfolio-tag-bassam-jarbawi-ca portfolio-tag-mostra-de-valencia-ca-2 portfolio-tag-palestina-ca portfolio-tag-seccion-informativa-ca\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"687\" src=\"https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Mafak-1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Mafak-1.jpg 1200w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Mafak-1-300x172.jpg 300w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Mafak-1-768x440.jpg 768w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Mafak-1-1024x586.jpg 1024w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" >\n\t\tMafak\t<\/h4>\n\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/lamostradevalencia.com\/ca\/categoria-portfolio-1\/festival-2019-ca\/\">Festival 2019<\/a>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/lamostradevalencia.com\/ca\/categoria-portfolio-1\/seccio-informativa-2019\/\">Secci\u00f3 Informativa 2019<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/lamostradevalencia.com\/ca\/peliculas\/mafak\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-default post-4063 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-festival-2019-ca portfolio-category-seccio-informativa-2019 portfolio-tag-egipto-ca portfolio-tag-marwan-hamed-ca portfolio-tag-mostra-de-valencia-ca-2 portfolio-tag-seccion-informativa-ca\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1271\" height=\"547\" src=\"https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Diamond-Dust.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Diamond-Dust.jpg 1271w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Diamond-Dust-300x129.jpg 300w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Diamond-Dust-768x331.jpg 768w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Diamond-Dust-1024x441.jpg 1024w\" sizes=\"auto, (max-width: 1271px) 100vw, 1271px\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" >\n\t\tDiamond Dust\t<\/h4>\n\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/lamostradevalencia.com\/ca\/categoria-portfolio-1\/festival-2019-ca\/\">Festival 2019<\/a>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/lamostradevalencia.com\/ca\/categoria-portfolio-1\/seccio-informativa-2019\/\">Secci\u00f3 Informativa 2019<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/lamostradevalencia.com\/ca\/peliculas\/diamond-dust\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-default post-4062 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-festival-2019-ca portfolio-category-seccio-informativa-2019 portfolio-tag-catherine-deneuve-ca portfolio-tag-ethan-hawke-ca portfolio-tag-hirokazu-koreeda-ca portfolio-tag-juliette-binoche-ca portfolio-tag-ludivine-sagnier-ca portfolio-tag-mostra-de-valencia-ca-2 portfolio-tag-seccion-informativa-ca\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"666\" height=\"1000\" src=\"https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/La-verdad.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/La-verdad.jpg 666w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/La-verdad-200x300.jpg 200w\" sizes=\"auto, (max-width: 666px) 100vw, 666px\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" >\n\t\tLa verdad\t<\/h4>\n\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/lamostradevalencia.com\/ca\/categoria-portfolio-1\/festival-2019-ca\/\">Festival 2019<\/a>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/lamostradevalencia.com\/ca\/categoria-portfolio-1\/seccio-informativa-2019\/\">Secci\u00f3 Informativa 2019<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/lamostradevalencia.com\/ca\/peliculas\/la-verdad\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-default post-4061 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-festival-2019-ca portfolio-category-seccio-informativa-2019 portfolio-tag-cinema-valencia portfolio-tag-juli-mira-ca portfolio-tag-mostra-de-valencia-ca-2 portfolio-tag-pedro-perez-rosado-ca portfolio-tag-seccion-informativa-ca portfolio-tag-victoria-salvador-ca\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1181\" height=\"647\" src=\"https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Una-dona-mab-unes-ales-tremendes.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Una-dona-mab-unes-ales-tremendes.jpg 1181w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Una-dona-mab-unes-ales-tremendes-300x164.jpg 300w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Una-dona-mab-unes-ales-tremendes-768x421.jpg 768w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Una-dona-mab-unes-ales-tremendes-1024x561.jpg 1024w\" sizes=\"auto, (max-width: 1181px) 100vw, 1181px\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" >\n\t\tUna dona amb unes ales tremendes\t<\/h4>\n\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/lamostradevalencia.com\/ca\/categoria-portfolio-1\/festival-2019-ca\/\">Festival 2019<\/a>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/lamostradevalencia.com\/ca\/categoria-portfolio-1\/seccio-informativa-2019\/\">Secci\u00f3 Informativa 2019<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/lamostradevalencia.com\/ca\/peliculas\/una-dona-amb-unes-ales-tremendes\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-default post-4060 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-festival-2019-ca portfolio-category-seccio-informativa-2019 portfolio-tag-marroc-ca portfolio-tag-mohamed-zineddaine-ca portfolio-tag-mostra-de-valencia-ca-2 portfolio-tag-seccion-informativa-ca\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"720\" src=\"https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/La-Gue\u0301risseuse.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/La-Gue\u0301risseuse.jpg 1280w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/La-Gue\u0301risseuse-300x169.jpg 300w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/La-Gue\u0301risseuse-768x432.jpg 768w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/La-Gue\u0301risseuse-1024x576.jpg 1024w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" >\n\t\tLa Gu\u00e9risseuse\t<\/h4>\n\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/lamostradevalencia.com\/ca\/categoria-portfolio-1\/festival-2019-ca\/\">Festival 2019<\/a>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/lamostradevalencia.com\/ca\/categoria-portfolio-1\/seccio-informativa-2019\/\">Secci\u00f3 Informativa 2019<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/lamostradevalencia.com\/ca\/peliculas\/la-guerisseuse\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-default post-4059 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-festival-2019-ca portfolio-category-seccio-informativa-2019 portfolio-tag-discapacitat portfolio-tag-margaux-bonhomme-ca portfolio-tag-mostra-de-valencia-ca-2 portfolio-tag-seccion-informativa-ca\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"878\" src=\"https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Head-Above-Water.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Head-Above-Water.jpg 1200w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Head-Above-Water-300x220.jpg 300w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Head-Above-Water-768x562.jpg 768w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Head-Above-Water-1024x749.jpg 1024w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" >\n\t\tHead above water\t<\/h4>\n\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/lamostradevalencia.com\/ca\/categoria-portfolio-1\/festival-2019-ca\/\">Festival 2019<\/a>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/lamostradevalencia.com\/ca\/categoria-portfolio-1\/seccio-informativa-2019\/\">Secci\u00f3 Informativa 2019<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/lamostradevalencia.com\/ca\/peliculas\/head-above-water\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article><article class=\"edgtf-pl-item edgtf-item-space edgtf-masonry-size-default post-4058 portfolio-item type-portfolio-item status-publish has-post-thumbnail hentry portfolio-category-festival-2019-ca portfolio-category-seccio-informativa-2019 portfolio-tag-discapacitat portfolio-tag-federico-bondi-ca portfolio-tag-mostra-de-valencia-ca-2 portfolio-tag-seccion-informativa-ca\">\n\t<div class=\"edgtf-pl-item-inner\">\n\t\t<div class=\"edgtf-pli-image\">\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1619\" height=\"1080\" src=\"https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Dafne.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Dafne.jpg 1619w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Dafne-300x200.jpg 300w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Dafne-768x512.jpg 768w, https:\/\/lamostradevalencia.com\/wp-content\/uploads\/2019\/10\/Dafne-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 1619px) 100vw, 1619px\" \/><\/div>\n<div class=\"edgtf-pli-text-holder\" >\n\t<div class=\"edgtf-pli-text-wrapper\">\n\t\t<div class=\"edgtf-pli-text\">\n\t\t\t\t<h4 itemprop=\"name\" class=\"edgtf-pli-title entry-title\" >\n\t\tDafne\t<\/h4>\n\n\t\t\t\t\t<div class=\"edgtf-pli-category-holder\">\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/lamostradevalencia.com\/ca\/categoria-portfolio-1\/festival-2019-ca\/\">Festival 2019<\/a>\n\t\t\t\t\t\t\t<a itemprop=\"url\" class=\"edgtf-pli-category\" href=\"https:\/\/lamostradevalencia.com\/ca\/categoria-portfolio-1\/seccio-informativa-2019\/\">Secci\u00f3 Informativa 2019<\/a>\n\t\t\t\t\t<\/div>\n\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<a itemprop=\"url\" class=\"edgtf-pli-link edgtf-block-drag-link\" href=\"https:\/\/lamostradevalencia.com\/ca\/peliculas\/dafne\/\" target=\"_self\"><\/a>\n\t<\/div>\n<\/article>\t<\/div>\n\t\n\t<\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css=\u00bb.vc_custom_1538589096442{padding-top: 90px !important;padding-right: 40px !important;padding-left: 40px !important;}\u00bb][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":3013,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"full-width.php","meta":{"_uag_custom_page_level_css":"","_jet_sm_ready_style":"","_jet_sm_style":"","_jet_sm_controls_values":"","_jet_sm_fonts_collection":"","_jet_sm_fonts_links":"","footnotes":""},"class_list":["post-2123","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Secci\u00f3 Informativa - Mostra de Val\u00e8ncia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lamostradevalencia.com\/ca\/edicio-2019\/seccio-informativa\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Secci\u00f3 Informativa - Mostra de Val\u00e8ncia\" \/>\n<meta property=\"og:description\" content=\"[vc_row css=\u00bb.vc_custom_1538589096442{padding-top: 90px !important;padding-right: 40px !important;padding-left: 40px !important;}\u00bb][vc_column][\/vc_column][\/vc_row]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lamostradevalencia.com\/ca\/edicio-2019\/seccio-informativa\/\" \/>\n<meta property=\"og:site_name\" content=\"Mostra de Val\u00e8ncia\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-04T11:25:26+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lamostradevalencia.com\\\/ca\\\/edicio-2019\\\/seccio-informativa\\\/\",\"url\":\"https:\\\/\\\/lamostradevalencia.com\\\/ca\\\/edicio-2019\\\/seccio-informativa\\\/\",\"name\":\"Secci\u00f3 Informativa - Mostra de Val\u00e8ncia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lamostradevalencia.com\\\/ca\\\/#website\"},\"datePublished\":\"2018-08-06T05:50:25+00:00\",\"dateModified\":\"2019-10-04T11:25:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lamostradevalencia.com\\\/ca\\\/edicio-2019\\\/seccio-informativa\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lamostradevalencia.com\\\/ca\\\/edicio-2019\\\/seccio-informativa\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lamostradevalencia.com\\\/ca\\\/edicio-2019\\\/seccio-informativa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lamostradevalencia.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Edici\u00f3 2019\",\"item\":\"https:\\\/\\\/lamostradevalencia.com\\\/ca\\\/edicion-2019\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Secci\u00f3 Informativa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lamostradevalencia.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/lamostradevalencia.com\\\/ca\\\/\",\"name\":\"Mostra de Val\u00e8ncia\",\"description\":\"Cinema del Mediterrani\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lamostradevalencia.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Secci\u00f3 Informativa - Mostra de Val\u00e8ncia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lamostradevalencia.com\/ca\/edicio-2019\/seccio-informativa\/","og_locale":"ca_ES","og_type":"article","og_title":"Secci\u00f3 Informativa - Mostra de Val\u00e8ncia","og_description":"[vc_row css=\u00bb.vc_custom_1538589096442{padding-top: 90px !important;padding-right: 40px !important;padding-left: 40px !important;}\u00bb][vc_column][\/vc_column][\/vc_row]","og_url":"https:\/\/lamostradevalencia.com\/ca\/edicio-2019\/seccio-informativa\/","og_site_name":"Mostra de Val\u00e8ncia","article_modified_time":"2019-10-04T11:25:26+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lamostradevalencia.com\/ca\/edicio-2019\/seccio-informativa\/","url":"https:\/\/lamostradevalencia.com\/ca\/edicio-2019\/seccio-informativa\/","name":"Secci\u00f3 Informativa - Mostra de Val\u00e8ncia","isPartOf":{"@id":"https:\/\/lamostradevalencia.com\/ca\/#website"},"datePublished":"2018-08-06T05:50:25+00:00","dateModified":"2019-10-04T11:25:26+00:00","breadcrumb":{"@id":"https:\/\/lamostradevalencia.com\/ca\/edicio-2019\/seccio-informativa\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lamostradevalencia.com\/ca\/edicio-2019\/seccio-informativa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lamostradevalencia.com\/ca\/edicio-2019\/seccio-informativa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lamostradevalencia.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Edici\u00f3 2019","item":"https:\/\/lamostradevalencia.com\/ca\/edicion-2019\/"},{"@type":"ListItem","position":3,"name":"Secci\u00f3 Informativa"}]},{"@type":"WebSite","@id":"https:\/\/lamostradevalencia.com\/ca\/#website","url":"https:\/\/lamostradevalencia.com\/ca\/","name":"Mostra de Val\u00e8ncia","description":"Cinema del Mediterrani","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lamostradevalencia.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"cinerama_edge_image_square":false,"cinerama_edge_image_landscape":false,"cinerama_edge_image_portrait":false,"cinerama_edge_image_huge":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"Mostra de Val\u00e8ncia","author_link":"https:\/\/lamostradevalencia.com\/ca\/author\/mostravalencia\/"},"uagb_comment_info":0,"uagb_excerpt":"[vc_row css=\u00bb.vc_custom_1538589096442{padding-top: 90px !important;padding-right: 40px !important;padding-left: 40px !important;}\u00bb][vc_column][\/vc_column][\/vc_row]","_links":{"self":[{"href":"https:\/\/lamostradevalencia.com\/ca\/wp-json\/wp\/v2\/pages\/2123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lamostradevalencia.com\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lamostradevalencia.com\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lamostradevalencia.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lamostradevalencia.com\/ca\/wp-json\/wp\/v2\/comments?post=2123"}],"version-history":[{"count":2,"href":"https:\/\/lamostradevalencia.com\/ca\/wp-json\/wp\/v2\/pages\/2123\/revisions"}],"predecessor-version":[{"id":4028,"href":"https:\/\/lamostradevalencia.com\/ca\/wp-json\/wp\/v2\/pages\/2123\/revisions\/4028"}],"up":[{"embeddable":true,"href":"https:\/\/lamostradevalencia.com\/ca\/wp-json\/wp\/v2\/pages\/3013"}],"wp:attachment":[{"href":"https:\/\/lamostradevalencia.com\/ca\/wp-json\/wp\/v2\/media?parent=2123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}