{"id":6894,"date":"2018-10-03T18:24:38","date_gmt":"2018-10-03T16:24:38","guid":{"rendered":"https:\/\/lamostradevalencia.com\/%d8%a7%d9%84%d8%a8%d8%b1%d9%86%d8%a7%d9%85%d8%ac\/"},"modified":"2020-09-15T18:47:27","modified_gmt":"2020-09-15T16:47:27","slug":"%d8%a7%d9%84%d8%a8%d8%b1%d9%86%d8%a7%d9%85%d8%ac","status":"publish","type":"page","link":"https:\/\/lamostradevalencia.com\/ar\/%d8%a7%d9%84%d8%a8%d8%b1%d9%86%d8%a7%d9%85%d8%ac\/","title":{"rendered":"\u0627\u0644\u0628\u0631\u0646\u0627\u0645\u062c"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1600188371980{padding-top: 90px !important;padding-right: 40px !important;padding-bottom: 50px !important;padding-left: 40px !important;}&#8221; anchor=&#8221;viernes-25&#8243;][vc_column]<div class=\"sched-loader\"><div class=\"sched-loader-icon\"><\/div><div class=\"sched-loader-text\"><\/div><\/div>\n<div class=\" sched sched-horizontal sched-horizontal-medium\" id=\"sched-schedule-9-1487908872\" data-options=\" {&quot;am_pm&quot;:&quot;0&quot;,&quot;sidebar_width&quot;:&quot;90&quot;,&quot;sidebar_position&quot;:&quot;left&quot;,&quot;event_hover_color&quot;:&quot;lighten&quot;,&quot;event_box_text_align&quot;:&quot;center&quot;,&quot;event_box_time&quot;:&quot;0&quot;,&quot;event_hover_text_color&quot;:&quot;#FFFFFF&quot;,&quot;event_hover_background_color&quot;:&quot;#000000&quot;,&quot;event_box_truncate_title&quot;:&quot;0&quot;,&quot;event_tooltip&quot;:&quot;0&quot;,&quot;event_tooltip_title&quot;:&quot;1&quot;,&quot;event_tooltip_time&quot;:&quot;1&quot;,&quot;event_tooltip_description&quot;:&quot;1&quot;,&quot;event_tooltip_width_type&quot;:&quot;event&quot;,&quot;event_tooltip_width&quot;:&quot;150&quot;,&quot;event_tooltip_color_type&quot;:&quot;event&quot;,&quot;event_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;event_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;column_tooltip&quot;:&quot;0&quot;,&quot;column_tooltip_title&quot;:&quot;1&quot;,&quot;column_tooltip_description&quot;:&quot;1&quot;,&quot;column_tooltip_width_type&quot;:&quot;column&quot;,&quot;column_tooltip_width&quot;:&quot;150&quot;,&quot;column_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;column_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;animations&quot;:&quot;1&quot;,&quot;animations_mobile&quot;:&quot;1&quot;,&quot;animations_speed&quot;:&quot;normal&quot;,&quot;animations_css3&quot;:&quot;1&quot;,&quot;tooltips_mobile&quot;:&quot;1&quot;,&quot;editor_bg&quot;:&quot;#F5F5F5&quot;,&quot;animations_editor&quot;:&quot;1&quot;,&quot;popup_max_width&quot;:&quot;560&quot;,&quot;popup_background_color&quot;:&quot;#ffffff&quot;,&quot;popup_text_color&quot;:&quot;#535353&quot;,&quot;popup_link_color&quot;:&quot;#ff4d00&quot;,&quot;autoplay_videos&quot;:&quot;1&quot;,&quot;column_color_bg&quot;:&quot;#e8e8e8&quot;,&quot;column_color_text&quot;:&quot;#3f3f3f&quot;,&quot;column_color_border&quot;:&quot;#ffffff&quot;,&quot;pattern_color_1&quot;:&quot;#ffffff&quot;,&quot;pattern_color_2&quot;:&quot;#e8e8e8&quot;,&quot;pattern_color_3&quot;:&quot;#ffffff&quot;,&quot;title_text_color&quot;:&quot;#3f3f3f&quot;,&quot;sidebar_text_color&quot;:&quot;#3f3f3f&quot;,&quot;event_box_text_color&quot;:&quot;#ffffff&quot;,&quot;title_attr&quot;:&quot;0&quot;,&quot;column_break&quot;:1,&quot;column_break_width&quot;:&quot;120&quot;,&quot;column_break_hide_sidebar&quot;:&quot;0&quot;,&quot;editor_custom_css&quot;:&quot;1&quot;,&quot;column_title&quot;:&quot;1&quot;,&quot;event_box_description_method&quot;:&quot;short&quot;,&quot;editor_quick_tooltips&quot;:&quot;1&quot;,&quot;editor_timepicker_increments&quot;:&quot;15&quot;,&quot;event_box_style&quot;:&quot;1&quot;,&quot;filter_position&quot;:&quot;right&quot;,&quot;filter_multiple&quot;:&quot;1&quot;,&quot;filter_hidden_events&quot;:&quot;hide&quot;,&quot;filter_hidden_events_opacity&quot;:&quot;30&quot;,&quot;filter_dropdown_width&quot;:&quot;100&quot;,&quot;filter_dropdown_hover_width&quot;:&quot;180&quot;,&quot;filter_dropdown_label&quot;:&quot;Secci\\u00f3n&quot;,&quot;filter_dropdown_show_all_label&quot;:&quot;Mostrar todo&quot;,&quot;hashtag_url&quot;:&quot;1&quot;,&quot;hide_popup_for_empty_events&quot;:&quot;1&quot;,&quot;event_box_padding_break&quot;:&quot;200&quot;,&quot;popup_arrows&quot;:&quot;1&quot;,&quot;filter_visible&quot;:&quot;1&quot;,&quot;column_break_action&quot;:&quot;list&quot;,&quot;list_view_column_title_color&quot;:&quot;#3f3f3f&quot;,&quot;list_view_event_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_hover_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_title_bold&quot;:&quot;1&quot;,&quot;list_view_event_bullets&quot;:&quot;2&quot;,&quot;list_view_event_short_description_method&quot;:&quot;short&quot;,&quot;list_view_event_description_color&quot;:&quot;#ffffff&quot;,&quot;list_view_hide_empty_columns&quot;:&quot;1&quot;,&quot;shortcodes_in_descriptions&quot;:&quot;1&quot;,&quot;columns_sticky_header&quot;:&quot;1&quot;,&quot;columns_sticky_header_offset&quot;:&quot;0&quot;,&quot;h_row_height&quot;:&quot;110&quot;,&quot;h_column_width&quot;:&quot;200&quot;,&quot;h_time_indicator&quot;:&quot;1&quot;,&quot;h_time_indicator_height&quot;:30,&quot;h_column_multiline&quot;:&quot;0&quot;,&quot;h_column_title_position&quot;:&quot;middle&quot;,&quot;h_column_title_align&quot;:&quot;center&quot;,&quot;h_break&quot;:&quot;0&quot;,&quot;h_width_break_point&quot;:&quot;200&quot;,&quot;h_bg_color&quot;:&quot;#f8f8f8&quot;,&quot;pdf_type&quot;:&quot;html&quot;,&quot;pdf_enable&quot;:&quot;0&quot;,&quot;pdf_enable_list&quot;:&quot;0&quot;,&quot;pdf_label&quot;:&quot;Download&quot;,&quot;pdf_css&quot;:&quot;&quot;,&quot;upcoming_type&quot;:&quot;current_datetime&quot;,&quot;upcoming_custom&quot;:&quot;2016-01-01 00:00&quot;,&quot;upcoming_limit&quot;:&quot;5&quot;,&quot;upcoming_title&quot;:&quot;timetable_title&quot;,&quot;upcoming_title_custom&quot;:&quot;Upcoming Events&quot;,&quot;upcoming_title_amount&quot;:&quot;1&quot;}\" data-start=\"11:00\" data-end=\"01:30\" data-timetable-id=\"9\" data-type=\"full\" data-list-id=\"#sched-schedule-9-1487908872-list\" data-layout=\"horizontal\">\t<div class=\"sched-style\"><style type=\"text\/css\">\/*\n * Custom CSS For Timetable\n*\/\n\n#sched-schedule-9-1487908872 .sched-column-header,\n#sched-schedule-9-1487908872 .sched-column-header-sticky {\n\tbackground: #e8e8e8;\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-9-1487908872 .sched-column-header:after,\n#sched-schedule-9-1487908872 .sched-column-header-sticky:after {\n\tbackground: #ffffff;\n}\n\n#sched-schedule-9-1487908872 .sched-columns .sched-column:last-child .sched-column-header:after,\n#sched-schedule-9-1487908872 .sched-columns .sched-column:last-child .sched-column-header-sticky:after {\n\tbackground: #e8e8e8;\n}\n\n#sched-schedule-9-1487908872 .sched-column-bg-block {\n\tbackground: #ffffff;\n\tborder-color: #e8e8e8;\n}\n\n#sched-schedule-9-1487908872 .sched-column-bg-block:after {\n\tbackground: #ffffff;\n}\n\n#sched-schedule-9-1487908872 .sched-row-no-title .sched-column .sched-column-bg {\n\tbox-shadow: 0 -1px 0 #e8e8e8;\n}\n\n#sched-schedule-9-1487908872 .sched-title {\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-9-1487908872 .sched-time-value {\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-9-1487908872 .sched-event .sched-event-inner {\n\tcolor: #ffffff;\n\ttext-align: center;\n}\n\n#sched-schedule-9-1487908872 .sched-event.sched-event-invert .sched-event-inner {\n\t<!-- background: #999; -->\n}\n\n\n\n\/*#sched-schedule-9-1487908872 a.sched-event.sched-event-sort-hidden {\n\topacity: 0;\n}*\/\n\n#sched-schedule-9-1487908872 .sched-sort .sched-sort-current .sched-sort-current-label {\n\twidth: 100px;\n}\n\n#sched-schedule-9-1487908872 .sched-sort.sched-sort-open .sched-sort-dropdown .sched-sort-current .sched-sort-current-label {\n\twidth: 180px;\n}\n\n\/*\n * Custom CSS Event Popup\n *\/\n\n#sched-schedule-9-1487908872-popup .sched-popup-description {\n\t\n}\n\n#sched-schedule-9-1487908872-popup .sched-popup-description .sched-meta a,\n#sched-schedule-9-1487908872-popup .sched-popup-description .sched-popup-description-text a {\n\tcolor: #ff4d00;\n}\n\n#sched-schedule-9-1487908872-popup .sched-popup-description .sched-meta,\n#sched-schedule-9-1487908872-popup .sched-popup-description .sched-popup-description-text {\n\tcolor: #535353;\n\tbackground: #ffffff;\n}\n\n\/*\n * List\n *\/\n\n#sched-schedule-9-1487908872-list .sched-list-title {\n\tcolor: #3f3f3f;\n}\n\n\n\n#sched-schedule-9-1487908872-list .sched-list-column-title {\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-9-1487908872-list .sched-list-event {\n\tcolor: #ffffff;\n\t\n\t\n}\n\n#sched-schedule-9-1487908872-list .sched-list-event:hover {\n\tcolor: #ffffff;\n}\n\n#sched-schedule-9-1487908872-list .sched-list-event-description {\n\tcolor: #ffffff;\n}\n\n#sched-schedule-9-1487908872-list .sched-list-event-title {\n\t\tfont-weight: bold;\n\t;\n}\n\n\/*\n * Horizontal\n *\/\n\n\n\n#sched-schedule-9-1487908872 .sched-h-columns {\n\tmargin-top: 30px;\n}\n\n#sched-schedule-9-1487908872 .sched-h-content-columns {\n\t\/*margin-top: 30px;*\/\n}\n\n\n#sched-schedule-9-1487908872 .sched-h-columns {\n\twidth: 200px;\n}\n\n#sched-schedule-9-1487908872 .sched-h-content {\n\tmargin-left: 200px;\n}\n\n#sched-schedule-9-1487908872 .sched-h-column-title {\n\ttext-align: center;\n}\n\n#sched-schedule-9-1487908872 .sched-h-column {\n\tbackground: #e8e8e8;\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-9-1487908872 .sched-h-row {\n\tbackground-color: #f8f8f8;\n}\n<\/style><\/div>\n\t<div class=\"sched-top\">\n\t\t\t<h2 class=\"sched-title\">Viernes 25 de octubre<\/h2>\n\t\t<div class=\"sched-top-buttons sched-top-buttons-right\">\n\t\t\t\n\t\t\t<\/div><!-- .sched-top-buttons -->\n<\/div><!-- .sched-top -->\t<div class=\"sched-row\">\n\t\t\t\t\t<!-- <div class=\"sched-sidebar\" style=\"width: 90px;\">\n\t\t\t\t<div class=\"sched-time\">\n\t\t\t\t\t<div class=\"sched-time-value\" style=\"padding-bottom: 36px\">11:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">12:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">13:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">14:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">15:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">16:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">17:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">18:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">19:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">20:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">21:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">22:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">23:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">00:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">01:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">02:00<\/div>\t\t\t\t<\/div>\n\t\t\t<\/div> -->\n\t\t\t\t\t\t<div class=\"sched-h-columns\">\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 1\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 2\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 3\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 4\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 5\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tFILMOTECA\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tFUNDACI\u00d3 BANCAIXA\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"sched-h-content\">\n\t\t\t<div class=\"sched-h-content-scroll\">\n\t\t\t\t\t\t\t\t<div class=\"sched-h-content-scroll-time\">\n\t\t\t\t\t<div class=\"sched-h-content-scroll-time-value\" data-i=\"0\" style=\"left: 0px;\">11:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"1\" style=\"left: 100px;\">12:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"2\" style=\"left: 200px;\">13:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"3\" style=\"left: 300px;\">14:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"4\" style=\"left: 400px;\">15:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"5\" style=\"left: 500px;\">16:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"6\" style=\"left: 600px;\">17:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"7\" style=\"left: 700px;\">18:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"8\" style=\"left: 800px;\">19:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"9\" style=\"left: 900px;\">20:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"10\" style=\"left: 1000px;\">21:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"11\" style=\"left: 1100px;\">22:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"12\" style=\"left: 1200px;\">23:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"13\" style=\"left: 1300px;\">00:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"14\" style=\"left: 1400px;\">01:00<\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"sched-h-content-columns\">\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/sympathy-for-the-devil\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"SYMPATHY FOR THE DEVIL 102&#039; Con la presencia del director, Guillaume de Fontenay\" data-event-id=\"171\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 50px;\" data-top=\"50\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\" https:\/\/lamostradevalencia.com\/peliculas\/sympathy-for-the-devil\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"SYMPATHY FOR THE DEVIL 102&#039; Con la presencia del director, Guillaume de Fontenay\" data-event-id=\"171\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 50px\" data-top=\"50\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ff7675; \" data-event-background-image-url=\"\" data-event-id=\"171\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">SYMPATHY FOR THE DEVIL 102&#039; Con la presencia del director, Guillaume de Fontenay<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"171\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-camisa-de-la-serp\/\" data-onclick=\"link\" data-color=\"#a3cb38\" title=\"LA CAMISA DE LA SERP 92&#039;\" data-event-id=\"386\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 500px;\" data-top=\"500\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-camisa-de-la-serp\/\"  data-onclick=\"link\" data-color=\"#a3cb38\" title=\"LA CAMISA DE LA SERP 92&#039;\" data-event-id=\"386\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 500px\" data-top=\"500\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #a3cb38; \" data-event-background-image-url=\"\" data-event-id=\"386\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">LA CAMISA DE LA SERP 92&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"386\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/los-inutiles\/\" data-onclick=\"link\" data-color=\"#128997\" title=\"LOS IN\u00daTILES 107&#039;\" data-event-id=\"387\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 700px;\" data-top=\"700\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/los-inutiles\/\"  data-onclick=\"link\" data-color=\"#128997\" title=\"LOS IN\u00daTILES 107&#039;\" data-event-id=\"387\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 700px\" data-top=\"700\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"387\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">LOS IN\u00daTILES 107&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"387\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-gran-guerra\/\" data-onclick=\"link\" data-color=\"#128997\" title=\"LA GRAN GUERRA 137&#039;\" data-event-id=\"388\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 225px; left: 900px;\" data-top=\"900\" data-size=\"1\" data-sort-index=\"3\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-gran-guerra\/\"  data-onclick=\"link\" data-color=\"#128997\" title=\"LA GRAN GUERRA 137&#039;\" data-event-id=\"388\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 225px; top: 900px\" data-top=\"900\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"388\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">LA GRAN GUERRA 137&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"388\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/todos-a-casa\/\" data-onclick=\"link\" data-color=\"#128997\" title=\"TODOS A CASA 122&#039;\" data-event-id=\"389\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 225px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"4\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/todos-a-casa\/\"  data-onclick=\"link\" data-color=\"#128997\" title=\"TODOS A CASA 122&#039;\" data-event-id=\"389\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 225px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"389\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">TODOS A CASA 122&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"389\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/hamam-el-bano-turco\/\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"HAMAM, EL BA\u00d1O TURCO 101&#039;\" data-event-id=\"168\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 500px;\" data-top=\"500\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/hamam-el-bano-turco\/\"  data-onclick=\"link\" data-color=\"#27ae60\" title=\"HAMAM, EL BA\u00d1O TURCO 101&#039;\" data-event-id=\"168\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 500px\" data-top=\"500\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #27ae60; \" data-event-background-image-url=\"\" data-event-id=\"168\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">HAMAM, EL BA\u00d1O TURCO 101&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"168\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/un-giorno-perfetto\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"UN GIORNO PERFETTO 105&#039;\" data-event-id=\"172\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 700px;\" data-top=\"700\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/un-giorno-perfetto\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"UN GIORNO PERFETTO 105&#039;\" data-event-id=\"172\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 700px\" data-top=\"700\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #27ae60; \" data-event-background-image-url=\"\" data-event-id=\"172\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">UN GIORNO PERFETTO 105&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"172\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/matrimonio-a-la-italiana\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#128997\" title=\"MATRIMONIO A LA ITALIANA 102&#039;\" data-event-id=\"173\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 900px;\" data-top=\"900\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/matrimonio-a-la-italiana\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#128997\" title=\"MATRIMONIO A LA ITALIANA 102&#039;\" data-event-id=\"173\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 900px\" data-top=\"900\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"173\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">MATRIMONIO A LA ITALIANA 102&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"173\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/divorcio-a-la-italiana\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#128997\" title=\"DIVORCIO A LA ITALIANA 105&#039;\" data-event-id=\"166\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 200px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"3\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/divorcio-a-la-italiana\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#128997\" title=\"DIVORCIO A LA ITALIANA 105&#039;\" data-event-id=\"166\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 200px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"166\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">DIVORCIO A LA ITALIANA 105&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"166\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/diamond-dust-2\/\" data-onclick=\"link\" data-color=\"#ffc312\" title=\"DIAMOND DUST 162&#039;\" data-event-id=\"169\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 275px; left: 500px;\" data-top=\"500\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/diamond-dust-2\/\"  data-onclick=\"link\" data-color=\"#ffc312\" title=\"DIAMOND DUST 162&#039;\" data-event-id=\"169\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 275px; top: 500px\" data-top=\"500\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ffc312; \" data-event-background-image-url=\"\" data-event-id=\"169\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">DIAMOND DUST 162&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"169\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-guerisseuse\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#fcc312\" title=\"LA GU\u00c9RISSEUESE 120&#039; Con la presencia del director, Mohamed Zineddaine\" data-event-id=\"177\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 225px; left: 900px;\" data-top=\"900\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-guerisseuse\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#fcc312\" title=\"LA GU\u00c9RISSEUESE 120&#039; Con la presencia del director, Mohamed Zineddaine\" data-event-id=\"177\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 225px; top: 900px\" data-top=\"900\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fcc312; \" data-event-background-image-url=\"\" data-event-id=\"177\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">LA GU\u00c9RISSEUESE 120&#039; Con la presencia del director, Mohamed Zineddaine<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"177\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/los-consejos-de-alice\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#ffc312\" title=\"LOS CONSEJOS DE ALICE 104&#039;\" data-event-id=\"175\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/los-consejos-de-alice\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#ffc312\" title=\"LOS CONSEJOS DE ALICE 104&#039;\" data-event-id=\"175\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ffc312; \" data-event-background-image-url=\"\" data-event-id=\"175\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">LOS CONSEJOS DE ALICE 104&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"175\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/fatwa\/\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"FATWA 102&#039; Con la presencia del director Mahmoud Ben Mahmoud\" data-event-id=\"167\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 500px;\" data-top=\"500\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\" https:\/\/lamostradevalencia.com\/peliculas\/fatwa\/\"  data-onclick=\"link\" data-color=\"#ff7675\" title=\"FATWA 102&#039; Con la presencia del director Mahmoud Ben Mahmoud\" data-event-id=\"167\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 500px\" data-top=\"500\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ff7675; \" data-event-background-image-url=\"\" data-event-id=\"167\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">FATWA 102&#039; Con la presencia del director Mahmoud Ben Mahmoud<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"167\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/istanbul-kirmizisi\/\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"ISTANBUL KIRMIZISI 110&#039;\" data-event-id=\"170\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 200px; left: 725px;\" data-top=\"725\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/istanbul-kirmizisi\/\"  data-onclick=\"link\" data-color=\"#27ae60\" title=\"ISTANBUL KIRMIZISI 110&#039;\" data-event-id=\"170\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 200px; top: 725px\" data-top=\"725\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #27ae60; \" data-event-background-image-url=\"\" data-event-id=\"170\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">ISTANBUL KIRMIZISI 110&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"170\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/matar-al-rey\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#fcc312\" title=\"MATAR AL REY 90&#039; Con la presencia del director, Vicente Monson\u00eds\" data-event-id=\"176\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/matar-al-rey\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#fcc312\" title=\"MATAR AL REY 90&#039; Con la presencia del director, Vicente Monson\u00eds\" data-event-id=\"176\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fcc312; \" data-event-background-image-url=\"\" data-event-id=\"176\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">MATAR AL REY 90&#039; Con la presencia del director, Vicente Monson\u00eds<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"176\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/one-zero\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#d63031\" title=\"ONE-ZERO 105&#039;\" data-event-id=\"180\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 700px;\" data-top=\"700\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/one-zero\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#d63031\" title=\"ONE-ZERO 105&#039;\" data-event-id=\"180\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 700px\" data-top=\"700\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #d63031; \" data-event-background-image-url=\"\" data-event-id=\"180\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">ONE-ZERO 105&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"180\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/venis-desde-lejos\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#d63031\" title=\"VEN\u00cdS DESDE LEJOS 85&#039; Con la presencia de la directora, Amal Ramsis\" data-event-id=\"181\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 900px;\" data-top=\"900\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/venis-desde-lejos\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#d63031\" title=\"VEN\u00cdS DESDE LEJOS 85&#039; Con la presencia de la directora, Amal Ramsis\" data-event-id=\"181\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 900px\" data-top=\"900\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #d63031; \" data-event-background-image-url=\"\" data-event-id=\"181\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">VEN\u00cdS DESDE LEJOS 85&#039; Con la presencia de la directora, Amal Ramsis<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"181\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/nawara\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#d63031\" title=\"NAWARA 122&#039; Con la presencia de la directora, Hala Khalil\" data-event-id=\"179\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 225px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/nawara\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#d63031\" title=\"NAWARA 122&#039; Con la presencia de la directora, Hala Khalil\" data-event-id=\"179\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 225px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #d63031; \" data-event-background-image-url=\"\" data-event-id=\"179\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">NAWARA 122&#039; Con la presencia de la directora, Hala Khalil<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"179\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-portero-de-noche\/\" data-onclick=\"link\" data-color=\"#fa983a\" title=\"EL PORTERO DE NOCHE 115&#039; Con la presencia de la directora, Liliana Cavani\" data-event-id=\"390\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 200px; left: 700px;\" data-top=\"700\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-portero-de-noche\/\"  data-onclick=\"link\" data-color=\"#fa983a\" title=\"EL PORTERO DE NOCHE 115&#039; Con la presencia de la directora, Liliana Cavani\" data-event-id=\"390\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 200px; top: 700px\" data-top=\"700\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fa983a; \" data-event-background-image-url=\"\" data-event-id=\"390\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">EL PORTERO DE NOCHE 115&#039; Con la presencia de la directora, Liliana Cavani<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"390\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/galileo\/\" data-onclick=\"link\" data-color=\"#fa983a\" title=\"GALILEO 105&#039;\" data-event-id=\"391\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 950px;\" data-top=\"950\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/galileo\/\"  data-onclick=\"link\" data-color=\"#fa983a\" title=\"GALILEO 105&#039;\" data-event-id=\"391\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 950px\" data-top=\"950\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fa983a; \" data-event-background-image-url=\"\" data-event-id=\"391\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">GALILEO 105&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"391\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/los-canibales\/\" data-onclick=\"link\" data-color=\"#fa983a\" title=\"LOS CAN\u00cdBALES 95&#039;\" data-event-id=\"183\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/los-canibales\/\"  data-onclick=\"link\" data-color=\"#fa983a\" title=\"LOS CAN\u00cdBALES 95&#039;\" data-event-id=\"183\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fa983a; \" data-event-background-image-url=\"\" data-event-id=\"183\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">LOS CAN\u00cdBALES 95&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"183\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/masterclass-liliana-cavani\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#833471\" title=\"MASTERCLASS LILIANA CAVANI. Modera Massimo Lechi.\" data-event-id=\"182\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 850px;\" data-top=\"850\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/masterclass-liliana-cavani\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#833471\" title=\"MASTERCLASS LILIANA CAVANI. Modera Massimo Lechi.\" data-event-id=\"182\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 850px\" data-top=\"850\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #833471; \" data-event-background-image-url=\"\" data-event-id=\"182\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">MASTERCLASS LILIANA CAVANI. Modera Massimo Lechi.<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"182\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n<\/div><div class=\" sched-list sched-hidden\" id=\"sched-schedule-9-1487908872-list\" data-id-schedule=\"sched-schedule-9-1487908872\" data-options=\" {&quot;am_pm&quot;:&quot;0&quot;,&quot;sidebar_width&quot;:&quot;90&quot;,&quot;sidebar_position&quot;:&quot;left&quot;,&quot;event_hover_color&quot;:&quot;lighten&quot;,&quot;event_box_text_align&quot;:&quot;center&quot;,&quot;event_box_time&quot;:&quot;0&quot;,&quot;event_hover_text_color&quot;:&quot;#FFFFFF&quot;,&quot;event_hover_background_color&quot;:&quot;#000000&quot;,&quot;event_box_truncate_title&quot;:&quot;0&quot;,&quot;event_tooltip&quot;:&quot;0&quot;,&quot;event_tooltip_title&quot;:&quot;1&quot;,&quot;event_tooltip_time&quot;:&quot;1&quot;,&quot;event_tooltip_description&quot;:&quot;1&quot;,&quot;event_tooltip_width_type&quot;:&quot;event&quot;,&quot;event_tooltip_width&quot;:&quot;150&quot;,&quot;event_tooltip_color_type&quot;:&quot;event&quot;,&quot;event_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;event_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;column_tooltip&quot;:&quot;0&quot;,&quot;column_tooltip_title&quot;:&quot;1&quot;,&quot;column_tooltip_description&quot;:&quot;1&quot;,&quot;column_tooltip_width_type&quot;:&quot;column&quot;,&quot;column_tooltip_width&quot;:&quot;150&quot;,&quot;column_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;column_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;animations&quot;:&quot;1&quot;,&quot;animations_mobile&quot;:&quot;1&quot;,&quot;animations_speed&quot;:&quot;normal&quot;,&quot;animations_css3&quot;:&quot;1&quot;,&quot;tooltips_mobile&quot;:&quot;1&quot;,&quot;editor_bg&quot;:&quot;#F5F5F5&quot;,&quot;animations_editor&quot;:&quot;1&quot;,&quot;popup_max_width&quot;:&quot;560&quot;,&quot;popup_background_color&quot;:&quot;#ffffff&quot;,&quot;popup_text_color&quot;:&quot;#535353&quot;,&quot;popup_link_color&quot;:&quot;#ff4d00&quot;,&quot;autoplay_videos&quot;:&quot;1&quot;,&quot;column_color_bg&quot;:&quot;#e8e8e8&quot;,&quot;column_color_text&quot;:&quot;#3f3f3f&quot;,&quot;column_color_border&quot;:&quot;#ffffff&quot;,&quot;pattern_color_1&quot;:&quot;#ffffff&quot;,&quot;pattern_color_2&quot;:&quot;#e8e8e8&quot;,&quot;pattern_color_3&quot;:&quot;#ffffff&quot;,&quot;title_text_color&quot;:&quot;#3f3f3f&quot;,&quot;sidebar_text_color&quot;:&quot;#3f3f3f&quot;,&quot;event_box_text_color&quot;:&quot;#ffffff&quot;,&quot;title_attr&quot;:&quot;0&quot;,&quot;column_break&quot;:1,&quot;column_break_width&quot;:&quot;120&quot;,&quot;column_break_hide_sidebar&quot;:&quot;0&quot;,&quot;editor_custom_css&quot;:&quot;1&quot;,&quot;column_title&quot;:&quot;1&quot;,&quot;event_box_description_method&quot;:&quot;short&quot;,&quot;editor_quick_tooltips&quot;:&quot;1&quot;,&quot;editor_timepicker_increments&quot;:&quot;15&quot;,&quot;event_box_style&quot;:&quot;1&quot;,&quot;filter_position&quot;:&quot;right&quot;,&quot;filter_multiple&quot;:&quot;1&quot;,&quot;filter_hidden_events&quot;:&quot;hide&quot;,&quot;filter_hidden_events_opacity&quot;:&quot;30&quot;,&quot;filter_dropdown_width&quot;:&quot;100&quot;,&quot;filter_dropdown_hover_width&quot;:&quot;180&quot;,&quot;filter_dropdown_label&quot;:&quot;Secci\\u00f3n&quot;,&quot;filter_dropdown_show_all_label&quot;:&quot;Mostrar todo&quot;,&quot;hashtag_url&quot;:&quot;1&quot;,&quot;hide_popup_for_empty_events&quot;:&quot;1&quot;,&quot;event_box_padding_break&quot;:&quot;200&quot;,&quot;popup_arrows&quot;:&quot;1&quot;,&quot;filter_visible&quot;:&quot;1&quot;,&quot;column_break_action&quot;:&quot;list&quot;,&quot;list_view_column_title_color&quot;:&quot;#3f3f3f&quot;,&quot;list_view_event_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_hover_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_title_bold&quot;:&quot;1&quot;,&quot;list_view_event_bullets&quot;:&quot;2&quot;,&quot;list_view_event_short_description_method&quot;:&quot;short&quot;,&quot;list_view_event_description_color&quot;:&quot;#ffffff&quot;,&quot;list_view_hide_empty_columns&quot;:&quot;1&quot;,&quot;shortcodes_in_descriptions&quot;:&quot;1&quot;,&quot;columns_sticky_header&quot;:&quot;1&quot;,&quot;columns_sticky_header_offset&quot;:&quot;0&quot;,&quot;h_row_height&quot;:&quot;110&quot;,&quot;h_column_width&quot;:&quot;200&quot;,&quot;h_time_indicator&quot;:&quot;1&quot;,&quot;h_time_indicator_height&quot;:30,&quot;h_column_multiline&quot;:&quot;0&quot;,&quot;h_column_title_position&quot;:&quot;middle&quot;,&quot;h_column_title_align&quot;:&quot;center&quot;,&quot;h_break&quot;:&quot;0&quot;,&quot;h_width_break_point&quot;:&quot;200&quot;,&quot;h_bg_color&quot;:&quot;#f8f8f8&quot;,&quot;pdf_type&quot;:&quot;html&quot;,&quot;pdf_enable&quot;:&quot;0&quot;,&quot;pdf_enable_list&quot;:&quot;0&quot;,&quot;pdf_label&quot;:&quot;Download&quot;,&quot;pdf_css&quot;:&quot;&quot;,&quot;upcoming_type&quot;:&quot;current_datetime&quot;,&quot;upcoming_custom&quot;:&quot;2016-01-01 00:00&quot;,&quot;upcoming_limit&quot;:&quot;5&quot;,&quot;upcoming_title&quot;:&quot;timetable_title&quot;,&quot;upcoming_title_custom&quot;:&quot;Upcoming Events&quot;,&quot;upcoming_title_amount&quot;:&quot;1&quot;}\" data-start=\"11:00\" data-end=\"01:30\" data-timetable-id=\"9\" data-type=\"list\" data-layout=\"horizontal\">\t<div class=\"sched-list-top\">\n\t\t<div class=\"sched-list-title\">Viernes 25 de octubre<\/div>\n\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 1<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/sympathy-for-the-devil\/\" data-event-id=\"171\" target=\"_blank\" style=\"background: #ff7675;\" data-color=\"#ff7675\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ff7675;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tSYMPATHY FOR THE DEVIL 102&#039; Con la presencia del director, Guillaume de Fontenay\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">11:30 - 13:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-camisa-de-la-serp\/\" data-event-id=\"386\" style=\"background: #a3cb38;\" data-color=\"#a3cb38\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #a3cb38;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tLA CAMISA DE LA SERP 92&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 17:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/los-inutiles\/\" data-event-id=\"387\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tLOS IN\u00daTILES 107&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-gran-guerra\/\" data-event-id=\"388\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tLA GRAN GUERRA 137&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 22:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/todos-a-casa\/\" data-event-id=\"389\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tTODOS A CASA 122&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 2<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/hamam-el-bano-turco\/\" data-event-id=\"168\" style=\"background: #27ae60;\" data-color=\"#27ae60\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #27ae60;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tHAMAM, EL BA\u00d1O TURCO 101&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 17:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/un-giorno-perfetto\/\" data-event-id=\"172\" target=\"_blank\" style=\"background: #27ae60;\" data-color=\"#27ae60\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #27ae60;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tUN GIORNO PERFETTO 105&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/matrimonio-a-la-italiana\/\" data-event-id=\"173\" target=\"_blank\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tMATRIMONIO A LA ITALIANA 102&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 21:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/divorcio-a-la-italiana\/\" data-event-id=\"166\" target=\"_blank\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tDIVORCIO A LA ITALIANA 105&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 3<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/diamond-dust-2\/\" data-event-id=\"169\" style=\"background: #ffc312;\" data-color=\"#ffc312\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ffc312;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tDIAMOND DUST 162&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 18:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-guerisseuse\/\" data-event-id=\"177\" target=\"_blank\" style=\"background: #fcc312;\" data-color=\"#fcc312\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fcc312;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tLA GU\u00c9RISSEUESE 120&#039; Con la presencia del director, Mohamed Zineddaine\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 22:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/los-consejos-de-alice\/\" data-event-id=\"175\" target=\"_blank\" style=\"background: #ffc312;\" data-color=\"#ffc312\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ffc312;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tLOS CONSEJOS DE ALICE 104&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 4<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/fatwa\/\" data-event-id=\"167\" style=\"background: #ff7675;\" data-color=\"#ff7675\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ff7675;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tFATWA 102&#039; Con la presencia del director Mahmoud Ben Mahmoud\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 17:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/istanbul-kirmizisi\/\" data-event-id=\"170\" style=\"background: #27ae60;\" data-color=\"#27ae60\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #27ae60;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tISTANBUL KIRMIZISI 110&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:15 - 20:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/matar-al-rey\/\" data-event-id=\"176\" target=\"_blank\" style=\"background: #fcc312;\" data-color=\"#fcc312\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fcc312;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tMATAR AL REY 90&#039; Con la presencia del director, Vicente Monson\u00eds\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 5<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/one-zero\/\" data-event-id=\"180\" target=\"_blank\" style=\"background: #d63031;\" data-color=\"#d63031\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #d63031;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tONE-ZERO 105&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/venis-desde-lejos\/\" data-event-id=\"181\" target=\"_blank\" style=\"background: #d63031;\" data-color=\"#d63031\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #d63031;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tVEN\u00cdS DESDE LEJOS 85&#039; Con la presencia de la directora, Amal Ramsis\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 21:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/nawara\/\" data-event-id=\"179\" target=\"_blank\" style=\"background: #d63031;\" data-color=\"#d63031\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #d63031;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tNAWARA 122&#039; Con la presencia de la directora, Hala Khalil\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">FILMOTECA<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-portero-de-noche\/\" data-event-id=\"390\" style=\"background: #fa983a;\" data-color=\"#fa983a\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fa983a;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tEL PORTERO DE NOCHE 115&#039; Con la presencia de la directora, Liliana Cavani\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 20:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/galileo\/\" data-event-id=\"391\" style=\"background: #fa983a;\" data-color=\"#fa983a\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fa983a;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tGALILEO 105&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:30 - 22:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/los-canibales\/\" data-event-id=\"183\" style=\"background: #fa983a;\" data-color=\"#fa983a\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fa983a;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tLOS CAN\u00cdBALES 95&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">FUNDACI\u00d3 BANCAIXA<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/masterclass-liliana-cavani\/\" data-event-id=\"182\" target=\"_blank\" style=\"background: #833471;\" data-color=\"#833471\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #833471;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tMASTERCLASS LILIANA CAVANI. Modera Massimo Lechi.\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">19:30 - 21:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t<!-- .sched-list-column -->\n\t\n<\/div>[\/vc_column][\/vc_row][vc_row disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1600188377582{padding-right: 40px !important;padding-bottom: 50px !important;padding-left: 40px !important;}&#8221; anchor=&#8221;sabado-26&#8243;][vc_column]<div class=\"sched-loader\"><div class=\"sched-loader-icon\"><\/div><div class=\"sched-loader-text\"><\/div><\/div>\n<div class=\" sched sched-horizontal sched-horizontal-medium\" id=\"sched-schedule-10-2140763413\" data-options=\" {&quot;am_pm&quot;:&quot;0&quot;,&quot;sidebar_width&quot;:&quot;90&quot;,&quot;sidebar_position&quot;:&quot;left&quot;,&quot;event_hover_color&quot;:&quot;lighten&quot;,&quot;event_box_text_align&quot;:&quot;center&quot;,&quot;event_box_time&quot;:&quot;0&quot;,&quot;event_hover_text_color&quot;:&quot;#FFFFFF&quot;,&quot;event_hover_background_color&quot;:&quot;#000000&quot;,&quot;event_box_truncate_title&quot;:&quot;0&quot;,&quot;event_tooltip&quot;:&quot;0&quot;,&quot;event_tooltip_title&quot;:&quot;1&quot;,&quot;event_tooltip_time&quot;:&quot;1&quot;,&quot;event_tooltip_description&quot;:&quot;1&quot;,&quot;event_tooltip_width_type&quot;:&quot;event&quot;,&quot;event_tooltip_width&quot;:&quot;150&quot;,&quot;event_tooltip_color_type&quot;:&quot;event&quot;,&quot;event_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;event_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;column_tooltip&quot;:&quot;0&quot;,&quot;column_tooltip_title&quot;:&quot;1&quot;,&quot;column_tooltip_description&quot;:&quot;1&quot;,&quot;column_tooltip_width_type&quot;:&quot;column&quot;,&quot;column_tooltip_width&quot;:&quot;150&quot;,&quot;column_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;column_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;animations&quot;:&quot;1&quot;,&quot;animations_mobile&quot;:&quot;1&quot;,&quot;animations_speed&quot;:&quot;normal&quot;,&quot;animations_css3&quot;:&quot;1&quot;,&quot;tooltips_mobile&quot;:&quot;1&quot;,&quot;editor_bg&quot;:&quot;#F5F5F5&quot;,&quot;animations_editor&quot;:&quot;1&quot;,&quot;popup_max_width&quot;:&quot;560&quot;,&quot;popup_background_color&quot;:&quot;#ffffff&quot;,&quot;popup_text_color&quot;:&quot;#535353&quot;,&quot;popup_link_color&quot;:&quot;#ff4d00&quot;,&quot;autoplay_videos&quot;:&quot;1&quot;,&quot;column_color_bg&quot;:&quot;#e8e8e8&quot;,&quot;column_color_text&quot;:&quot;#3f3f3f&quot;,&quot;column_color_border&quot;:&quot;#ffffff&quot;,&quot;pattern_color_1&quot;:&quot;#ffffff&quot;,&quot;pattern_color_2&quot;:&quot;#e8e8e8&quot;,&quot;pattern_color_3&quot;:&quot;#ffffff&quot;,&quot;title_text_color&quot;:&quot;#3f3f3f&quot;,&quot;sidebar_text_color&quot;:&quot;#3f3f3f&quot;,&quot;event_box_text_color&quot;:&quot;#ffffff&quot;,&quot;title_attr&quot;:&quot;0&quot;,&quot;column_break&quot;:1,&quot;column_break_width&quot;:&quot;120&quot;,&quot;column_break_hide_sidebar&quot;:&quot;0&quot;,&quot;editor_custom_css&quot;:&quot;1&quot;,&quot;column_title&quot;:&quot;1&quot;,&quot;event_box_description_method&quot;:&quot;short&quot;,&quot;editor_quick_tooltips&quot;:&quot;1&quot;,&quot;editor_timepicker_increments&quot;:&quot;15&quot;,&quot;event_box_style&quot;:&quot;1&quot;,&quot;filter_position&quot;:&quot;right&quot;,&quot;filter_multiple&quot;:&quot;1&quot;,&quot;filter_hidden_events&quot;:&quot;hide&quot;,&quot;filter_hidden_events_opacity&quot;:&quot;30&quot;,&quot;filter_dropdown_width&quot;:&quot;100&quot;,&quot;filter_dropdown_hover_width&quot;:&quot;180&quot;,&quot;filter_dropdown_label&quot;:&quot;Secci\\u00f3n&quot;,&quot;filter_dropdown_show_all_label&quot;:&quot;Mostrar todo&quot;,&quot;hashtag_url&quot;:&quot;1&quot;,&quot;hide_popup_for_empty_events&quot;:&quot;1&quot;,&quot;event_box_padding_break&quot;:&quot;200&quot;,&quot;popup_arrows&quot;:&quot;1&quot;,&quot;filter_visible&quot;:&quot;1&quot;,&quot;column_break_action&quot;:&quot;list&quot;,&quot;list_view_column_title_color&quot;:&quot;#3f3f3f&quot;,&quot;list_view_event_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_hover_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_title_bold&quot;:&quot;1&quot;,&quot;list_view_event_bullets&quot;:&quot;2&quot;,&quot;list_view_event_short_description_method&quot;:&quot;short&quot;,&quot;list_view_event_description_color&quot;:&quot;#ffffff&quot;,&quot;list_view_hide_empty_columns&quot;:&quot;1&quot;,&quot;shortcodes_in_descriptions&quot;:&quot;1&quot;,&quot;columns_sticky_header&quot;:&quot;1&quot;,&quot;columns_sticky_header_offset&quot;:&quot;0&quot;,&quot;h_row_height&quot;:&quot;110&quot;,&quot;h_column_width&quot;:&quot;200&quot;,&quot;h_time_indicator&quot;:&quot;1&quot;,&quot;h_time_indicator_height&quot;:30,&quot;h_column_multiline&quot;:&quot;0&quot;,&quot;h_column_title_position&quot;:&quot;middle&quot;,&quot;h_column_title_align&quot;:&quot;center&quot;,&quot;h_break&quot;:&quot;0&quot;,&quot;h_width_break_point&quot;:&quot;200&quot;,&quot;h_bg_color&quot;:&quot;#f8f8f8&quot;,&quot;pdf_type&quot;:&quot;html&quot;,&quot;pdf_enable&quot;:&quot;0&quot;,&quot;pdf_enable_list&quot;:&quot;0&quot;,&quot;pdf_label&quot;:&quot;Download&quot;,&quot;pdf_css&quot;:&quot;&quot;,&quot;upcoming_type&quot;:&quot;current_datetime&quot;,&quot;upcoming_custom&quot;:&quot;2016-01-01 00:00&quot;,&quot;upcoming_limit&quot;:&quot;5&quot;,&quot;upcoming_title&quot;:&quot;timetable_title&quot;,&quot;upcoming_title_custom&quot;:&quot;Upcoming Events&quot;,&quot;upcoming_title_amount&quot;:&quot;1&quot;}\" data-start=\"11:00\" data-end=\"01:30\" data-timetable-id=\"10\" data-type=\"full\" data-list-id=\"#sched-schedule-10-2140763413-list\" data-layout=\"horizontal\">\t<div class=\"sched-style\"><style type=\"text\/css\">\/*\n * Custom CSS For Timetable\n*\/\n\n#sched-schedule-10-2140763413 .sched-column-header,\n#sched-schedule-10-2140763413 .sched-column-header-sticky {\n\tbackground: #e8e8e8;\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-10-2140763413 .sched-column-header:after,\n#sched-schedule-10-2140763413 .sched-column-header-sticky:after {\n\tbackground: #ffffff;\n}\n\n#sched-schedule-10-2140763413 .sched-columns .sched-column:last-child .sched-column-header:after,\n#sched-schedule-10-2140763413 .sched-columns .sched-column:last-child .sched-column-header-sticky:after {\n\tbackground: #e8e8e8;\n}\n\n#sched-schedule-10-2140763413 .sched-column-bg-block {\n\tbackground: #ffffff;\n\tborder-color: #e8e8e8;\n}\n\n#sched-schedule-10-2140763413 .sched-column-bg-block:after {\n\tbackground: #ffffff;\n}\n\n#sched-schedule-10-2140763413 .sched-row-no-title .sched-column .sched-column-bg {\n\tbox-shadow: 0 -1px 0 #e8e8e8;\n}\n\n#sched-schedule-10-2140763413 .sched-title {\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-10-2140763413 .sched-time-value {\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-10-2140763413 .sched-event .sched-event-inner {\n\tcolor: #ffffff;\n\ttext-align: center;\n}\n\n#sched-schedule-10-2140763413 .sched-event.sched-event-invert .sched-event-inner {\n\t<!-- background: #999; -->\n}\n\n\n\n\/*#sched-schedule-10-2140763413 a.sched-event.sched-event-sort-hidden {\n\topacity: 0;\n}*\/\n\n#sched-schedule-10-2140763413 .sched-sort .sched-sort-current .sched-sort-current-label {\n\twidth: 100px;\n}\n\n#sched-schedule-10-2140763413 .sched-sort.sched-sort-open .sched-sort-dropdown .sched-sort-current .sched-sort-current-label {\n\twidth: 180px;\n}\n\n\/*\n * Custom CSS Event Popup\n *\/\n\n#sched-schedule-10-2140763413-popup .sched-popup-description {\n\t\n}\n\n#sched-schedule-10-2140763413-popup .sched-popup-description .sched-meta a,\n#sched-schedule-10-2140763413-popup .sched-popup-description .sched-popup-description-text a {\n\tcolor: #ff4d00;\n}\n\n#sched-schedule-10-2140763413-popup .sched-popup-description .sched-meta,\n#sched-schedule-10-2140763413-popup .sched-popup-description .sched-popup-description-text {\n\tcolor: #535353;\n\tbackground: #ffffff;\n}\n\n\/*\n * List\n *\/\n\n#sched-schedule-10-2140763413-list .sched-list-title {\n\tcolor: #3f3f3f;\n}\n\n\n\n#sched-schedule-10-2140763413-list .sched-list-column-title {\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-10-2140763413-list .sched-list-event {\n\tcolor: #ffffff;\n\t\n\t\n}\n\n#sched-schedule-10-2140763413-list .sched-list-event:hover {\n\tcolor: #ffffff;\n}\n\n#sched-schedule-10-2140763413-list .sched-list-event-description {\n\tcolor: #ffffff;\n}\n\n#sched-schedule-10-2140763413-list .sched-list-event-title {\n\t\tfont-weight: bold;\n\t;\n}\n\n\/*\n * Horizontal\n *\/\n\n\n\n#sched-schedule-10-2140763413 .sched-h-columns {\n\tmargin-top: 30px;\n}\n\n#sched-schedule-10-2140763413 .sched-h-content-columns {\n\t\/*margin-top: 30px;*\/\n}\n\n\n#sched-schedule-10-2140763413 .sched-h-columns {\n\twidth: 200px;\n}\n\n#sched-schedule-10-2140763413 .sched-h-content {\n\tmargin-left: 200px;\n}\n\n#sched-schedule-10-2140763413 .sched-h-column-title {\n\ttext-align: center;\n}\n\n#sched-schedule-10-2140763413 .sched-h-column {\n\tbackground: #e8e8e8;\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-10-2140763413 .sched-h-row {\n\tbackground-color: #f8f8f8;\n}\n<\/style><\/div>\n\t<div class=\"sched-top\">\n\t\t\t<h2 class=\"sched-title\">S\u00e1bado 26 de octubre<\/h2>\n\t\t<div class=\"sched-top-buttons sched-top-buttons-right\">\n\t\t\t\n\t\t\t<\/div><!-- .sched-top-buttons -->\n<\/div><!-- .sched-top -->\t<div class=\"sched-row\">\n\t\t\t\t\t<!-- <div class=\"sched-sidebar\" style=\"width: 90px;\">\n\t\t\t\t<div class=\"sched-time\">\n\t\t\t\t\t<div class=\"sched-time-value\" style=\"padding-bottom: 36px\">11:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">12:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">13:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">14:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">15:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">16:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">17:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">18:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">19:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">20:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">21:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">22:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">23:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">00:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">01:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">02:00<\/div>\t\t\t\t<\/div>\n\t\t\t<\/div> -->\n\t\t\t\t\t\t<div class=\"sched-h-columns\">\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 1\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 2\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 3\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 4\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 5\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tFILMOTECA\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tFUNDACI\u00d3 BANCAIXA\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"sched-h-content\">\n\t\t\t<div class=\"sched-h-content-scroll\">\n\t\t\t\t\t\t\t\t<div class=\"sched-h-content-scroll-time\">\n\t\t\t\t\t<div class=\"sched-h-content-scroll-time-value\" data-i=\"0\" style=\"left: 0px;\">11:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"1\" style=\"left: 100px;\">12:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"2\" style=\"left: 200px;\">13:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"3\" style=\"left: 300px;\">14:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"4\" style=\"left: 400px;\">15:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"5\" style=\"left: 500px;\">16:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"6\" style=\"left: 600px;\">17:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"7\" style=\"left: 700px;\">18:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"8\" style=\"left: 800px;\">19:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"9\" style=\"left: 900px;\">20:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"10\" style=\"left: 1000px;\">21:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"11\" style=\"left: 1100px;\">22:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"12\" style=\"left: 1200px;\">23:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"13\" style=\"left: 1300px;\">00:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"14\" style=\"left: 1400px;\">01:00<\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"sched-h-content-columns\">\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/the-day-i-lost-my-shadow\/\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"THE DAY I LOST MY SHADOW 94&#039; Con la presencia de la directora Soudade Kaadan\" data-event-id=\"392\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 50px;\" data-top=\"50\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\" https:\/\/lamostradevalencia.com\/peliculas\/the-day-i-lost-my-shadow\/\"  data-onclick=\"link\" data-color=\"#ff7675\" title=\"THE DAY I LOST MY SHADOW 94&#039; Con la presencia de la directora Soudade Kaadan\" data-event-id=\"392\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 50px\" data-top=\"50\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ff7675; \" data-event-background-image-url=\"\" data-event-id=\"392\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">THE DAY I LOST MY SHADOW 94&#039; Con la presencia de la directora Soudade Kaadan<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"392\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/los-inutiles\/\" data-onclick=\"link\" data-color=\"#128997\" title=\"LOS IN\u00daTILES 108&#039;\" data-event-id=\"396\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 500px;\" data-top=\"500\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/los-inutiles\/\"  data-onclick=\"link\" data-color=\"#128997\" title=\"LOS IN\u00daTILES 108&#039;\" data-event-id=\"396\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 500px\" data-top=\"500\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"396\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">LOS IN\u00daTILES 108&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"396\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/dove-la-liberta\/\" data-onclick=\"link\" data-color=\"#128997\" title=\"DOV&#039;\u00c8 LA LIBERT\u00c0\u2026? 93&#039;\" data-event-id=\"395\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 700px;\" data-top=\"700\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/dove-la-liberta\/\"  data-onclick=\"link\" data-color=\"#128997\" title=\"DOV&#039;\u00c8 LA LIBERT\u00c0\u2026? 93&#039;\" data-event-id=\"395\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 700px\" data-top=\"700\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"395\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">DOV&#039;\u00c8 LA LIBERT\u00c0\u2026? 93&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"395\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/las-alas-de-la-vida\/\" data-onclick=\"link\" data-color=\"#a3cb38\" title=\"LAS ALAS DE LA VIDA 90&#039;\" data-event-id=\"394\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 900px;\" data-top=\"900\" data-size=\"1\" data-sort-index=\"3\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/las-alas-de-la-vida\/\"  data-onclick=\"link\" data-color=\"#a3cb38\" title=\"LAS ALAS DE LA VIDA 90&#039;\" data-event-id=\"394\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 900px\" data-top=\"900\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #a3cb38; \" data-event-background-image-url=\"\" data-event-id=\"394\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">LAS ALAS DE LA VIDA 90&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"394\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-gran-guerra\/\" data-onclick=\"link\" data-color=\"#128997\" title=\"LA GRAN GUERRA 137&#039;\" data-event-id=\"393\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 225px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"4\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-gran-guerra\/\"  data-onclick=\"link\" data-color=\"#128997\" title=\"LA GRAN GUERRA 137&#039;\" data-event-id=\"393\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 225px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"393\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">LA GRAN GUERRA 137&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"393\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"#\" data-onclick=\"popup\" data-color=\"#0694d6\" title=\"PROGRAMA DE CORTOS FILMLAB PALESTINE 108&#039;\" data-event-id=\"398\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 500px;\" data-top=\"500\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"#\"  data-onclick=\"popup\" data-color=\"#0694d6\" title=\"PROGRAMA DE CORTOS FILMLAB PALESTINE 108&#039;\" data-event-id=\"398\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 500px\" data-top=\"500\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #0694d6; \" data-event-background-image-url=\"\" data-event-id=\"398\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">PROGRAMA DE CORTOS FILMLAB PALESTINE 108&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"398\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text\">\n\t\tIncluye:\r\n \t<li><strong>\"AMBIENCE\"<\/strong> 2019. B\/N. 15\u2019. VOSE<\/li>\r\n \t<li><strong>\"THE PIPE\"<\/strong> 2019. COLOR. 10\u2019. VOSE<\/li>\r\n \t<li><strong>\"THE WHITE ELEPHANT\"<\/strong> 2018. COLOR. 12\u2019. VOSE<\/li>\r\n \t<li><strong>\"AREA C\"<\/strong> 2018. COLOR. 10\u2019. VOSE<\/li>\r\n        <li><strong>\"THE CHAIR\"<\/strong> 2017 COLOR. 15\u2019. VOSE<\/li>\r\n \t<li><strong>\"BONBON\u00c9\"<\/strong> 2017 COLOR. 15\u2019. VOSE<\/li>\r\n \t<li><strong>\"AYNY\"<\/strong> 2016 COLOR. 11\u2019. VOSE<\/li>\r\n \t<li><strong>\"FIVE BOYS AND A WHEEL\"<\/strong> 2016 COLOR. 20\u2019. VOSE<\/li>\r\n<\/ul>\r\n\r\n<p style=\"text-align:center\" class=\"has-text-color has-medium-font-size has-luminous-vivid-orange-color\"><a href=\"https:\/\/www.reservaentradas.com\/sesiones\/valencia\/cinesbabel\/programa-de-cortos-filmlab-palestine\/596?proximamente=true&amp;\"><strong>COMPRAR ENTRADAS<\/strong><\/a><\/p>\r\n&nbsp\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/hamam-el-bano-turco\/\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"HAMAM, EL BA\u00d1O TURCO 101&#039;\" data-event-id=\"399\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 700px;\" data-top=\"700\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/hamam-el-bano-turco\/\"  data-onclick=\"link\" data-color=\"#27ae60\" title=\"HAMAM, EL BA\u00d1O TURCO 101&#039;\" data-event-id=\"399\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 700px\" data-top=\"700\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #27ae60; \" data-event-background-image-url=\"\" data-event-id=\"399\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">HAMAM, EL BA\u00d1O TURCO 101&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"399\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-armada-brancaleone\/\" data-onclick=\"link\" data-color=\"#128997\" title=\"LA ARMADA BRANCALEONE 120&#039;\" data-event-id=\"400\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 200px; left: 900px;\" data-top=\"900\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-armada-brancaleone\/\"  data-onclick=\"link\" data-color=\"#128997\" title=\"LA ARMADA BRANCALEONE 120&#039;\" data-event-id=\"400\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 200px; top: 900px\" data-top=\"900\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"400\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">LA ARMADA BRANCALEONE 120&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"400\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/matrimonio-a-la-italiana\/\" data-onclick=\"link\" data-color=\"#128997\" title=\"MATRIMONIO A LA ITALIANA 102&#039;\" data-event-id=\"397\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"3\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/matrimonio-a-la-italiana\/\"  data-onclick=\"link\" data-color=\"#128997\" title=\"MATRIMONIO A LA ITALIANA 102&#039;\" data-event-id=\"397\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"397\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">MATRIMONIO A LA ITALIANA 102&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"397\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/los-consejos-de-alice\/\" data-onclick=\"link\" data-color=\"#fcc312\" title=\"LOS CONSEJOS DE ALICE 104&#039;\" data-event-id=\"401\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 500px;\" data-top=\"500\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/los-consejos-de-alice\/\"  data-onclick=\"link\" data-color=\"#fcc312\" title=\"LOS CONSEJOS DE ALICE 104&#039;\" data-event-id=\"401\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 500px\" data-top=\"500\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fcc312; \" data-event-background-image-url=\"\" data-event-id=\"401\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">LOS CONSEJOS DE ALICE 104&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"401\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/los-miserables\/\" data-onclick=\"link\" data-color=\"#ffc312\" title=\"LOS MISERABLES 102&#039;\" data-event-id=\"402\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 700px;\" data-top=\"700\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/los-miserables\/\"  data-onclick=\"link\" data-color=\"#ffc312\" title=\"LOS MISERABLES 102&#039;\" data-event-id=\"402\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 700px\" data-top=\"700\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ffc312; \" data-event-background-image-url=\"\" data-event-id=\"402\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">LOS MISERABLES 102&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"402\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-verdad\/\" data-onclick=\"link\" data-color=\"#fcc312\" title=\"LA VERDAD 106&#039;\" data-event-id=\"403\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 200px; left: 900px;\" data-top=\"900\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-verdad\/\"  data-onclick=\"link\" data-color=\"#fcc312\" title=\"LA VERDAD 106&#039;\" data-event-id=\"403\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 200px; top: 900px\" data-top=\"900\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fcc312; \" data-event-background-image-url=\"\" data-event-id=\"403\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">LA VERDAD 106&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"403\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-guerisseuse\/\" data-onclick=\"link\" data-color=\"#fcc312\" title=\"LA GU\u00c9RISSUESE 120&#039; Con la presencia del director, Mohamed Zineddaine\" data-event-id=\"184\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 200px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"3\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-guerisseuse\/\"  data-onclick=\"link\" data-color=\"#fcc312\" title=\"LA GU\u00c9RISSUESE 120&#039; Con la presencia del director, Mohamed Zineddaine\" data-event-id=\"184\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 200px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fcc312; \" data-event-background-image-url=\"\" data-event-id=\"184\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">LA GU\u00c9RISSUESE 120&#039; Con la presencia del director, Mohamed Zineddaine<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"184\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/the-miracle-of-the-sargasso-sea\/\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"THE MIRACLE OF THE SARGASSO SEA 121&#039; Con la presencia de la actriz Angeliki Papoulia\" data-event-id=\"405\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 225px; left: 500px;\" data-top=\"500\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/the-miracle-of-the-sargasso-sea\/\"  data-onclick=\"link\" data-color=\"#ff7675\" title=\"THE MIRACLE OF THE SARGASSO SEA 121&#039; Con la presencia de la actriz Angeliki Papoulia\" data-event-id=\"405\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 225px; top: 500px\" data-top=\"500\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ff7675; \" data-event-background-image-url=\"\" data-event-id=\"405\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">THE MIRACLE OF THE SARGASSO SEA 121&#039; Con la presencia de la actriz Angeliki Papoulia<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"405\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/sympathy-for-the-devil\/\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"SYMPATHY FOR THE DEVIL 102&#039; Con la presencia del director, Guillaume de Fontenay\" data-event-id=\"406\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 900px;\" data-top=\"900\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\" https:\/\/lamostradevalencia.com\/peliculas\/sympathy-for-the-devil\/\"  data-onclick=\"link\" data-color=\"#ff7675\" title=\"SYMPATHY FOR THE DEVIL 102&#039; Con la presencia del director, Guillaume de Fontenay\" data-event-id=\"406\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 900px\" data-top=\"900\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ff7675; \" data-event-background-image-url=\"\" data-event-id=\"406\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">SYMPATHY FOR THE DEVIL 102&#039; Con la presencia del director, Guillaume de Fontenay<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"406\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/fatwa\/\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"FATWA 102&#039; Con la presencia de la actriz Mariem Sayah\" data-event-id=\"404\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\" https:\/\/lamostradevalencia.com\/peliculas\/fatwa\/\"  data-onclick=\"link\" data-color=\"#ff7675\" title=\"FATWA 102&#039; Con la presencia de la actriz Mariem Sayah\" data-event-id=\"404\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ff7675; \" data-event-background-image-url=\"\" data-event-id=\"404\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">FATWA 102&#039; Con la presencia de la actriz Mariem Sayah<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"404\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/bebo-wa-bashir\/\" data-onclick=\"link\" data-color=\"#d63031\" title=\"BEBO WA BASHIR 115&#039;\" data-event-id=\"410\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 500px;\" data-top=\"500\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/bebo-wa-bashir\/\"  data-onclick=\"link\" data-color=\"#d63031\" title=\"BEBO WA BASHIR 115&#039;\" data-event-id=\"410\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 500px\" data-top=\"500\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #d63031; \" data-event-background-image-url=\"\" data-event-id=\"410\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">BEBO WA BASHIR 115&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"410\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/napoli-velata\/\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"NAPOLI VELATA 113&#039;\" data-event-id=\"408\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 700px;\" data-top=\"700\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/napoli-velata\/\"  data-onclick=\"link\" data-color=\"#27ae60\" title=\"NAPOLI VELATA 113&#039;\" data-event-id=\"408\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 700px\" data-top=\"700\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #27ae60; \" data-event-background-image-url=\"\" data-event-id=\"408\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">NAPOLI VELATA 113&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"408\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/nawara\/\" data-onclick=\"link\" data-color=\"#d63031\" title=\"NAWARA 122&#039;\" data-event-id=\"409\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 225px; left: 900px;\" data-top=\"900\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/nawara\/\"  data-onclick=\"link\" data-color=\"#d63031\" title=\"NAWARA 122&#039;\" data-event-id=\"409\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 225px; top: 900px\" data-top=\"900\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #d63031; \" data-event-background-image-url=\"\" data-event-id=\"409\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">NAWARA 122&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"409\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/18-days\/\" data-onclick=\"link\" data-color=\"#d63031\" title=\"18 DAYS 122&#039;\" data-event-id=\"407\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 225px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"3\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/18-days\/\"  data-onclick=\"link\" data-color=\"#d63031\" title=\"18 DAYS 122&#039;\" data-event-id=\"407\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 225px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #d63031; \" data-event-background-image-url=\"\" data-event-id=\"407\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">18 DAYS 122&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"407\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/francesco-dassisi\/\" data-onclick=\"link\" data-color=\"#fa983a\" title=\"FRANCESCO D&#039;ASSISI 134&#039;\" data-event-id=\"413\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 225px; left: 700px;\" data-top=\"700\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/francesco-dassisi\/\"  data-onclick=\"link\" data-color=\"#fa983a\" title=\"FRANCESCO D&#039;ASSISI 134&#039;\" data-event-id=\"413\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 225px; top: 700px\" data-top=\"700\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fa983a; \" data-event-background-image-url=\"\" data-event-id=\"413\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">FRANCESCO D&#039;ASSISI 134&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"413\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/los-canibales\/\" data-onclick=\"link\" data-color=\"#fa983a\" title=\"LOS CAN\u00cdBALES 95&#039;\" data-event-id=\"416\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 950px;\" data-top=\"950\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/los-canibales\/\"  data-onclick=\"link\" data-color=\"#fa983a\" title=\"LOS CAN\u00cdBALES 95&#039;\" data-event-id=\"416\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 950px\" data-top=\"950\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fa983a; \" data-event-background-image-url=\"\" data-event-id=\"416\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">LOS CAN\u00cdBALES 95&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"416\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-portero-de-noche\/\" data-onclick=\"link\" data-color=\"#fa983a\" title=\"EL PORTERO DE NOCHE 115&#039;\" data-event-id=\"411\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 200px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-portero-de-noche\/\"  data-onclick=\"link\" data-color=\"#fa983a\" title=\"EL PORTERO DE NOCHE 115&#039;\" data-event-id=\"411\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 200px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fa983a; \" data-event-background-image-url=\"\" data-event-id=\"411\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">EL PORTERO DE NOCHE 115&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"411\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/mesa-redonda-directoras-egipcias\/\" data-onclick=\"link\" data-color=\"#833471\" title=\"MESA REDONDA. LA REVOLUCI\u00d3N DE LA MUJER EN EL CINE EGIPCIO. Con Hala Khalil, Amal Ramsis, Kamla Abuzekry, Nadine Khan, Mariam Abou-Ouf y Marianne Khoury. Modera Awatef Ketiti.\" data-event-id=\"417\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 250px; left: 850px;\" data-top=\"850\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/mesa-redonda-directoras-egipcias\/\"  data-onclick=\"link\" data-color=\"#833471\" title=\"MESA REDONDA. LA REVOLUCI\u00d3N DE LA MUJER EN EL CINE EGIPCIO. Con Hala Khalil, Amal Ramsis, Kamla Abuzekry, Nadine Khan, Mariam Abou-Ouf y Marianne Khoury. Modera Awatef Ketiti.\" data-event-id=\"417\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 250px; top: 850px\" data-top=\"850\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #833471; \" data-event-background-image-url=\"\" data-event-id=\"417\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">MESA REDONDA. LA REVOLUCI\u00d3N DE LA MUJER EN EL CINE EGIPCIO. Con Hala Khalil, Amal Ramsis, Kamla Abuzekry, Nadine Khan, Mariam Abou-Ouf y Marianne Khoury. Modera Awatef Ketiti.<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"417\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n<\/div><div class=\" sched-list sched-hidden\" id=\"sched-schedule-10-2140763413-list\" data-id-schedule=\"sched-schedule-10-2140763413\" data-options=\" {&quot;am_pm&quot;:&quot;0&quot;,&quot;sidebar_width&quot;:&quot;90&quot;,&quot;sidebar_position&quot;:&quot;left&quot;,&quot;event_hover_color&quot;:&quot;lighten&quot;,&quot;event_box_text_align&quot;:&quot;center&quot;,&quot;event_box_time&quot;:&quot;0&quot;,&quot;event_hover_text_color&quot;:&quot;#FFFFFF&quot;,&quot;event_hover_background_color&quot;:&quot;#000000&quot;,&quot;event_box_truncate_title&quot;:&quot;0&quot;,&quot;event_tooltip&quot;:&quot;0&quot;,&quot;event_tooltip_title&quot;:&quot;1&quot;,&quot;event_tooltip_time&quot;:&quot;1&quot;,&quot;event_tooltip_description&quot;:&quot;1&quot;,&quot;event_tooltip_width_type&quot;:&quot;event&quot;,&quot;event_tooltip_width&quot;:&quot;150&quot;,&quot;event_tooltip_color_type&quot;:&quot;event&quot;,&quot;event_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;event_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;column_tooltip&quot;:&quot;0&quot;,&quot;column_tooltip_title&quot;:&quot;1&quot;,&quot;column_tooltip_description&quot;:&quot;1&quot;,&quot;column_tooltip_width_type&quot;:&quot;column&quot;,&quot;column_tooltip_width&quot;:&quot;150&quot;,&quot;column_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;column_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;animations&quot;:&quot;1&quot;,&quot;animations_mobile&quot;:&quot;1&quot;,&quot;animations_speed&quot;:&quot;normal&quot;,&quot;animations_css3&quot;:&quot;1&quot;,&quot;tooltips_mobile&quot;:&quot;1&quot;,&quot;editor_bg&quot;:&quot;#F5F5F5&quot;,&quot;animations_editor&quot;:&quot;1&quot;,&quot;popup_max_width&quot;:&quot;560&quot;,&quot;popup_background_color&quot;:&quot;#ffffff&quot;,&quot;popup_text_color&quot;:&quot;#535353&quot;,&quot;popup_link_color&quot;:&quot;#ff4d00&quot;,&quot;autoplay_videos&quot;:&quot;1&quot;,&quot;column_color_bg&quot;:&quot;#e8e8e8&quot;,&quot;column_color_text&quot;:&quot;#3f3f3f&quot;,&quot;column_color_border&quot;:&quot;#ffffff&quot;,&quot;pattern_color_1&quot;:&quot;#ffffff&quot;,&quot;pattern_color_2&quot;:&quot;#e8e8e8&quot;,&quot;pattern_color_3&quot;:&quot;#ffffff&quot;,&quot;title_text_color&quot;:&quot;#3f3f3f&quot;,&quot;sidebar_text_color&quot;:&quot;#3f3f3f&quot;,&quot;event_box_text_color&quot;:&quot;#ffffff&quot;,&quot;title_attr&quot;:&quot;0&quot;,&quot;column_break&quot;:1,&quot;column_break_width&quot;:&quot;120&quot;,&quot;column_break_hide_sidebar&quot;:&quot;0&quot;,&quot;editor_custom_css&quot;:&quot;1&quot;,&quot;column_title&quot;:&quot;1&quot;,&quot;event_box_description_method&quot;:&quot;short&quot;,&quot;editor_quick_tooltips&quot;:&quot;1&quot;,&quot;editor_timepicker_increments&quot;:&quot;15&quot;,&quot;event_box_style&quot;:&quot;1&quot;,&quot;filter_position&quot;:&quot;right&quot;,&quot;filter_multiple&quot;:&quot;1&quot;,&quot;filter_hidden_events&quot;:&quot;hide&quot;,&quot;filter_hidden_events_opacity&quot;:&quot;30&quot;,&quot;filter_dropdown_width&quot;:&quot;100&quot;,&quot;filter_dropdown_hover_width&quot;:&quot;180&quot;,&quot;filter_dropdown_label&quot;:&quot;Secci\\u00f3n&quot;,&quot;filter_dropdown_show_all_label&quot;:&quot;Mostrar todo&quot;,&quot;hashtag_url&quot;:&quot;1&quot;,&quot;hide_popup_for_empty_events&quot;:&quot;1&quot;,&quot;event_box_padding_break&quot;:&quot;200&quot;,&quot;popup_arrows&quot;:&quot;1&quot;,&quot;filter_visible&quot;:&quot;1&quot;,&quot;column_break_action&quot;:&quot;list&quot;,&quot;list_view_column_title_color&quot;:&quot;#3f3f3f&quot;,&quot;list_view_event_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_hover_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_title_bold&quot;:&quot;1&quot;,&quot;list_view_event_bullets&quot;:&quot;2&quot;,&quot;list_view_event_short_description_method&quot;:&quot;short&quot;,&quot;list_view_event_description_color&quot;:&quot;#ffffff&quot;,&quot;list_view_hide_empty_columns&quot;:&quot;1&quot;,&quot;shortcodes_in_descriptions&quot;:&quot;1&quot;,&quot;columns_sticky_header&quot;:&quot;1&quot;,&quot;columns_sticky_header_offset&quot;:&quot;0&quot;,&quot;h_row_height&quot;:&quot;110&quot;,&quot;h_column_width&quot;:&quot;200&quot;,&quot;h_time_indicator&quot;:&quot;1&quot;,&quot;h_time_indicator_height&quot;:30,&quot;h_column_multiline&quot;:&quot;0&quot;,&quot;h_column_title_position&quot;:&quot;middle&quot;,&quot;h_column_title_align&quot;:&quot;center&quot;,&quot;h_break&quot;:&quot;0&quot;,&quot;h_width_break_point&quot;:&quot;200&quot;,&quot;h_bg_color&quot;:&quot;#f8f8f8&quot;,&quot;pdf_type&quot;:&quot;html&quot;,&quot;pdf_enable&quot;:&quot;0&quot;,&quot;pdf_enable_list&quot;:&quot;0&quot;,&quot;pdf_label&quot;:&quot;Download&quot;,&quot;pdf_css&quot;:&quot;&quot;,&quot;upcoming_type&quot;:&quot;current_datetime&quot;,&quot;upcoming_custom&quot;:&quot;2016-01-01 00:00&quot;,&quot;upcoming_limit&quot;:&quot;5&quot;,&quot;upcoming_title&quot;:&quot;timetable_title&quot;,&quot;upcoming_title_custom&quot;:&quot;Upcoming Events&quot;,&quot;upcoming_title_amount&quot;:&quot;1&quot;}\" data-start=\"11:00\" data-end=\"01:30\" data-timetable-id=\"10\" data-type=\"list\" data-layout=\"horizontal\">\t<div class=\"sched-list-top\">\n\t\t<div class=\"sched-list-title\">S\u00e1bado 26 de octubre<\/div>\n\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 1<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/the-day-i-lost-my-shadow\/\" data-event-id=\"392\" style=\"background: #ff7675;\" data-color=\"#ff7675\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ff7675;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tTHE DAY I LOST MY SHADOW 94&#039; Con la presencia de la directora Soudade Kaadan\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">11:30 - 13:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/los-inutiles\/\" data-event-id=\"396\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tLOS IN\u00daTILES 108&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 17:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/dove-la-liberta\/\" data-event-id=\"395\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tDOV&#039;\u00c8 LA LIBERT\u00c0\u2026? 93&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/las-alas-de-la-vida\/\" data-event-id=\"394\" style=\"background: #a3cb38;\" data-color=\"#a3cb38\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #a3cb38;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tLAS ALAS DE LA VIDA 90&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 21:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-gran-guerra\/\" data-event-id=\"393\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tLA GRAN GUERRA 137&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 2<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"#event-398\" data-event-id=\"398\" style=\"background: #0694d6;\" data-color=\"#0694d6\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #0694d6;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tPROGRAMA DE CORTOS FILMLAB PALESTINE 108&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 17:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/hamam-el-bano-turco\/\" data-event-id=\"399\" style=\"background: #27ae60;\" data-color=\"#27ae60\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #27ae60;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tHAMAM, EL BA\u00d1O TURCO 101&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-armada-brancaleone\/\" data-event-id=\"400\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tLA ARMADA BRANCALEONE 120&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 22:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/matrimonio-a-la-italiana\/\" data-event-id=\"397\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tMATRIMONIO A LA ITALIANA 102&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 3<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/los-consejos-de-alice\/\" data-event-id=\"401\" style=\"background: #fcc312;\" data-color=\"#fcc312\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fcc312;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tLOS CONSEJOS DE ALICE 104&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 17:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/los-miserables\/\" data-event-id=\"402\" style=\"background: #ffc312;\" data-color=\"#ffc312\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ffc312;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tLOS MISERABLES 102&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-verdad\/\" data-event-id=\"403\" style=\"background: #fcc312;\" data-color=\"#fcc312\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fcc312;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tLA VERDAD 106&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 22:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-guerisseuse\/\" data-event-id=\"184\" style=\"background: #fcc312;\" data-color=\"#fcc312\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fcc312;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tLA GU\u00c9RISSUESE 120&#039; Con la presencia del director, Mohamed Zineddaine\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 4<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/the-miracle-of-the-sargasso-sea\/\" data-event-id=\"405\" style=\"background: #ff7675;\" data-color=\"#ff7675\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ff7675;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tTHE MIRACLE OF THE SARGASSO SEA 121&#039; Con la presencia de la actriz Angeliki Papoulia\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 18:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/sympathy-for-the-devil\/\" data-event-id=\"406\" style=\"background: #ff7675;\" data-color=\"#ff7675\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ff7675;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tSYMPATHY FOR THE DEVIL 102&#039; Con la presencia del director, Guillaume de Fontenay\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 21:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/fatwa\/\" data-event-id=\"404\" style=\"background: #ff7675;\" data-color=\"#ff7675\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ff7675;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tFATWA 102&#039; Con la presencia de la actriz Mariem Sayah\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 5<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/bebo-wa-bashir\/\" data-event-id=\"410\" style=\"background: #d63031;\" data-color=\"#d63031\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #d63031;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tBEBO WA BASHIR 115&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 17:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/napoli-velata\/\" data-event-id=\"408\" style=\"background: #27ae60;\" data-color=\"#27ae60\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #27ae60;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tNAPOLI VELATA 113&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/nawara\/\" data-event-id=\"409\" style=\"background: #d63031;\" data-color=\"#d63031\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #d63031;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tNAWARA 122&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 22:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/18-days\/\" data-event-id=\"407\" style=\"background: #d63031;\" data-color=\"#d63031\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #d63031;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\t18 DAYS 122&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">FILMOTECA<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/francesco-dassisi\/\" data-event-id=\"413\" style=\"background: #fa983a;\" data-color=\"#fa983a\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fa983a;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tFRANCESCO D&#039;ASSISI 134&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 20:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/los-canibales\/\" data-event-id=\"416\" style=\"background: #fa983a;\" data-color=\"#fa983a\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fa983a;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tLOS CAN\u00cdBALES 95&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:30 - 22:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-portero-de-noche\/\" data-event-id=\"411\" style=\"background: #fa983a;\" data-color=\"#fa983a\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fa983a;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tEL PORTERO DE NOCHE 115&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">FUNDACI\u00d3 BANCAIXA<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/mesa-redonda-directoras-egipcias\/\" data-event-id=\"417\" style=\"background: #833471;\" data-color=\"#833471\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #833471;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tMESA REDONDA. LA REVOLUCI\u00d3N DE LA MUJER EN EL CINE EGIPCIO. Con Hala Khalil, Amal Ramsis, Kamla Abuzekry, Nadine Khan, Mariam Abou-Ouf y Marianne Khoury. Modera Awatef Ketiti.\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">19:30 - 22:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t<!-- .sched-list-column -->\n\t\n<\/div>[\/vc_column][\/vc_row][vc_row disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1600188391318{padding-right: 40px !important;padding-bottom: 50px !important;padding-left: 40px !important;}&#8221; anchor=&#8221;domingo-27&#8243;][vc_column]<div class=\"sched-loader\"><div class=\"sched-loader-icon\"><\/div><div class=\"sched-loader-text\"><\/div><\/div>\n<div class=\" sched sched-horizontal sched-horizontal-medium\" id=\"sched-schedule-11-367451792\" data-options=\" {&quot;am_pm&quot;:&quot;0&quot;,&quot;sidebar_width&quot;:&quot;90&quot;,&quot;sidebar_position&quot;:&quot;left&quot;,&quot;event_hover_color&quot;:&quot;lighten&quot;,&quot;event_box_text_align&quot;:&quot;center&quot;,&quot;event_box_time&quot;:&quot;0&quot;,&quot;event_hover_text_color&quot;:&quot;#FFFFFF&quot;,&quot;event_hover_background_color&quot;:&quot;#000000&quot;,&quot;event_box_truncate_title&quot;:&quot;0&quot;,&quot;event_tooltip&quot;:&quot;0&quot;,&quot;event_tooltip_title&quot;:&quot;1&quot;,&quot;event_tooltip_time&quot;:&quot;1&quot;,&quot;event_tooltip_description&quot;:&quot;1&quot;,&quot;event_tooltip_width_type&quot;:&quot;event&quot;,&quot;event_tooltip_width&quot;:&quot;150&quot;,&quot;event_tooltip_color_type&quot;:&quot;event&quot;,&quot;event_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;event_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;column_tooltip&quot;:&quot;0&quot;,&quot;column_tooltip_title&quot;:&quot;1&quot;,&quot;column_tooltip_description&quot;:&quot;1&quot;,&quot;column_tooltip_width_type&quot;:&quot;column&quot;,&quot;column_tooltip_width&quot;:&quot;150&quot;,&quot;column_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;column_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;animations&quot;:&quot;1&quot;,&quot;animations_mobile&quot;:&quot;1&quot;,&quot;animations_speed&quot;:&quot;normal&quot;,&quot;animations_css3&quot;:&quot;1&quot;,&quot;tooltips_mobile&quot;:&quot;1&quot;,&quot;editor_bg&quot;:&quot;#F5F5F5&quot;,&quot;animations_editor&quot;:&quot;1&quot;,&quot;popup_max_width&quot;:&quot;560&quot;,&quot;popup_background_color&quot;:&quot;#ffffff&quot;,&quot;popup_text_color&quot;:&quot;#535353&quot;,&quot;popup_link_color&quot;:&quot;#ff4d00&quot;,&quot;autoplay_videos&quot;:&quot;1&quot;,&quot;column_color_bg&quot;:&quot;#e8e8e8&quot;,&quot;column_color_text&quot;:&quot;#3f3f3f&quot;,&quot;column_color_border&quot;:&quot;#ffffff&quot;,&quot;pattern_color_1&quot;:&quot;#ffffff&quot;,&quot;pattern_color_2&quot;:&quot;#e8e8e8&quot;,&quot;pattern_color_3&quot;:&quot;#ffffff&quot;,&quot;title_text_color&quot;:&quot;#3f3f3f&quot;,&quot;sidebar_text_color&quot;:&quot;#3f3f3f&quot;,&quot;event_box_text_color&quot;:&quot;#ffffff&quot;,&quot;title_attr&quot;:&quot;0&quot;,&quot;column_break&quot;:1,&quot;column_break_width&quot;:&quot;120&quot;,&quot;column_break_hide_sidebar&quot;:&quot;0&quot;,&quot;editor_custom_css&quot;:&quot;1&quot;,&quot;column_title&quot;:&quot;1&quot;,&quot;event_box_description_method&quot;:&quot;short&quot;,&quot;editor_quick_tooltips&quot;:&quot;1&quot;,&quot;editor_timepicker_increments&quot;:&quot;15&quot;,&quot;event_box_style&quot;:&quot;1&quot;,&quot;filter_position&quot;:&quot;right&quot;,&quot;filter_multiple&quot;:&quot;1&quot;,&quot;filter_hidden_events&quot;:&quot;hide&quot;,&quot;filter_hidden_events_opacity&quot;:&quot;30&quot;,&quot;filter_dropdown_width&quot;:&quot;100&quot;,&quot;filter_dropdown_hover_width&quot;:&quot;180&quot;,&quot;filter_dropdown_label&quot;:&quot;Secci\\u00f3n&quot;,&quot;filter_dropdown_show_all_label&quot;:&quot;Mostrar todo&quot;,&quot;hashtag_url&quot;:&quot;1&quot;,&quot;hide_popup_for_empty_events&quot;:&quot;1&quot;,&quot;event_box_padding_break&quot;:&quot;200&quot;,&quot;popup_arrows&quot;:&quot;1&quot;,&quot;filter_visible&quot;:&quot;1&quot;,&quot;column_break_action&quot;:&quot;list&quot;,&quot;list_view_column_title_color&quot;:&quot;#3f3f3f&quot;,&quot;list_view_event_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_hover_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_title_bold&quot;:&quot;1&quot;,&quot;list_view_event_bullets&quot;:&quot;2&quot;,&quot;list_view_event_short_description_method&quot;:&quot;short&quot;,&quot;list_view_event_description_color&quot;:&quot;#ffffff&quot;,&quot;list_view_hide_empty_columns&quot;:&quot;1&quot;,&quot;shortcodes_in_descriptions&quot;:&quot;1&quot;,&quot;columns_sticky_header&quot;:&quot;1&quot;,&quot;columns_sticky_header_offset&quot;:&quot;0&quot;,&quot;h_row_height&quot;:&quot;110&quot;,&quot;h_column_width&quot;:&quot;200&quot;,&quot;h_time_indicator&quot;:&quot;1&quot;,&quot;h_time_indicator_height&quot;:30,&quot;h_column_multiline&quot;:&quot;0&quot;,&quot;h_column_title_position&quot;:&quot;middle&quot;,&quot;h_column_title_align&quot;:&quot;center&quot;,&quot;h_break&quot;:&quot;0&quot;,&quot;h_width_break_point&quot;:&quot;200&quot;,&quot;h_bg_color&quot;:&quot;#f8f8f8&quot;,&quot;pdf_type&quot;:&quot;html&quot;,&quot;pdf_enable&quot;:&quot;0&quot;,&quot;pdf_enable_list&quot;:&quot;0&quot;,&quot;pdf_label&quot;:&quot;Download&quot;,&quot;pdf_css&quot;:&quot;&quot;,&quot;upcoming_type&quot;:&quot;current_datetime&quot;,&quot;upcoming_custom&quot;:&quot;2016-01-01 00:00&quot;,&quot;upcoming_limit&quot;:&quot;5&quot;,&quot;upcoming_title&quot;:&quot;timetable_title&quot;,&quot;upcoming_title_custom&quot;:&quot;Upcoming Events&quot;,&quot;upcoming_title_amount&quot;:&quot;1&quot;}\" data-start=\"11:00\" data-end=\"01:30\" data-timetable-id=\"11\" data-type=\"full\" data-list-id=\"#sched-schedule-11-367451792-list\" data-layout=\"horizontal\">\t<div class=\"sched-style\"><style type=\"text\/css\">\/*\n * Custom CSS For Timetable\n*\/\n\n#sched-schedule-11-367451792 .sched-column-header,\n#sched-schedule-11-367451792 .sched-column-header-sticky {\n\tbackground: #e8e8e8;\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-11-367451792 .sched-column-header:after,\n#sched-schedule-11-367451792 .sched-column-header-sticky:after {\n\tbackground: #ffffff;\n}\n\n#sched-schedule-11-367451792 .sched-columns .sched-column:last-child .sched-column-header:after,\n#sched-schedule-11-367451792 .sched-columns .sched-column:last-child .sched-column-header-sticky:after {\n\tbackground: #e8e8e8;\n}\n\n#sched-schedule-11-367451792 .sched-column-bg-block {\n\tbackground: #ffffff;\n\tborder-color: #e8e8e8;\n}\n\n#sched-schedule-11-367451792 .sched-column-bg-block:after {\n\tbackground: #ffffff;\n}\n\n#sched-schedule-11-367451792 .sched-row-no-title .sched-column .sched-column-bg {\n\tbox-shadow: 0 -1px 0 #e8e8e8;\n}\n\n#sched-schedule-11-367451792 .sched-title {\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-11-367451792 .sched-time-value {\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-11-367451792 .sched-event .sched-event-inner {\n\tcolor: #ffffff;\n\ttext-align: center;\n}\n\n#sched-schedule-11-367451792 .sched-event.sched-event-invert .sched-event-inner {\n\t<!-- background: #999; -->\n}\n\n\n\n\/*#sched-schedule-11-367451792 a.sched-event.sched-event-sort-hidden {\n\topacity: 0;\n}*\/\n\n#sched-schedule-11-367451792 .sched-sort .sched-sort-current .sched-sort-current-label {\n\twidth: 100px;\n}\n\n#sched-schedule-11-367451792 .sched-sort.sched-sort-open .sched-sort-dropdown .sched-sort-current .sched-sort-current-label {\n\twidth: 180px;\n}\n\n\/*\n * Custom CSS Event Popup\n *\/\n\n#sched-schedule-11-367451792-popup .sched-popup-description {\n\t\n}\n\n#sched-schedule-11-367451792-popup .sched-popup-description .sched-meta a,\n#sched-schedule-11-367451792-popup .sched-popup-description .sched-popup-description-text a {\n\tcolor: #ff4d00;\n}\n\n#sched-schedule-11-367451792-popup .sched-popup-description .sched-meta,\n#sched-schedule-11-367451792-popup .sched-popup-description .sched-popup-description-text {\n\tcolor: #535353;\n\tbackground: #ffffff;\n}\n\n\/*\n * List\n *\/\n\n#sched-schedule-11-367451792-list .sched-list-title {\n\tcolor: #3f3f3f;\n}\n\n\n\n#sched-schedule-11-367451792-list .sched-list-column-title {\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-11-367451792-list .sched-list-event {\n\tcolor: #ffffff;\n\t\n\t\n}\n\n#sched-schedule-11-367451792-list .sched-list-event:hover {\n\tcolor: #ffffff;\n}\n\n#sched-schedule-11-367451792-list .sched-list-event-description {\n\tcolor: #ffffff;\n}\n\n#sched-schedule-11-367451792-list .sched-list-event-title {\n\t\tfont-weight: bold;\n\t;\n}\n\n\/*\n * Horizontal\n *\/\n\n\n\n#sched-schedule-11-367451792 .sched-h-columns {\n\tmargin-top: 30px;\n}\n\n#sched-schedule-11-367451792 .sched-h-content-columns {\n\t\/*margin-top: 30px;*\/\n}\n\n\n#sched-schedule-11-367451792 .sched-h-columns {\n\twidth: 200px;\n}\n\n#sched-schedule-11-367451792 .sched-h-content {\n\tmargin-left: 200px;\n}\n\n#sched-schedule-11-367451792 .sched-h-column-title {\n\ttext-align: center;\n}\n\n#sched-schedule-11-367451792 .sched-h-column {\n\tbackground: #e8e8e8;\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-11-367451792 .sched-h-row {\n\tbackground-color: #f8f8f8;\n}\n<\/style><\/div>\n\t<div class=\"sched-top\">\n\t\t\t<h2 class=\"sched-title\">Domingo 27 de octubre<\/h2>\n\t\t<div class=\"sched-top-buttons sched-top-buttons-right\">\n\t\t\t\n\t\t\t<\/div><!-- .sched-top-buttons -->\n<\/div><!-- .sched-top -->\t<div class=\"sched-row\">\n\t\t\t\t\t<!-- <div class=\"sched-sidebar\" style=\"width: 90px;\">\n\t\t\t\t<div class=\"sched-time\">\n\t\t\t\t\t<div class=\"sched-time-value\" style=\"padding-bottom: 36px\">11:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">12:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">13:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">14:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">15:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">16:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">17:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">18:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">19:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">20:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">21:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">22:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">23:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">00:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">01:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">02:00<\/div>\t\t\t\t<\/div>\n\t\t\t<\/div> -->\n\t\t\t\t\t\t<div class=\"sched-h-columns\">\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 1\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 2\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 3\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 4\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 5\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tFILMOTECA\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tPALAU DE CONGRESSOS DE VAL\u00c8NCIA\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"sched-h-content\">\n\t\t\t<div class=\"sched-h-content-scroll\">\n\t\t\t\t\t\t\t\t<div class=\"sched-h-content-scroll-time\">\n\t\t\t\t\t<div class=\"sched-h-content-scroll-time-value\" data-i=\"0\" style=\"left: 0px;\">11:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"1\" style=\"left: 100px;\">12:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"2\" style=\"left: 200px;\">13:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"3\" style=\"left: 300px;\">14:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"4\" style=\"left: 400px;\">15:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"5\" style=\"left: 500px;\">16:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"6\" style=\"left: 600px;\">17:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"7\" style=\"left: 700px;\">18:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"8\" style=\"left: 800px;\">19:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"9\" style=\"left: 900px;\">20:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"10\" style=\"left: 1000px;\">21:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"11\" style=\"left: 1100px;\">22:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"12\" style=\"left: 1200px;\">23:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"13\" style=\"left: 1300px;\">00:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"14\" style=\"left: 1400px;\">01:00<\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"sched-h-content-columns\">\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/alice\/\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"ALICE 103&#039; Con la presencia de Mickael Dalahie (Director de Fotograf\u00eda y Eug\u00e9nie Gressier (Directora de Producci\u00f3n)\" data-event-id=\"418\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 50px;\" data-top=\"50\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\" https:\/\/lamostradevalencia.com\/peliculas\/alice\/\"  data-onclick=\"link\" data-color=\"#ff7675\" title=\"ALICE 103&#039; Con la presencia de Mickael Dalahie (Director de Fotograf\u00eda y Eug\u00e9nie Gressier (Directora de Producci\u00f3n)\" data-event-id=\"418\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 50px\" data-top=\"50\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ff7675; \" data-event-background-image-url=\"\" data-event-id=\"418\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">ALICE 103&#039; Con la presencia de Mickael Dalahie (Director de Fotograf\u00eda y Eug\u00e9nie Gressier (Directora de Producci\u00f3n)<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"418\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/dove-la-liberta\/\" data-onclick=\"link\" data-color=\"#128997\" title=\"DOV&#039;\u00c8 LA LIBERT\u00c0\u2026? 93&#039;\" data-event-id=\"419\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 500px;\" data-top=\"500\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/dove-la-liberta\/\"  data-onclick=\"link\" data-color=\"#128997\" title=\"DOV&#039;\u00c8 LA LIBERT\u00c0\u2026? 93&#039;\" data-event-id=\"419\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 500px\" data-top=\"500\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"419\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">DOV&#039;\u00c8 LA LIBERT\u00c0\u2026? 93&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"419\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-camisa-de-la-serp\/\" data-onclick=\"link\" data-color=\"#a3cb38\" title=\"LA CAMISA DE LA SERP 92&#039;\" data-event-id=\"421\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 700px;\" data-top=\"700\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-camisa-de-la-serp\/\"  data-onclick=\"link\" data-color=\"#a3cb38\" title=\"LA CAMISA DE LA SERP 92&#039;\" data-event-id=\"421\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 700px\" data-top=\"700\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #a3cb38; \" data-event-background-image-url=\"\" data-event-id=\"421\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">LA CAMISA DE LA SERP 92&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"421\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/todos-a-casa\/\" data-onclick=\"link\" data-color=\"#128997\" title=\"TODOS A CASA 122&#039;\" data-event-id=\"420\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 200px; left: 900px;\" data-top=\"900\" data-size=\"1\" data-sort-index=\"3\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/todos-a-casa\/\"  data-onclick=\"link\" data-color=\"#128997\" title=\"TODOS A CASA 122&#039;\" data-event-id=\"420\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 200px; top: 900px\" data-top=\"900\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"420\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">TODOS A CASA 122&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"420\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/las-alas-de-la-vida\/\" data-onclick=\"link\" data-color=\"#a3cb38\" title=\"LAS ALAS DE LA VIDA 90&#039;\" data-event-id=\"190\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"4\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/las-alas-de-la-vida\/\"  data-onclick=\"link\" data-color=\"#a3cb38\" title=\"LAS ALAS DE LA VIDA 90&#039;\" data-event-id=\"190\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #a3cb38; \" data-event-background-image-url=\"\" data-event-id=\"190\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">LAS ALAS DE LA VIDA 90&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"190\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/poveri-ma-belli\/\" data-onclick=\"link\" data-color=\"#128997\" title=\"POVERI MA BELLI 101&#039;\" data-event-id=\"425\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 700px;\" data-top=\"700\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/poveri-ma-belli\/\"  data-onclick=\"link\" data-color=\"#128997\" title=\"POVERI MA BELLI 101&#039;\" data-event-id=\"425\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 700px\" data-top=\"700\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"425\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">POVERI MA BELLI 101&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"425\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/divorcio-a-la-italiana\/\" data-onclick=\"link\" data-color=\"#128997\" title=\"DIVORCIO A LA ITALIANA 105&#039;\" data-event-id=\"426\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 900px;\" data-top=\"900\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/divorcio-a-la-italiana\/\"  data-onclick=\"link\" data-color=\"#128997\" title=\"DIVORCIO A LA ITALIANA 105&#039;\" data-event-id=\"426\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 900px\" data-top=\"900\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"426\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">DIVORCIO A LA ITALIANA 105&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"426\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-armada-brancaleone\/\" data-onclick=\"link\" data-color=\"#128997\" title=\"LA ARMADA BRANCALEONE 120&#039;\" data-event-id=\"423\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 200px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-armada-brancaleone\/\"  data-onclick=\"link\" data-color=\"#128997\" title=\"LA ARMADA BRANCALEONE 120&#039;\" data-event-id=\"423\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 200px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"423\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">LA ARMADA BRANCALEONE 120&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"423\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/dafne\/\" data-onclick=\"link\" data-color=\"#fcc312\" title=\"DAFNE 94&#039;\" data-event-id=\"429\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 500px;\" data-top=\"500\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/dafne\/\"  data-onclick=\"link\" data-color=\"#fcc312\" title=\"DAFNE 94&#039;\" data-event-id=\"429\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 500px\" data-top=\"500\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fcc312; \" data-event-background-image-url=\"\" data-event-id=\"429\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">DAFNE 94&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"429\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/mar\/\" data-onclick=\"link\" data-color=\"#fcc312\" title=\"MAR 103&#039;\" data-event-id=\"430\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 700px;\" data-top=\"700\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/mar\/\"  data-onclick=\"link\" data-color=\"#fcc312\" title=\"MAR 103&#039;\" data-event-id=\"430\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 700px\" data-top=\"700\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fcc312; \" data-event-background-image-url=\"\" data-event-id=\"430\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">MAR 103&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"430\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"#\" data-onclick=\"popup\" data-color=\"#0694d6\" title=\"PROGRAMA DE CORTOS FILMLAB PALESTINE 108&#039; Presentado por Muayad Alayan\" data-event-id=\"424\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 900px;\" data-top=\"900\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"#\"  data-onclick=\"popup\" data-color=\"#0694d6\" title=\"PROGRAMA DE CORTOS FILMLAB PALESTINE 108&#039; Presentado por Muayad Alayan\" data-event-id=\"424\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 900px\" data-top=\"900\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #0694d6; \" data-event-background-image-url=\"\" data-event-id=\"424\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">PROGRAMA DE CORTOS FILMLAB PALESTINE 108&#039; Presentado por Muayad Alayan<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"424\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text\">\n\t\tIncluye:\r\n \t<li><strong>\"AMBIENCE\"<\/strong> 2019. B\/N. 15\u2019. VOSE<\/li>\r\n \t<li><strong>\"THE PIPE\"<\/strong> 2019. COLOR. 10\u2019. VOSE<\/li>\r\n \t<li><strong>\"THE WHITE ELEPHANT\"<\/strong> 2018. COLOR. 12\u2019. VOSE<\/li>\r\n \t<li><strong>\"AREA C\"<\/strong> 2018. COLOR. 10\u2019. VOSE<\/li>\r\n        <li><strong>\"THE CHAIR\"<\/strong> 2017 COLOR. 15\u2019. VOSE<\/li>\r\n \t<li><strong>\"BONBON\u00c9\"<\/strong> 2017 COLOR. 15\u2019. VOSE<\/li>\r\n \t<li><strong>\"AYNY\"<\/strong> 2016 COLOR. 11\u2019. VOSE<\/li>\r\n \t<li><strong>\"FIVE BOYS AND A WHEEL\"<\/strong> 2016 COLOR. 20\u2019. VOSE<\/li>\r\n<\/ul>\r\n\r\n<p style=\"text-align:center\" class=\"has-text-color has-medium-font-size has-luminous-vivid-orange-color\"><a href=\"https:\/\/www.reservaentradas.com\/sesiones\/valencia\/cinesbabel\/programa-de-cortos-filmlab-palestine\/596?proximamente=true&amp;\"><strong>COMPRAR ENTRADAS<\/strong><\/a><\/p>\r\n&nbsp\r\n\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-verdad\/\" data-onclick=\"link\" data-color=\"#fcc312\" title=\"LA VERDAD 106&#039;\" data-event-id=\"427\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"3\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-verdad\/\"  data-onclick=\"link\" data-color=\"#fcc312\" title=\"LA VERDAD 106&#039;\" data-event-id=\"427\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fcc312; \" data-event-background-image-url=\"\" data-event-id=\"427\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">LA VERDAD 106&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"427\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/tu-merites-un-amour\/\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"TU M\u00c9RITES UN AMOUR 102&#039; Con la presencia de la directora, Hafsia Herzi\" data-event-id=\"432\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 500px;\" data-top=\"500\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\" https:\/\/lamostradevalencia.com\/peliculas\/tu-merites-un-amour\/\"  data-onclick=\"link\" data-color=\"#ff7675\" title=\"TU M\u00c9RITES UN AMOUR 102&#039; Con la presencia de la directora, Hafsia Herzi\" data-event-id=\"432\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 500px\" data-top=\"500\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ff7675; \" data-event-background-image-url=\"\" data-event-id=\"432\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">TU M\u00c9RITES UN AMOUR 102&#039; Con la presencia de la directora, Hafsia Herzi<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"432\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/the-day-i-lost-my-shadow\/\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"THE DAY I LOST MY SHADOW 94&#039; Con la presencia de la directora, Soudade Kaadan\" data-event-id=\"433\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 725px;\" data-top=\"725\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\" https:\/\/lamostradevalencia.com\/peliculas\/the-day-i-lost-my-shadow\/\"  data-onclick=\"link\" data-color=\"#ff7675\" title=\"THE DAY I LOST MY SHADOW 94&#039; Con la presencia de la directora, Soudade Kaadan\" data-event-id=\"433\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 725px\" data-top=\"725\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ff7675; \" data-event-background-image-url=\"\" data-event-id=\"433\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">THE DAY I LOST MY SHADOW 94&#039; Con la presencia de la directora, Soudade Kaadan<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"433\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/de-rodillas-corazon\/\" data-onclick=\"link\" data-color=\"#0694d6\" title=\"DE RODILLAS CORAZ\u00d3N 90&#039; Con la presencia de la directora, Susanna Barranco y la core\u00f3grafa Sol Pic\u00f3\" data-event-id=\"434\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 925px;\" data-top=\"925\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/de-rodillas-corazon\/\"  data-onclick=\"link\" data-color=\"#0694d6\" title=\"DE RODILLAS CORAZ\u00d3N 90&#039; Con la presencia de la directora, Susanna Barranco y la core\u00f3grafa Sol Pic\u00f3\" data-event-id=\"434\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 925px\" data-top=\"925\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #0694d6; \" data-event-background-image-url=\"\" data-event-id=\"434\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">DE RODILLAS CORAZ\u00d3N 90&#039; Con la presencia de la directora, Susanna Barranco y la core\u00f3grafa Sol Pic\u00f3<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"434\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/the-miracle-of-the-sargasso-sea\/\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"THE MIRACLE OF THE SARGASSO SEA 121&#039; Con la presencia de la actriz Angeliki Papoulia\" data-event-id=\"431\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 200px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"3\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/the-miracle-of-the-sargasso-sea\/\"  data-onclick=\"link\" data-color=\"#ff7675\" title=\"THE MIRACLE OF THE SARGASSO SEA 121&#039; Con la presencia de la actriz Angeliki Papoulia\" data-event-id=\"431\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 200px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ff7675; \" data-event-background-image-url=\"\" data-event-id=\"431\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">THE MIRACLE OF THE SARGASSO SEA 121&#039; Con la presencia de la actriz Angeliki Papoulia<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"431\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/chaos-disorder\/\" data-onclick=\"link\" data-color=\"#d63031\" title=\"CHAOS, DISORDER 77&#039; Con la presencia de la directora, Nadine Kahn\" data-event-id=\"436\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 500px;\" data-top=\"500\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/chaos-disorder\/\"  data-onclick=\"link\" data-color=\"#d63031\" title=\"CHAOS, DISORDER 77&#039; Con la presencia de la directora, Nadine Kahn\" data-event-id=\"436\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 500px\" data-top=\"500\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #d63031; \" data-event-background-image-url=\"\" data-event-id=\"436\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">CHAOS, DISORDER 77&#039; Con la presencia de la directora, Nadine Kahn<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"436\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/venis-desde-lejos\/\" data-onclick=\"link\" data-color=\"#d63031\" title=\"VEN\u00cdS DESDE LEJOS 85&#039; Con la presencia de la directora, Amal Ramsis\" data-event-id=\"437\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 700px;\" data-top=\"700\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/venis-desde-lejos\/\"  data-onclick=\"link\" data-color=\"#d63031\" title=\"VEN\u00cdS DESDE LEJOS 85&#039; Con la presencia de la directora, Amal Ramsis\" data-event-id=\"437\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 700px\" data-top=\"700\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #d63031; \" data-event-background-image-url=\"\" data-event-id=\"437\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">VEN\u00cdS DESDE LEJOS 85&#039; Con la presencia de la directora, Amal Ramsis<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"437\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/women-who-loved-cinema\/\" data-onclick=\"link\" data-color=\"#d63031\" title=\"WOMEN WHO LOVED CINEMA 120&#039;\" data-event-id=\"438\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 200px; left: 925px;\" data-top=\"925\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/women-who-loved-cinema\/\"  data-onclick=\"link\" data-color=\"#d63031\" title=\"WOMEN WHO LOVED CINEMA 120&#039;\" data-event-id=\"438\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 200px; top: 925px\" data-top=\"925\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #d63031; \" data-event-background-image-url=\"\" data-event-id=\"438\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">WOMEN WHO LOVED CINEMA 120&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"438\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/cut-and-paste\/\" data-onclick=\"link\" data-color=\"#d63031\" title=\"CUT AND PASTE 105&#039;\" data-event-id=\"435\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"3\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/cut-and-paste\/\"  data-onclick=\"link\" data-color=\"#d63031\" title=\"CUT AND PASTE 105&#039;\" data-event-id=\"435\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #d63031; \" data-event-background-image-url=\"\" data-event-id=\"435\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">CUT AND PASTE 105&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"435\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/de-quelques-evenements-sans-signification\/\" data-onclick=\"link\" data-color=\"#0694d6\" title=\"DE QUELQUES \u00c9V\u00c8NEMENTS SANS SIGNIFICATION 74&#039; Con la presencia de Esteve Riambau, director de Filmoteca de Catalunya\" data-event-id=\"439\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 900px;\" data-top=\"900\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/de-quelques-evenements-sans-signification\/\"  data-onclick=\"link\" data-color=\"#0694d6\" title=\"DE QUELQUES \u00c9V\u00c8NEMENTS SANS SIGNIFICATION 74&#039; Con la presencia de Esteve Riambau, director de Filmoteca de Catalunya\" data-event-id=\"439\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 900px\" data-top=\"900\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #0694d6; \" data-event-background-image-url=\"\" data-event-id=\"439\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">DE QUELQUES \u00c9V\u00c8NEMENTS SANS SIGNIFICATION 74&#039; Con la presencia de Esteve Riambau, director de Filmoteca de Catalunya<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"439\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/concierto-banda-municipal-valencia\/\" data-onclick=\"link\" data-color=\"#833471\" title=\"CONCIERTO BANDA MUNICIPAL DE VAL\u00c8NCIA Compositores mediterr\u00e1neos de cine\" data-event-id=\"562\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 100px;\" data-top=\"100\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/concierto-banda-municipal-valencia\/\"  data-onclick=\"link\" data-color=\"#833471\" title=\"CONCIERTO BANDA MUNICIPAL DE VAL\u00c8NCIA Compositores mediterr\u00e1neos de cine\" data-event-id=\"562\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 100px\" data-top=\"100\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #833471; \" data-event-background-image-url=\"\" data-event-id=\"562\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">CONCIERTO BANDA MUNICIPAL DE VAL\u00c8NCIA Compositores mediterr\u00e1neos de cine<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"562\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n<\/div><div class=\" sched-list sched-hidden\" id=\"sched-schedule-11-367451792-list\" data-id-schedule=\"sched-schedule-11-367451792\" data-options=\" {&quot;am_pm&quot;:&quot;0&quot;,&quot;sidebar_width&quot;:&quot;90&quot;,&quot;sidebar_position&quot;:&quot;left&quot;,&quot;event_hover_color&quot;:&quot;lighten&quot;,&quot;event_box_text_align&quot;:&quot;center&quot;,&quot;event_box_time&quot;:&quot;0&quot;,&quot;event_hover_text_color&quot;:&quot;#FFFFFF&quot;,&quot;event_hover_background_color&quot;:&quot;#000000&quot;,&quot;event_box_truncate_title&quot;:&quot;0&quot;,&quot;event_tooltip&quot;:&quot;0&quot;,&quot;event_tooltip_title&quot;:&quot;1&quot;,&quot;event_tooltip_time&quot;:&quot;1&quot;,&quot;event_tooltip_description&quot;:&quot;1&quot;,&quot;event_tooltip_width_type&quot;:&quot;event&quot;,&quot;event_tooltip_width&quot;:&quot;150&quot;,&quot;event_tooltip_color_type&quot;:&quot;event&quot;,&quot;event_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;event_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;column_tooltip&quot;:&quot;0&quot;,&quot;column_tooltip_title&quot;:&quot;1&quot;,&quot;column_tooltip_description&quot;:&quot;1&quot;,&quot;column_tooltip_width_type&quot;:&quot;column&quot;,&quot;column_tooltip_width&quot;:&quot;150&quot;,&quot;column_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;column_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;animations&quot;:&quot;1&quot;,&quot;animations_mobile&quot;:&quot;1&quot;,&quot;animations_speed&quot;:&quot;normal&quot;,&quot;animations_css3&quot;:&quot;1&quot;,&quot;tooltips_mobile&quot;:&quot;1&quot;,&quot;editor_bg&quot;:&quot;#F5F5F5&quot;,&quot;animations_editor&quot;:&quot;1&quot;,&quot;popup_max_width&quot;:&quot;560&quot;,&quot;popup_background_color&quot;:&quot;#ffffff&quot;,&quot;popup_text_color&quot;:&quot;#535353&quot;,&quot;popup_link_color&quot;:&quot;#ff4d00&quot;,&quot;autoplay_videos&quot;:&quot;1&quot;,&quot;column_color_bg&quot;:&quot;#e8e8e8&quot;,&quot;column_color_text&quot;:&quot;#3f3f3f&quot;,&quot;column_color_border&quot;:&quot;#ffffff&quot;,&quot;pattern_color_1&quot;:&quot;#ffffff&quot;,&quot;pattern_color_2&quot;:&quot;#e8e8e8&quot;,&quot;pattern_color_3&quot;:&quot;#ffffff&quot;,&quot;title_text_color&quot;:&quot;#3f3f3f&quot;,&quot;sidebar_text_color&quot;:&quot;#3f3f3f&quot;,&quot;event_box_text_color&quot;:&quot;#ffffff&quot;,&quot;title_attr&quot;:&quot;0&quot;,&quot;column_break&quot;:1,&quot;column_break_width&quot;:&quot;120&quot;,&quot;column_break_hide_sidebar&quot;:&quot;0&quot;,&quot;editor_custom_css&quot;:&quot;1&quot;,&quot;column_title&quot;:&quot;1&quot;,&quot;event_box_description_method&quot;:&quot;short&quot;,&quot;editor_quick_tooltips&quot;:&quot;1&quot;,&quot;editor_timepicker_increments&quot;:&quot;15&quot;,&quot;event_box_style&quot;:&quot;1&quot;,&quot;filter_position&quot;:&quot;right&quot;,&quot;filter_multiple&quot;:&quot;1&quot;,&quot;filter_hidden_events&quot;:&quot;hide&quot;,&quot;filter_hidden_events_opacity&quot;:&quot;30&quot;,&quot;filter_dropdown_width&quot;:&quot;100&quot;,&quot;filter_dropdown_hover_width&quot;:&quot;180&quot;,&quot;filter_dropdown_label&quot;:&quot;Secci\\u00f3n&quot;,&quot;filter_dropdown_show_all_label&quot;:&quot;Mostrar todo&quot;,&quot;hashtag_url&quot;:&quot;1&quot;,&quot;hide_popup_for_empty_events&quot;:&quot;1&quot;,&quot;event_box_padding_break&quot;:&quot;200&quot;,&quot;popup_arrows&quot;:&quot;1&quot;,&quot;filter_visible&quot;:&quot;1&quot;,&quot;column_break_action&quot;:&quot;list&quot;,&quot;list_view_column_title_color&quot;:&quot;#3f3f3f&quot;,&quot;list_view_event_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_hover_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_title_bold&quot;:&quot;1&quot;,&quot;list_view_event_bullets&quot;:&quot;2&quot;,&quot;list_view_event_short_description_method&quot;:&quot;short&quot;,&quot;list_view_event_description_color&quot;:&quot;#ffffff&quot;,&quot;list_view_hide_empty_columns&quot;:&quot;1&quot;,&quot;shortcodes_in_descriptions&quot;:&quot;1&quot;,&quot;columns_sticky_header&quot;:&quot;1&quot;,&quot;columns_sticky_header_offset&quot;:&quot;0&quot;,&quot;h_row_height&quot;:&quot;110&quot;,&quot;h_column_width&quot;:&quot;200&quot;,&quot;h_time_indicator&quot;:&quot;1&quot;,&quot;h_time_indicator_height&quot;:30,&quot;h_column_multiline&quot;:&quot;0&quot;,&quot;h_column_title_position&quot;:&quot;middle&quot;,&quot;h_column_title_align&quot;:&quot;center&quot;,&quot;h_break&quot;:&quot;0&quot;,&quot;h_width_break_point&quot;:&quot;200&quot;,&quot;h_bg_color&quot;:&quot;#f8f8f8&quot;,&quot;pdf_type&quot;:&quot;html&quot;,&quot;pdf_enable&quot;:&quot;0&quot;,&quot;pdf_enable_list&quot;:&quot;0&quot;,&quot;pdf_label&quot;:&quot;Download&quot;,&quot;pdf_css&quot;:&quot;&quot;,&quot;upcoming_type&quot;:&quot;current_datetime&quot;,&quot;upcoming_custom&quot;:&quot;2016-01-01 00:00&quot;,&quot;upcoming_limit&quot;:&quot;5&quot;,&quot;upcoming_title&quot;:&quot;timetable_title&quot;,&quot;upcoming_title_custom&quot;:&quot;Upcoming Events&quot;,&quot;upcoming_title_amount&quot;:&quot;1&quot;}\" data-start=\"11:00\" data-end=\"01:30\" data-timetable-id=\"11\" data-type=\"list\" data-layout=\"horizontal\">\t<div class=\"sched-list-top\">\n\t\t<div class=\"sched-list-title\">Domingo 27 de octubre<\/div>\n\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 1<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/alice\/\" data-event-id=\"418\" style=\"background: #ff7675;\" data-color=\"#ff7675\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ff7675;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tALICE 103&#039; Con la presencia de Mickael Dalahie (Director de Fotograf\u00eda y Eug\u00e9nie Gressier (Directora de Producci\u00f3n)\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">11:30 - 13:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/dove-la-liberta\/\" data-event-id=\"419\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tDOV&#039;\u00c8 LA LIBERT\u00c0\u2026? 93&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 17:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-camisa-de-la-serp\/\" data-event-id=\"421\" style=\"background: #a3cb38;\" data-color=\"#a3cb38\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #a3cb38;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tLA CAMISA DE LA SERP 92&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/todos-a-casa\/\" data-event-id=\"420\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tTODOS A CASA 122&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 22:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/las-alas-de-la-vida\/\" data-event-id=\"190\" style=\"background: #a3cb38;\" data-color=\"#a3cb38\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #a3cb38;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tLAS ALAS DE LA VIDA 90&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 2<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/poveri-ma-belli\/\" data-event-id=\"425\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tPOVERI MA BELLI 101&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/divorcio-a-la-italiana\/\" data-event-id=\"426\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tDIVORCIO A LA ITALIANA 105&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 21:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-armada-brancaleone\/\" data-event-id=\"423\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tLA ARMADA BRANCALEONE 120&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 3<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/dafne\/\" data-event-id=\"429\" style=\"background: #fcc312;\" data-color=\"#fcc312\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fcc312;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tDAFNE 94&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 17:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/mar\/\" data-event-id=\"430\" style=\"background: #fcc312;\" data-color=\"#fcc312\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fcc312;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tMAR 103&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"#event-424\" data-event-id=\"424\" style=\"background: #0694d6;\" data-color=\"#0694d6\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #0694d6;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tPROGRAMA DE CORTOS FILMLAB PALESTINE 108&#039; Presentado por Muayad Alayan\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 21:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-verdad\/\" data-event-id=\"427\" style=\"background: #fcc312;\" data-color=\"#fcc312\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fcc312;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tLA VERDAD 106&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 4<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/tu-merites-un-amour\/\" data-event-id=\"432\" style=\"background: #ff7675;\" data-color=\"#ff7675\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ff7675;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tTU M\u00c9RITES UN AMOUR 102&#039; Con la presencia de la directora, Hafsia Herzi\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 17:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/the-day-i-lost-my-shadow\/\" data-event-id=\"433\" style=\"background: #ff7675;\" data-color=\"#ff7675\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ff7675;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tTHE DAY I LOST MY SHADOW 94&#039; Con la presencia de la directora, Soudade Kaadan\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:15 - 19:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/de-rodillas-corazon\/\" data-event-id=\"434\" style=\"background: #0694d6;\" data-color=\"#0694d6\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #0694d6;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tDE RODILLAS CORAZ\u00d3N 90&#039; Con la presencia de la directora, Susanna Barranco y la core\u00f3grafa Sol Pic\u00f3\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:15 - 22:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/the-miracle-of-the-sargasso-sea\/\" data-event-id=\"431\" style=\"background: #ff7675;\" data-color=\"#ff7675\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ff7675;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tTHE MIRACLE OF THE SARGASSO SEA 121&#039; Con la presencia de la actriz Angeliki Papoulia\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 5<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/chaos-disorder\/\" data-event-id=\"436\" style=\"background: #d63031;\" data-color=\"#d63031\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #d63031;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tCHAOS, DISORDER 77&#039; Con la presencia de la directora, Nadine Kahn\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 17:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/venis-desde-lejos\/\" data-event-id=\"437\" style=\"background: #d63031;\" data-color=\"#d63031\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #d63031;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tVEN\u00cdS DESDE LEJOS 85&#039; Con la presencia de la directora, Amal Ramsis\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/women-who-loved-cinema\/\" data-event-id=\"438\" style=\"background: #d63031;\" data-color=\"#d63031\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #d63031;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tWOMEN WHO LOVED CINEMA 120&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:15 - 22:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/cut-and-paste\/\" data-event-id=\"435\" style=\"background: #d63031;\" data-color=\"#d63031\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #d63031;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tCUT AND PASTE 105&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">FILMOTECA<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/de-quelques-evenements-sans-signification\/\" data-event-id=\"439\" style=\"background: #0694d6;\" data-color=\"#0694d6\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #0694d6;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tDE QUELQUES \u00c9V\u00c8NEMENTS SANS SIGNIFICATION 74&#039; Con la presencia de Esteve Riambau, director de Filmoteca de Catalunya\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 21:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">PALAU DE CONGRESSOS DE VAL\u00c8NCIA<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/concierto-banda-municipal-valencia\/\" data-event-id=\"562\" style=\"background: #833471;\" data-color=\"#833471\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #833471;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tCONCIERTO BANDA MUNICIPAL DE VAL\u00c8NCIA Compositores mediterr\u00e1neos de cine\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">12:00 - 13:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t<!-- .sched-list-column -->\n\t\n<\/div>[\/vc_column][\/vc_row][vc_row disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1600188383007{padding-right: 40px !important;padding-bottom: 50px !important;padding-left: 40px !important;}&#8221; anchor=&#8221;lunes-28&#8243;][vc_column]<div class=\"sched-loader\"><div class=\"sched-loader-icon\"><\/div><div class=\"sched-loader-text\"><\/div><\/div>\n<div class=\" sched sched-horizontal sched-horizontal-medium\" id=\"sched-schedule-5-933497302\" data-options=\" {&quot;am_pm&quot;:&quot;0&quot;,&quot;sidebar_width&quot;:&quot;90&quot;,&quot;sidebar_position&quot;:&quot;left&quot;,&quot;event_hover_color&quot;:&quot;lighten&quot;,&quot;event_box_text_align&quot;:&quot;center&quot;,&quot;event_box_time&quot;:&quot;0&quot;,&quot;event_hover_text_color&quot;:&quot;#FFFFFF&quot;,&quot;event_hover_background_color&quot;:&quot;#000000&quot;,&quot;event_box_truncate_title&quot;:&quot;0&quot;,&quot;event_tooltip&quot;:&quot;0&quot;,&quot;event_tooltip_title&quot;:&quot;1&quot;,&quot;event_tooltip_time&quot;:&quot;1&quot;,&quot;event_tooltip_description&quot;:&quot;1&quot;,&quot;event_tooltip_width_type&quot;:&quot;event&quot;,&quot;event_tooltip_width&quot;:&quot;150&quot;,&quot;event_tooltip_color_type&quot;:&quot;event&quot;,&quot;event_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;event_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;column_tooltip&quot;:&quot;0&quot;,&quot;column_tooltip_title&quot;:&quot;1&quot;,&quot;column_tooltip_description&quot;:&quot;1&quot;,&quot;column_tooltip_width_type&quot;:&quot;column&quot;,&quot;column_tooltip_width&quot;:&quot;150&quot;,&quot;column_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;column_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;animations&quot;:&quot;1&quot;,&quot;animations_mobile&quot;:&quot;1&quot;,&quot;animations_speed&quot;:&quot;normal&quot;,&quot;animations_css3&quot;:&quot;1&quot;,&quot;tooltips_mobile&quot;:&quot;1&quot;,&quot;editor_bg&quot;:&quot;#F5F5F5&quot;,&quot;animations_editor&quot;:&quot;1&quot;,&quot;popup_max_width&quot;:&quot;560&quot;,&quot;popup_background_color&quot;:&quot;#ffffff&quot;,&quot;popup_text_color&quot;:&quot;#535353&quot;,&quot;popup_link_color&quot;:&quot;#ff4d00&quot;,&quot;autoplay_videos&quot;:&quot;1&quot;,&quot;column_color_bg&quot;:&quot;#e8e8e8&quot;,&quot;column_color_text&quot;:&quot;#3f3f3f&quot;,&quot;column_color_border&quot;:&quot;#ffffff&quot;,&quot;pattern_color_1&quot;:&quot;#ffffff&quot;,&quot;pattern_color_2&quot;:&quot;#e8e8e8&quot;,&quot;pattern_color_3&quot;:&quot;#ffffff&quot;,&quot;title_text_color&quot;:&quot;#3f3f3f&quot;,&quot;sidebar_text_color&quot;:&quot;#3f3f3f&quot;,&quot;event_box_text_color&quot;:&quot;#ffffff&quot;,&quot;title_attr&quot;:&quot;0&quot;,&quot;column_break&quot;:1,&quot;column_break_width&quot;:&quot;120&quot;,&quot;column_break_hide_sidebar&quot;:&quot;0&quot;,&quot;editor_custom_css&quot;:&quot;1&quot;,&quot;column_title&quot;:&quot;1&quot;,&quot;event_box_description_method&quot;:&quot;short&quot;,&quot;editor_quick_tooltips&quot;:&quot;1&quot;,&quot;editor_timepicker_increments&quot;:&quot;15&quot;,&quot;event_box_style&quot;:&quot;1&quot;,&quot;filter_position&quot;:&quot;right&quot;,&quot;filter_multiple&quot;:&quot;1&quot;,&quot;filter_hidden_events&quot;:&quot;hide&quot;,&quot;filter_hidden_events_opacity&quot;:&quot;30&quot;,&quot;filter_dropdown_width&quot;:&quot;100&quot;,&quot;filter_dropdown_hover_width&quot;:&quot;180&quot;,&quot;filter_dropdown_label&quot;:&quot;Secci\\u00f3n&quot;,&quot;filter_dropdown_show_all_label&quot;:&quot;Mostrar todo&quot;,&quot;hashtag_url&quot;:&quot;1&quot;,&quot;hide_popup_for_empty_events&quot;:&quot;1&quot;,&quot;event_box_padding_break&quot;:&quot;200&quot;,&quot;popup_arrows&quot;:&quot;1&quot;,&quot;filter_visible&quot;:&quot;1&quot;,&quot;column_break_action&quot;:&quot;list&quot;,&quot;list_view_column_title_color&quot;:&quot;#3f3f3f&quot;,&quot;list_view_event_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_hover_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_title_bold&quot;:&quot;1&quot;,&quot;list_view_event_bullets&quot;:&quot;2&quot;,&quot;list_view_event_short_description_method&quot;:&quot;short&quot;,&quot;list_view_event_description_color&quot;:&quot;#ffffff&quot;,&quot;list_view_hide_empty_columns&quot;:&quot;1&quot;,&quot;shortcodes_in_descriptions&quot;:&quot;1&quot;,&quot;columns_sticky_header&quot;:&quot;1&quot;,&quot;columns_sticky_header_offset&quot;:&quot;0&quot;,&quot;h_row_height&quot;:&quot;110&quot;,&quot;h_column_width&quot;:&quot;200&quot;,&quot;h_time_indicator&quot;:&quot;1&quot;,&quot;h_time_indicator_height&quot;:30,&quot;h_column_multiline&quot;:&quot;0&quot;,&quot;h_column_title_position&quot;:&quot;middle&quot;,&quot;h_column_title_align&quot;:&quot;center&quot;,&quot;h_break&quot;:&quot;0&quot;,&quot;h_width_break_point&quot;:&quot;200&quot;,&quot;h_bg_color&quot;:&quot;#f8f8f8&quot;,&quot;pdf_type&quot;:&quot;html&quot;,&quot;pdf_enable&quot;:&quot;0&quot;,&quot;pdf_enable_list&quot;:&quot;0&quot;,&quot;pdf_label&quot;:&quot;Download&quot;,&quot;pdf_css&quot;:&quot;&quot;,&quot;upcoming_type&quot;:&quot;current_datetime&quot;,&quot;upcoming_custom&quot;:&quot;2016-01-01 00:00&quot;,&quot;upcoming_limit&quot;:&quot;5&quot;,&quot;upcoming_title&quot;:&quot;timetable_title&quot;,&quot;upcoming_title_custom&quot;:&quot;Upcoming Events&quot;,&quot;upcoming_title_amount&quot;:&quot;1&quot;}\" data-start=\"10:00\" data-end=\"01:30\" data-timetable-id=\"5\" data-type=\"full\" data-list-id=\"#sched-schedule-5-933497302-list\" data-layout=\"horizontal\">\t<div class=\"sched-style\"><style type=\"text\/css\">\/*\n * Custom CSS For Timetable\n*\/\n\n#sched-schedule-5-933497302 .sched-column-header,\n#sched-schedule-5-933497302 .sched-column-header-sticky {\n\tbackground: #e8e8e8;\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-5-933497302 .sched-column-header:after,\n#sched-schedule-5-933497302 .sched-column-header-sticky:after {\n\tbackground: #ffffff;\n}\n\n#sched-schedule-5-933497302 .sched-columns .sched-column:last-child .sched-column-header:after,\n#sched-schedule-5-933497302 .sched-columns .sched-column:last-child .sched-column-header-sticky:after {\n\tbackground: #e8e8e8;\n}\n\n#sched-schedule-5-933497302 .sched-column-bg-block {\n\tbackground: #ffffff;\n\tborder-color: #e8e8e8;\n}\n\n#sched-schedule-5-933497302 .sched-column-bg-block:after {\n\tbackground: #ffffff;\n}\n\n#sched-schedule-5-933497302 .sched-row-no-title .sched-column .sched-column-bg {\n\tbox-shadow: 0 -1px 0 #e8e8e8;\n}\n\n#sched-schedule-5-933497302 .sched-title {\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-5-933497302 .sched-time-value {\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-5-933497302 .sched-event .sched-event-inner {\n\tcolor: #ffffff;\n\ttext-align: center;\n}\n\n#sched-schedule-5-933497302 .sched-event.sched-event-invert .sched-event-inner {\n\t<!-- background: #999; -->\n}\n\n\n\n\/*#sched-schedule-5-933497302 a.sched-event.sched-event-sort-hidden {\n\topacity: 0;\n}*\/\n\n#sched-schedule-5-933497302 .sched-sort .sched-sort-current .sched-sort-current-label {\n\twidth: 100px;\n}\n\n#sched-schedule-5-933497302 .sched-sort.sched-sort-open .sched-sort-dropdown .sched-sort-current .sched-sort-current-label {\n\twidth: 180px;\n}\n\n\/*\n * Custom CSS Event Popup\n *\/\n\n#sched-schedule-5-933497302-popup .sched-popup-description {\n\t\n}\n\n#sched-schedule-5-933497302-popup .sched-popup-description .sched-meta a,\n#sched-schedule-5-933497302-popup .sched-popup-description .sched-popup-description-text a {\n\tcolor: #ff4d00;\n}\n\n#sched-schedule-5-933497302-popup .sched-popup-description .sched-meta,\n#sched-schedule-5-933497302-popup .sched-popup-description .sched-popup-description-text {\n\tcolor: #535353;\n\tbackground: #ffffff;\n}\n\n\/*\n * List\n *\/\n\n#sched-schedule-5-933497302-list .sched-list-title {\n\tcolor: #3f3f3f;\n}\n\n\n\n#sched-schedule-5-933497302-list .sched-list-column-title {\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-5-933497302-list .sched-list-event {\n\tcolor: #ffffff;\n\t\n\t\n}\n\n#sched-schedule-5-933497302-list .sched-list-event:hover {\n\tcolor: #ffffff;\n}\n\n#sched-schedule-5-933497302-list .sched-list-event-description {\n\tcolor: #ffffff;\n}\n\n#sched-schedule-5-933497302-list .sched-list-event-title {\n\t\tfont-weight: bold;\n\t;\n}\n\n\/*\n * Horizontal\n *\/\n\n\n\n#sched-schedule-5-933497302 .sched-h-columns {\n\tmargin-top: 30px;\n}\n\n#sched-schedule-5-933497302 .sched-h-content-columns {\n\t\/*margin-top: 30px;*\/\n}\n\n\n#sched-schedule-5-933497302 .sched-h-columns {\n\twidth: 200px;\n}\n\n#sched-schedule-5-933497302 .sched-h-content {\n\tmargin-left: 200px;\n}\n\n#sched-schedule-5-933497302 .sched-h-column-title {\n\ttext-align: center;\n}\n\n#sched-schedule-5-933497302 .sched-h-column {\n\tbackground: #e8e8e8;\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-5-933497302 .sched-h-row {\n\tbackground-color: #f8f8f8;\n}\n<\/style><\/div>\n\t<div class=\"sched-top\">\n\t\t\t<h2 class=\"sched-title\">Lunes 28 de octubre<\/h2>\n\t\t<div class=\"sched-top-buttons sched-top-buttons-right\">\n\t\t\t\n\t\t\t<\/div><!-- .sched-top-buttons -->\n<\/div><!-- .sched-top -->\t<div class=\"sched-row\">\n\t\t\t\t\t<!-- <div class=\"sched-sidebar\" style=\"width: 90px;\">\n\t\t\t\t<div class=\"sched-time\">\n\t\t\t\t\t<div class=\"sched-time-value\" style=\"padding-bottom: 36px\">10:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">11:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">12:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">13:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">14:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">15:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">16:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">17:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">18:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">19:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">20:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">21:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">22:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">23:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">00:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">01:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">02:00<\/div>\t\t\t\t<\/div>\n\t\t\t<\/div> -->\n\t\t\t\t\t\t<div class=\"sched-h-columns\">\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 1\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 2\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 3\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 4\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 5\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tFILMOTECA\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tOTROS ESPACIOS\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"sched-h-content\">\n\t\t\t<div class=\"sched-h-content-scroll\">\n\t\t\t\t\t\t\t\t<div class=\"sched-h-content-scroll-time\">\n\t\t\t\t\t<div class=\"sched-h-content-scroll-time-value\" data-i=\"0\" style=\"left: 0px;\">10:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"1\" style=\"left: 100px;\">11:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"2\" style=\"left: 200px;\">12:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"3\" style=\"left: 300px;\">13:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"4\" style=\"left: 400px;\">14:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"5\" style=\"left: 500px;\">15:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"6\" style=\"left: 600px;\">16:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"7\" style=\"left: 700px;\">17:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"8\" style=\"left: 800px;\">18:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"9\" style=\"left: 900px;\">19:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"10\" style=\"left: 1000px;\">20:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"11\" style=\"left: 1100px;\">21:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"12\" style=\"left: 1200px;\">22:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"13\" style=\"left: 1300px;\">23:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"14\" style=\"left: 1400px;\">00:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"15\" style=\"left: 1500px;\">01:00<\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"sched-h-content-columns\">\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1550px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/the-announcement\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"THE ANNOUNCEMENT 94&#039; Con la presencia del actor \u015eencan G\u00fclery\u00fcz\" data-event-id=\"72\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 150px;\" data-top=\"150\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\" https:\/\/lamostradevalencia.com\/peliculas\/the-announcement\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"THE ANNOUNCEMENT 94&#039; Con la presencia del actor \u015eencan G\u00fclery\u00fcz\" data-event-id=\"72\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 150px\" data-top=\"150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ff7675; \" data-event-background-image-url=\"\" data-event-id=\"72\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">THE ANNOUNCEMENT 94&#039; Con la presencia del actor \u015eencan G\u00fclery\u00fcz<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"72\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-alcalde-el-guardia-y-la-jirafita\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#128997\" title=\"EL ALCALDE, EL GUARDIA Y LA JIRAFITA 100&#039;\" data-event-id=\"440\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 600px;\" data-top=\"600\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-alcalde-el-guardia-y-la-jirafita\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#128997\" title=\"EL ALCALDE, EL GUARDIA Y LA JIRAFITA 100&#039;\" data-event-id=\"440\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 600px\" data-top=\"600\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"440\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">EL ALCALDE, EL GUARDIA Y LA JIRAFITA 100&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"440\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/magnifica-presenza\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"MAGNIFICA PRESENZA 105&#039;\" data-event-id=\"441\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 800px;\" data-top=\"800\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/magnifica-presenza\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"MAGNIFICA PRESENZA 105&#039;\" data-event-id=\"441\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 800px\" data-top=\"800\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #27ae60; \" data-event-background-image-url=\"\" data-event-id=\"441\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">MAGNIFICA PRESENZA 105&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"441\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/celos-a-la-italiana\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#128997\" title=\"CELOS A LA ITALIANA 124&#039;\" data-event-id=\"73\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 200px; left: 1000px;\" data-top=\"1000\" data-size=\"1\" data-sort-index=\"3\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/celos-a-la-italiana\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#128997\" title=\"CELOS A LA ITALIANA 124&#039;\" data-event-id=\"73\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 200px; top: 1000px\" data-top=\"1000\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"73\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">CELOS A LA ITALIANA 124&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"73\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/no-basta-una-vida\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"NO BASTA UNA VIDA 110&#039;\" data-event-id=\"74\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 1250px;\" data-top=\"1250\" data-size=\"1\" data-sort-index=\"4\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/no-basta-una-vida\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"NO BASTA UNA VIDA 110&#039;\" data-event-id=\"74\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 1250px\" data-top=\"1250\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #27ae60; \" data-event-background-image-url=\"\" data-event-id=\"74\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">NO BASTA UNA VIDA 110&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"74\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1550px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/poveri-ma-belli\/\" data-onclick=\"link\" data-color=\"#128997\" title=\"POVERI MA BELLI 101&#039;\" data-event-id=\"442\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 600px;\" data-top=\"600\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/poveri-ma-belli\/\"  data-onclick=\"link\" data-color=\"#128997\" title=\"POVERI MA BELLI 101&#039;\" data-event-id=\"442\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 600px\" data-top=\"600\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"442\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">POVERI MA BELLI 101&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"442\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/guapas-pero-pobres\/\" data-onclick=\"link\" data-color=\"#128997\" title=\"GUAPAS, PERO POBRES 99&#039;\" data-event-id=\"443\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 800px;\" data-top=\"800\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/guapas-pero-pobres\/\"  data-onclick=\"link\" data-color=\"#128997\" title=\"GUAPAS, PERO POBRES 99&#039;\" data-event-id=\"443\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 800px\" data-top=\"800\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"443\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">GUAPAS, PERO POBRES 99&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"443\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/pobre-y-millonario\/\" data-onclick=\"link\" data-color=\"#128997\" title=\"POBRE Y MILLONARIO 95&#039;\" data-event-id=\"444\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 1000px;\" data-top=\"1000\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/pobre-y-millonario\/\"  data-onclick=\"link\" data-color=\"#128997\" title=\"POBRE Y MILLONARIO 95&#039;\" data-event-id=\"444\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 1000px\" data-top=\"1000\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"444\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">POBRE Y MILLONARIO 95&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"444\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-ultimo-haren\/\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"EL \u00daLTIMO HAR\u00c9N 115&#039;\" data-event-id=\"77\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 200px; left: 1250px;\" data-top=\"1250\" data-size=\"1\" data-sort-index=\"3\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-ultimo-haren\/\"  data-onclick=\"link\" data-color=\"#27ae60\" title=\"EL \u00daLTIMO HAR\u00c9N 115&#039;\" data-event-id=\"77\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 200px; top: 1250px\" data-top=\"1250\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #27ae60; \" data-event-background-image-url=\"\" data-event-id=\"77\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">EL \u00daLTIMO HAR\u00c9N 115&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"77\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1550px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/head-above-water\/\" data-onclick=\"link\" data-color=\"#fcc312\" title=\"HEAD ABOVE WATER 85&#039;\" data-event-id=\"445\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 600px;\" data-top=\"600\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/head-above-water\/\"  data-onclick=\"link\" data-color=\"#fcc312\" title=\"HEAD ABOVE WATER 85&#039;\" data-event-id=\"445\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 600px\" data-top=\"600\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fcc312; \" data-event-background-image-url=\"\" data-event-id=\"445\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">HEAD ABOVE WATER 85&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"445\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/freedom-fields\/\" data-onclick=\"link\" data-color=\"#ffc312\" title=\"FREEDOM FIELDS 97&#039;\" data-event-id=\"446\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 800px;\" data-top=\"800\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/freedom-fields\/\"  data-onclick=\"link\" data-color=\"#ffc312\" title=\"FREEDOM FIELDS 97&#039;\" data-event-id=\"446\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 800px\" data-top=\"800\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ffc312; \" data-event-background-image-url=\"\" data-event-id=\"446\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">FREEDOM FIELDS 97&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"446\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-inocencia\/\" data-onclick=\"link\" data-color=\"#fcc312\" title=\"LA INOCENCIA 93&#039; Con la presencia de la directora Lucia Alemany, la actriz Carmen Arrufat y el equipo de la pel\u00edcula\" data-event-id=\"447\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 1000px;\" data-top=\"1000\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-inocencia\/\"  data-onclick=\"link\" data-color=\"#fcc312\" title=\"LA INOCENCIA 93&#039; Con la presencia de la directora Lucia Alemany, la actriz Carmen Arrufat y el equipo de la pel\u00edcula\" data-event-id=\"447\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 1000px\" data-top=\"1000\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fcc312; \" data-event-background-image-url=\"\" data-event-id=\"447\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">LA INOCENCIA 93&#039; Con la presencia de la directora Lucia Alemany, la actriz Carmen Arrufat y el equipo de la pel\u00edcula<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"447\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/una-dona-amb-unes-ales-tremendes\/\" data-onclick=\"link\" data-color=\"#ffc312\" title=\"UNA DONA AMB UNES ALES TREMENDES 85&#039; Con la presencia del director, Pedro Rosado, y el equipo de la pel\u00edcula\" data-event-id=\"78\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 1250px;\" data-top=\"1250\" data-size=\"1\" data-sort-index=\"3\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/una-dona-amb-unes-ales-tremendes\/\"  data-onclick=\"link\" data-color=\"#ffc312\" title=\"UNA DONA AMB UNES ALES TREMENDES 85&#039; Con la presencia del director, Pedro Rosado, y el equipo de la pel\u00edcula\" data-event-id=\"78\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 1250px\" data-top=\"1250\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ffc312; \" data-event-background-image-url=\"\" data-event-id=\"78\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">UNA DONA AMB UNES ALES TREMENDES 85&#039; Con la presencia del director, Pedro Rosado, y el equipo de la pel\u00edcula<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"78\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1550px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/a-herdade\/\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"A HERDADE 166&#039; Con la presencia del director Tiago Guedes\" data-event-id=\"448\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 275px; left: 600px;\" data-top=\"600\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\" https:\/\/lamostradevalencia.com\/peliculas\/a-herdade\/\"  data-onclick=\"link\" data-color=\"#ff7675\" title=\"A HERDADE 166&#039; Con la presencia del director Tiago Guedes\" data-event-id=\"448\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 275px; top: 600px\" data-top=\"600\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ff7675; \" data-event-background-image-url=\"\" data-event-id=\"448\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">A HERDADE 166&#039; Con la presencia del director Tiago Guedes<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"448\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/tu-merites-un-amour\/\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"TU M\u00c9RITES UN AMOUR 102&#039; Con la presencia de la directora, Hafsia Herzi\" data-event-id=\"449\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 1000px;\" data-top=\"1000\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\" https:\/\/lamostradevalencia.com\/peliculas\/tu-merites-un-amour\/\"  data-onclick=\"link\" data-color=\"#ff7675\" title=\"TU M\u00c9RITES UN AMOUR 102&#039; Con la presencia de la directora, Hafsia Herzi\" data-event-id=\"449\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 1000px\" data-top=\"1000\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ff7675; \" data-event-background-image-url=\"\" data-event-id=\"449\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">TU M\u00c9RITES UN AMOUR 102&#039; Con la presencia de la directora, Hafsia Herzi<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"449\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/alice\/\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"ALICE 103&#039; Con la presencia de Mickael Delahaie (director de fotograf\u00eda) y Eug\u00e9nie Gressier (directora de producci\u00f3n)\" data-event-id=\"79\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 200px; left: 1250px;\" data-top=\"1250\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\" https:\/\/lamostradevalencia.com\/peliculas\/alice\/\"  data-onclick=\"link\" data-color=\"#ff7675\" title=\"ALICE 103&#039; Con la presencia de Mickael Delahaie (director de fotograf\u00eda) y Eug\u00e9nie Gressier (directora de producci\u00f3n)\" data-event-id=\"79\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 200px; top: 1250px\" data-top=\"1250\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ff7675; \" data-event-background-image-url=\"\" data-event-id=\"79\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">ALICE 103&#039; Con la presencia de Mickael Delahaie (director de fotograf\u00eda) y Eug\u00e9nie Gressier (directora de producci\u00f3n)<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"79\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1550px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/cut-and-paste\/\" data-onclick=\"link\" data-color=\"#d63031\" title=\"CUT AND PASTE 105&#039;\" data-event-id=\"450\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 800px;\" data-top=\"800\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/cut-and-paste\/\"  data-onclick=\"link\" data-color=\"#d63031\" title=\"CUT AND PASTE 105&#039;\" data-event-id=\"450\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 800px\" data-top=\"800\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #d63031; \" data-event-background-image-url=\"\" data-event-id=\"450\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">CUT AND PASTE 105&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"450\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/bebo-wa-bashir\/\" data-onclick=\"link\" data-color=\"#d63031\" title=\"BEBO WA BASHIR 115&#039;\" data-event-id=\"451\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 200px; left: 1000px;\" data-top=\"1000\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/bebo-wa-bashir\/\"  data-onclick=\"link\" data-color=\"#d63031\" title=\"BEBO WA BASHIR 115&#039;\" data-event-id=\"451\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 200px; top: 1000px\" data-top=\"1000\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #d63031; \" data-event-background-image-url=\"\" data-event-id=\"451\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">BEBO WA BASHIR 115&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"451\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/chaos-disorder\/\" data-onclick=\"link\" data-color=\"#d63031\" title=\"CHAOS, DISORDER 77&#039;\" data-event-id=\"76\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 125px; left: 1250px;\" data-top=\"1250\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/chaos-disorder\/\"  data-onclick=\"link\" data-color=\"#d63031\" title=\"CHAOS, DISORDER 77&#039;\" data-event-id=\"76\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 125px; top: 1250px\" data-top=\"1250\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #d63031; \" data-event-background-image-url=\"\" data-event-id=\"76\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">CHAOS, DISORDER 77&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"76\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1550px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/galileo\/\" data-onclick=\"link\" data-color=\"#fa983a\" title=\"GALILEO 105&#039;\" data-event-id=\"453\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 800px;\" data-top=\"800\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/galileo\/\"  data-onclick=\"link\" data-color=\"#fa983a\" title=\"GALILEO 105&#039;\" data-event-id=\"453\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 800px\" data-top=\"800\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fa983a; \" data-event-background-image-url=\"\" data-event-id=\"453\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">GALILEO 105&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"453\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/mas-alla-del-bien-y-del-mal\/\" data-onclick=\"link\" data-color=\"#fa983a\" title=\"M\u00c1S ALL\u00c1 DEL BIEN Y DEL MAL 122&#039;\" data-event-id=\"454\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 200px; left: 1000px;\" data-top=\"1000\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/mas-alla-del-bien-y-del-mal\/\"  data-onclick=\"link\" data-color=\"#fa983a\" title=\"M\u00c1S ALL\u00c1 DEL BIEN Y DEL MAL 122&#039;\" data-event-id=\"454\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 200px; top: 1000px\" data-top=\"1000\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fa983a; \" data-event-background-image-url=\"\" data-event-id=\"454\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">M\u00c1S ALL\u00c1 DEL BIEN Y DEL MAL 122&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"454\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/milarepa\/\" data-onclick=\"link\" data-color=\"#fa983a\" title=\"MILAREPA 108&#039;\" data-event-id=\"452\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 1250px;\" data-top=\"1250\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/milarepa\/\"  data-onclick=\"link\" data-color=\"#fa983a\" title=\"MILAREPA 108&#039;\" data-event-id=\"452\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 1250px\" data-top=\"1250\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fa983a; \" data-event-background-image-url=\"\" data-event-id=\"452\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">MILAREPA 108&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"452\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1550px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/guy-debord-del-texto-a-la-imagen\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#833471\" title=\"UNIVERSITAT DE VAL\u00c8NCIA: SEMINARIO &quot;GUY DEBORD, CINEASTA&quot;\" data-event-id=\"90\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 350px; left: 0px;\" data-top=\"0\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/guy-debord-del-texto-a-la-imagen\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#833471\" title=\"UNIVERSITAT DE VAL\u00c8NCIA: SEMINARIO &quot;GUY DEBORD, CINEASTA&quot;\" data-event-id=\"90\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 350px; top: 0px\" data-top=\"0\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #833471; \" data-event-background-image-url=\"\" data-event-id=\"90\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">UNIVERSITAT DE VAL\u00c8NCIA: SEMINARIO &quot;GUY DEBORD, CINEASTA&quot;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"Sal\u00f3n de Grados de la Facultad de Filolog\u00eda, Traducci\u00f3n i Comunicaci\u00f3n\">Sal\u00f3n de Grados de la Facultad de Filolog\u00eda, Traducci\u00f3n i Comunicaci\u00f3n<\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"90\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n<\/div><div class=\" sched-list sched-hidden\" id=\"sched-schedule-5-933497302-list\" data-id-schedule=\"sched-schedule-5-933497302\" data-options=\" {&quot;am_pm&quot;:&quot;0&quot;,&quot;sidebar_width&quot;:&quot;90&quot;,&quot;sidebar_position&quot;:&quot;left&quot;,&quot;event_hover_color&quot;:&quot;lighten&quot;,&quot;event_box_text_align&quot;:&quot;center&quot;,&quot;event_box_time&quot;:&quot;0&quot;,&quot;event_hover_text_color&quot;:&quot;#FFFFFF&quot;,&quot;event_hover_background_color&quot;:&quot;#000000&quot;,&quot;event_box_truncate_title&quot;:&quot;0&quot;,&quot;event_tooltip&quot;:&quot;0&quot;,&quot;event_tooltip_title&quot;:&quot;1&quot;,&quot;event_tooltip_time&quot;:&quot;1&quot;,&quot;event_tooltip_description&quot;:&quot;1&quot;,&quot;event_tooltip_width_type&quot;:&quot;event&quot;,&quot;event_tooltip_width&quot;:&quot;150&quot;,&quot;event_tooltip_color_type&quot;:&quot;event&quot;,&quot;event_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;event_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;column_tooltip&quot;:&quot;0&quot;,&quot;column_tooltip_title&quot;:&quot;1&quot;,&quot;column_tooltip_description&quot;:&quot;1&quot;,&quot;column_tooltip_width_type&quot;:&quot;column&quot;,&quot;column_tooltip_width&quot;:&quot;150&quot;,&quot;column_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;column_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;animations&quot;:&quot;1&quot;,&quot;animations_mobile&quot;:&quot;1&quot;,&quot;animations_speed&quot;:&quot;normal&quot;,&quot;animations_css3&quot;:&quot;1&quot;,&quot;tooltips_mobile&quot;:&quot;1&quot;,&quot;editor_bg&quot;:&quot;#F5F5F5&quot;,&quot;animations_editor&quot;:&quot;1&quot;,&quot;popup_max_width&quot;:&quot;560&quot;,&quot;popup_background_color&quot;:&quot;#ffffff&quot;,&quot;popup_text_color&quot;:&quot;#535353&quot;,&quot;popup_link_color&quot;:&quot;#ff4d00&quot;,&quot;autoplay_videos&quot;:&quot;1&quot;,&quot;column_color_bg&quot;:&quot;#e8e8e8&quot;,&quot;column_color_text&quot;:&quot;#3f3f3f&quot;,&quot;column_color_border&quot;:&quot;#ffffff&quot;,&quot;pattern_color_1&quot;:&quot;#ffffff&quot;,&quot;pattern_color_2&quot;:&quot;#e8e8e8&quot;,&quot;pattern_color_3&quot;:&quot;#ffffff&quot;,&quot;title_text_color&quot;:&quot;#3f3f3f&quot;,&quot;sidebar_text_color&quot;:&quot;#3f3f3f&quot;,&quot;event_box_text_color&quot;:&quot;#ffffff&quot;,&quot;title_attr&quot;:&quot;0&quot;,&quot;column_break&quot;:1,&quot;column_break_width&quot;:&quot;120&quot;,&quot;column_break_hide_sidebar&quot;:&quot;0&quot;,&quot;editor_custom_css&quot;:&quot;1&quot;,&quot;column_title&quot;:&quot;1&quot;,&quot;event_box_description_method&quot;:&quot;short&quot;,&quot;editor_quick_tooltips&quot;:&quot;1&quot;,&quot;editor_timepicker_increments&quot;:&quot;15&quot;,&quot;event_box_style&quot;:&quot;1&quot;,&quot;filter_position&quot;:&quot;right&quot;,&quot;filter_multiple&quot;:&quot;1&quot;,&quot;filter_hidden_events&quot;:&quot;hide&quot;,&quot;filter_hidden_events_opacity&quot;:&quot;30&quot;,&quot;filter_dropdown_width&quot;:&quot;100&quot;,&quot;filter_dropdown_hover_width&quot;:&quot;180&quot;,&quot;filter_dropdown_label&quot;:&quot;Secci\\u00f3n&quot;,&quot;filter_dropdown_show_all_label&quot;:&quot;Mostrar todo&quot;,&quot;hashtag_url&quot;:&quot;1&quot;,&quot;hide_popup_for_empty_events&quot;:&quot;1&quot;,&quot;event_box_padding_break&quot;:&quot;200&quot;,&quot;popup_arrows&quot;:&quot;1&quot;,&quot;filter_visible&quot;:&quot;1&quot;,&quot;column_break_action&quot;:&quot;list&quot;,&quot;list_view_column_title_color&quot;:&quot;#3f3f3f&quot;,&quot;list_view_event_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_hover_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_title_bold&quot;:&quot;1&quot;,&quot;list_view_event_bullets&quot;:&quot;2&quot;,&quot;list_view_event_short_description_method&quot;:&quot;short&quot;,&quot;list_view_event_description_color&quot;:&quot;#ffffff&quot;,&quot;list_view_hide_empty_columns&quot;:&quot;1&quot;,&quot;shortcodes_in_descriptions&quot;:&quot;1&quot;,&quot;columns_sticky_header&quot;:&quot;1&quot;,&quot;columns_sticky_header_offset&quot;:&quot;0&quot;,&quot;h_row_height&quot;:&quot;110&quot;,&quot;h_column_width&quot;:&quot;200&quot;,&quot;h_time_indicator&quot;:&quot;1&quot;,&quot;h_time_indicator_height&quot;:30,&quot;h_column_multiline&quot;:&quot;0&quot;,&quot;h_column_title_position&quot;:&quot;middle&quot;,&quot;h_column_title_align&quot;:&quot;center&quot;,&quot;h_break&quot;:&quot;0&quot;,&quot;h_width_break_point&quot;:&quot;200&quot;,&quot;h_bg_color&quot;:&quot;#f8f8f8&quot;,&quot;pdf_type&quot;:&quot;html&quot;,&quot;pdf_enable&quot;:&quot;0&quot;,&quot;pdf_enable_list&quot;:&quot;0&quot;,&quot;pdf_label&quot;:&quot;Download&quot;,&quot;pdf_css&quot;:&quot;&quot;,&quot;upcoming_type&quot;:&quot;current_datetime&quot;,&quot;upcoming_custom&quot;:&quot;2016-01-01 00:00&quot;,&quot;upcoming_limit&quot;:&quot;5&quot;,&quot;upcoming_title&quot;:&quot;timetable_title&quot;,&quot;upcoming_title_custom&quot;:&quot;Upcoming Events&quot;,&quot;upcoming_title_amount&quot;:&quot;1&quot;}\" data-start=\"10:00\" data-end=\"01:30\" data-timetable-id=\"5\" data-type=\"list\" data-layout=\"horizontal\">\t<div class=\"sched-list-top\">\n\t\t<div class=\"sched-list-title\">Lunes 28 de octubre<\/div>\n\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 1<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/the-announcement\/\" data-event-id=\"72\" target=\"_blank\" style=\"background: #ff7675;\" data-color=\"#ff7675\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ff7675;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tTHE ANNOUNCEMENT 94&#039; Con la presencia del actor \u015eencan G\u00fclery\u00fcz\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">11:30 - 13:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-alcalde-el-guardia-y-la-jirafita\/\" data-event-id=\"440\" target=\"_blank\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tEL ALCALDE, EL GUARDIA Y LA JIRAFITA 100&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 17:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/magnifica-presenza\/\" data-event-id=\"441\" target=\"_blank\" style=\"background: #27ae60;\" data-color=\"#27ae60\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #27ae60;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tMAGNIFICA PRESENZA 105&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/celos-a-la-italiana\/\" data-event-id=\"73\" target=\"_blank\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tCELOS A LA ITALIANA 124&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 22:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/no-basta-una-vida\/\" data-event-id=\"74\" target=\"_blank\" style=\"background: #27ae60;\" data-color=\"#27ae60\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #27ae60;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tNO BASTA UNA VIDA 110&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 2<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/poveri-ma-belli\/\" data-event-id=\"442\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tPOVERI MA BELLI 101&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 17:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/guapas-pero-pobres\/\" data-event-id=\"443\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tGUAPAS, PERO POBRES 99&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/pobre-y-millonario\/\" data-event-id=\"444\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tPOBRE Y MILLONARIO 95&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 21:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-ultimo-haren\/\" data-event-id=\"77\" style=\"background: #27ae60;\" data-color=\"#27ae60\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #27ae60;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tEL \u00daLTIMO HAR\u00c9N 115&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 3<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/head-above-water\/\" data-event-id=\"445\" style=\"background: #fcc312;\" data-color=\"#fcc312\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fcc312;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tHEAD ABOVE WATER 85&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 17:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/freedom-fields\/\" data-event-id=\"446\" style=\"background: #ffc312;\" data-color=\"#ffc312\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ffc312;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tFREEDOM FIELDS 97&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-inocencia\/\" data-event-id=\"447\" style=\"background: #fcc312;\" data-color=\"#fcc312\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fcc312;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tLA INOCENCIA 93&#039; Con la presencia de la directora Lucia Alemany, la actriz Carmen Arrufat y el equipo de la pel\u00edcula\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 21:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/una-dona-amb-unes-ales-tremendes\/\" data-event-id=\"78\" style=\"background: #ffc312;\" data-color=\"#ffc312\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ffc312;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tUNA DONA AMB UNES ALES TREMENDES 85&#039; Con la presencia del director, Pedro Rosado, y el equipo de la pel\u00edcula\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 4<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/a-herdade\/\" data-event-id=\"448\" style=\"background: #ff7675;\" data-color=\"#ff7675\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ff7675;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tA HERDADE 166&#039; Con la presencia del director Tiago Guedes\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 18:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/tu-merites-un-amour\/\" data-event-id=\"449\" style=\"background: #ff7675;\" data-color=\"#ff7675\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ff7675;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tTU M\u00c9RITES UN AMOUR 102&#039; Con la presencia de la directora, Hafsia Herzi\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 21:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/alice\/\" data-event-id=\"79\" style=\"background: #ff7675;\" data-color=\"#ff7675\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ff7675;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tALICE 103&#039; Con la presencia de Mickael Delahaie (director de fotograf\u00eda) y Eug\u00e9nie Gressier (directora de producci\u00f3n)\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 5<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/cut-and-paste\/\" data-event-id=\"450\" style=\"background: #d63031;\" data-color=\"#d63031\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #d63031;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tCUT AND PASTE 105&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/bebo-wa-bashir\/\" data-event-id=\"451\" style=\"background: #d63031;\" data-color=\"#d63031\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #d63031;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tBEBO WA BASHIR 115&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 22:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/chaos-disorder\/\" data-event-id=\"76\" style=\"background: #d63031;\" data-color=\"#d63031\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #d63031;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tCHAOS, DISORDER 77&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 23:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">FILMOTECA<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/galileo\/\" data-event-id=\"453\" style=\"background: #fa983a;\" data-color=\"#fa983a\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fa983a;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tGALILEO 105&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/mas-alla-del-bien-y-del-mal\/\" data-event-id=\"454\" style=\"background: #fa983a;\" data-color=\"#fa983a\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fa983a;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tM\u00c1S ALL\u00c1 DEL BIEN Y DEL MAL 122&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 22:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/milarepa\/\" data-event-id=\"452\" style=\"background: #fa983a;\" data-color=\"#fa983a\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fa983a;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tMILAREPA 108&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">OTROS ESPACIOS<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/guy-debord-del-texto-a-la-imagen\/\" data-event-id=\"90\" target=\"_blank\" style=\"background: #833471;\" data-color=\"#833471\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #833471;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tUNIVERSITAT DE VAL\u00c8NCIA: SEMINARIO &quot;GUY DEBORD, CINEASTA&quot;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\tSal\u00f3n de Grados de la Facultad de Filolog\u00eda, Traducci\u00f3n i Comunicaci\u00f3n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">10:00 - 13:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t<!-- .sched-list-column -->\n\t\n<\/div>[\/vc_column][\/vc_row][vc_row disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1600188397137{padding-right: 40px !important;padding-bottom: 50px !important;padding-left: 40px !important;}&#8221; anchor=&#8221;martes-29&#8243;][vc_column]<div class=\"sched-loader\"><div class=\"sched-loader-icon\"><\/div><div class=\"sched-loader-text\"><\/div><\/div>\n<div class=\" sched sched-horizontal sched-horizontal-medium\" id=\"sched-schedule-6-24027596\" data-options=\" {&quot;am_pm&quot;:&quot;0&quot;,&quot;sidebar_width&quot;:&quot;90&quot;,&quot;sidebar_position&quot;:&quot;left&quot;,&quot;event_hover_color&quot;:&quot;lighten&quot;,&quot;event_box_text_align&quot;:&quot;center&quot;,&quot;event_box_time&quot;:&quot;0&quot;,&quot;event_hover_text_color&quot;:&quot;#FFFFFF&quot;,&quot;event_hover_background_color&quot;:&quot;#000000&quot;,&quot;event_box_truncate_title&quot;:&quot;0&quot;,&quot;event_tooltip&quot;:&quot;0&quot;,&quot;event_tooltip_title&quot;:&quot;1&quot;,&quot;event_tooltip_time&quot;:&quot;1&quot;,&quot;event_tooltip_description&quot;:&quot;1&quot;,&quot;event_tooltip_width_type&quot;:&quot;event&quot;,&quot;event_tooltip_width&quot;:&quot;150&quot;,&quot;event_tooltip_color_type&quot;:&quot;event&quot;,&quot;event_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;event_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;column_tooltip&quot;:&quot;0&quot;,&quot;column_tooltip_title&quot;:&quot;1&quot;,&quot;column_tooltip_description&quot;:&quot;1&quot;,&quot;column_tooltip_width_type&quot;:&quot;column&quot;,&quot;column_tooltip_width&quot;:&quot;150&quot;,&quot;column_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;column_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;animations&quot;:&quot;1&quot;,&quot;animations_mobile&quot;:&quot;1&quot;,&quot;animations_speed&quot;:&quot;normal&quot;,&quot;animations_css3&quot;:&quot;1&quot;,&quot;tooltips_mobile&quot;:&quot;1&quot;,&quot;editor_bg&quot;:&quot;#F5F5F5&quot;,&quot;animations_editor&quot;:&quot;1&quot;,&quot;popup_max_width&quot;:&quot;560&quot;,&quot;popup_background_color&quot;:&quot;#ffffff&quot;,&quot;popup_text_color&quot;:&quot;#535353&quot;,&quot;popup_link_color&quot;:&quot;#ff4d00&quot;,&quot;autoplay_videos&quot;:&quot;1&quot;,&quot;column_color_bg&quot;:&quot;#e8e8e8&quot;,&quot;column_color_text&quot;:&quot;#3f3f3f&quot;,&quot;column_color_border&quot;:&quot;#ffffff&quot;,&quot;pattern_color_1&quot;:&quot;#ffffff&quot;,&quot;pattern_color_2&quot;:&quot;#e8e8e8&quot;,&quot;pattern_color_3&quot;:&quot;#ffffff&quot;,&quot;title_text_color&quot;:&quot;#3f3f3f&quot;,&quot;sidebar_text_color&quot;:&quot;#3f3f3f&quot;,&quot;event_box_text_color&quot;:&quot;#ffffff&quot;,&quot;title_attr&quot;:&quot;0&quot;,&quot;column_break&quot;:1,&quot;column_break_width&quot;:&quot;120&quot;,&quot;column_break_hide_sidebar&quot;:&quot;0&quot;,&quot;editor_custom_css&quot;:&quot;1&quot;,&quot;column_title&quot;:&quot;1&quot;,&quot;event_box_description_method&quot;:&quot;short&quot;,&quot;editor_quick_tooltips&quot;:&quot;1&quot;,&quot;editor_timepicker_increments&quot;:&quot;15&quot;,&quot;event_box_style&quot;:&quot;1&quot;,&quot;filter_position&quot;:&quot;right&quot;,&quot;filter_multiple&quot;:&quot;1&quot;,&quot;filter_hidden_events&quot;:&quot;hide&quot;,&quot;filter_hidden_events_opacity&quot;:&quot;30&quot;,&quot;filter_dropdown_width&quot;:&quot;100&quot;,&quot;filter_dropdown_hover_width&quot;:&quot;180&quot;,&quot;filter_dropdown_label&quot;:&quot;Secci\\u00f3n&quot;,&quot;filter_dropdown_show_all_label&quot;:&quot;Mostrar todo&quot;,&quot;hashtag_url&quot;:&quot;1&quot;,&quot;hide_popup_for_empty_events&quot;:&quot;1&quot;,&quot;event_box_padding_break&quot;:&quot;200&quot;,&quot;popup_arrows&quot;:&quot;1&quot;,&quot;filter_visible&quot;:&quot;1&quot;,&quot;column_break_action&quot;:&quot;list&quot;,&quot;list_view_column_title_color&quot;:&quot;#3f3f3f&quot;,&quot;list_view_event_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_hover_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_title_bold&quot;:&quot;1&quot;,&quot;list_view_event_bullets&quot;:&quot;2&quot;,&quot;list_view_event_short_description_method&quot;:&quot;short&quot;,&quot;list_view_event_description_color&quot;:&quot;#ffffff&quot;,&quot;list_view_hide_empty_columns&quot;:&quot;1&quot;,&quot;shortcodes_in_descriptions&quot;:&quot;1&quot;,&quot;columns_sticky_header&quot;:&quot;1&quot;,&quot;columns_sticky_header_offset&quot;:&quot;0&quot;,&quot;h_row_height&quot;:&quot;110&quot;,&quot;h_column_width&quot;:&quot;200&quot;,&quot;h_time_indicator&quot;:&quot;1&quot;,&quot;h_time_indicator_height&quot;:30,&quot;h_column_multiline&quot;:&quot;0&quot;,&quot;h_column_title_position&quot;:&quot;middle&quot;,&quot;h_column_title_align&quot;:&quot;center&quot;,&quot;h_break&quot;:&quot;0&quot;,&quot;h_width_break_point&quot;:&quot;200&quot;,&quot;h_bg_color&quot;:&quot;#f8f8f8&quot;,&quot;pdf_type&quot;:&quot;html&quot;,&quot;pdf_enable&quot;:&quot;0&quot;,&quot;pdf_enable_list&quot;:&quot;0&quot;,&quot;pdf_label&quot;:&quot;Download&quot;,&quot;pdf_css&quot;:&quot;&quot;,&quot;upcoming_type&quot;:&quot;current_datetime&quot;,&quot;upcoming_custom&quot;:&quot;2016-01-01 00:00&quot;,&quot;upcoming_limit&quot;:&quot;5&quot;,&quot;upcoming_title&quot;:&quot;timetable_title&quot;,&quot;upcoming_title_custom&quot;:&quot;Upcoming Events&quot;,&quot;upcoming_title_amount&quot;:&quot;1&quot;}\" data-start=\"10:00\" data-end=\"01:30\" data-timetable-id=\"6\" data-type=\"full\" data-list-id=\"#sched-schedule-6-24027596-list\" data-layout=\"horizontal\">\t<div class=\"sched-style\"><style type=\"text\/css\">\/*\n * Custom CSS For Timetable\n*\/\n\n#sched-schedule-6-24027596 .sched-column-header,\n#sched-schedule-6-24027596 .sched-column-header-sticky {\n\tbackground: #e8e8e8;\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-6-24027596 .sched-column-header:after,\n#sched-schedule-6-24027596 .sched-column-header-sticky:after {\n\tbackground: #ffffff;\n}\n\n#sched-schedule-6-24027596 .sched-columns .sched-column:last-child .sched-column-header:after,\n#sched-schedule-6-24027596 .sched-columns .sched-column:last-child .sched-column-header-sticky:after {\n\tbackground: #e8e8e8;\n}\n\n#sched-schedule-6-24027596 .sched-column-bg-block {\n\tbackground: #ffffff;\n\tborder-color: #e8e8e8;\n}\n\n#sched-schedule-6-24027596 .sched-column-bg-block:after {\n\tbackground: #ffffff;\n}\n\n#sched-schedule-6-24027596 .sched-row-no-title .sched-column .sched-column-bg {\n\tbox-shadow: 0 -1px 0 #e8e8e8;\n}\n\n#sched-schedule-6-24027596 .sched-title {\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-6-24027596 .sched-time-value {\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-6-24027596 .sched-event .sched-event-inner {\n\tcolor: #ffffff;\n\ttext-align: center;\n}\n\n#sched-schedule-6-24027596 .sched-event.sched-event-invert .sched-event-inner {\n\t<!-- background: #999; -->\n}\n\n\n\n\/*#sched-schedule-6-24027596 a.sched-event.sched-event-sort-hidden {\n\topacity: 0;\n}*\/\n\n#sched-schedule-6-24027596 .sched-sort .sched-sort-current .sched-sort-current-label {\n\twidth: 100px;\n}\n\n#sched-schedule-6-24027596 .sched-sort.sched-sort-open .sched-sort-dropdown .sched-sort-current .sched-sort-current-label {\n\twidth: 180px;\n}\n\n\/*\n * Custom CSS Event Popup\n *\/\n\n#sched-schedule-6-24027596-popup .sched-popup-description {\n\t\n}\n\n#sched-schedule-6-24027596-popup .sched-popup-description .sched-meta a,\n#sched-schedule-6-24027596-popup .sched-popup-description .sched-popup-description-text a {\n\tcolor: #ff4d00;\n}\n\n#sched-schedule-6-24027596-popup .sched-popup-description .sched-meta,\n#sched-schedule-6-24027596-popup .sched-popup-description .sched-popup-description-text {\n\tcolor: #535353;\n\tbackground: #ffffff;\n}\n\n\/*\n * List\n *\/\n\n#sched-schedule-6-24027596-list .sched-list-title {\n\tcolor: #3f3f3f;\n}\n\n\n\n#sched-schedule-6-24027596-list .sched-list-column-title {\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-6-24027596-list .sched-list-event {\n\tcolor: #ffffff;\n\t\n\t\n}\n\n#sched-schedule-6-24027596-list .sched-list-event:hover {\n\tcolor: #ffffff;\n}\n\n#sched-schedule-6-24027596-list .sched-list-event-description {\n\tcolor: #ffffff;\n}\n\n#sched-schedule-6-24027596-list .sched-list-event-title {\n\t\tfont-weight: bold;\n\t;\n}\n\n\/*\n * Horizontal\n *\/\n\n\n\n#sched-schedule-6-24027596 .sched-h-columns {\n\tmargin-top: 30px;\n}\n\n#sched-schedule-6-24027596 .sched-h-content-columns {\n\t\/*margin-top: 30px;*\/\n}\n\n\n#sched-schedule-6-24027596 .sched-h-columns {\n\twidth: 200px;\n}\n\n#sched-schedule-6-24027596 .sched-h-content {\n\tmargin-left: 200px;\n}\n\n#sched-schedule-6-24027596 .sched-h-column-title {\n\ttext-align: center;\n}\n\n#sched-schedule-6-24027596 .sched-h-column {\n\tbackground: #e8e8e8;\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-6-24027596 .sched-h-row {\n\tbackground-color: #f8f8f8;\n}\n<\/style><\/div>\n\t<div class=\"sched-top\">\n\t\t\t<h2 class=\"sched-title\">Martes 29 de octubre<\/h2>\n\t\t<div class=\"sched-top-buttons sched-top-buttons-right\">\n\t\t\t\n\t\t\t<\/div><!-- .sched-top-buttons -->\n<\/div><!-- .sched-top -->\t<div class=\"sched-row\">\n\t\t\t\t\t<!-- <div class=\"sched-sidebar\" style=\"width: 90px;\">\n\t\t\t\t<div class=\"sched-time\">\n\t\t\t\t\t<div class=\"sched-time-value\" style=\"padding-bottom: 36px\">10:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">11:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">12:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">13:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">14:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">15:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">16:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">17:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">18:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">19:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">20:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">21:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">22:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">23:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">00:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">01:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">02:00<\/div>\t\t\t\t<\/div>\n\t\t\t<\/div> -->\n\t\t\t\t\t\t<div class=\"sched-h-columns\">\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 1\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 2\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 3\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 4\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 5\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tFILMOTECA\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tSGAE\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"sched-h-content\">\n\t\t\t<div class=\"sched-h-content-scroll\">\n\t\t\t\t\t\t\t\t<div class=\"sched-h-content-scroll-time\">\n\t\t\t\t\t<div class=\"sched-h-content-scroll-time-value\" data-i=\"0\" style=\"left: 0px;\">10:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"1\" style=\"left: 100px;\">11:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"2\" style=\"left: 200px;\">12:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"3\" style=\"left: 300px;\">13:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"4\" style=\"left: 400px;\">14:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"5\" style=\"left: 500px;\">15:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"6\" style=\"left: 600px;\">16:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"7\" style=\"left: 700px;\">17:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"8\" style=\"left: 800px;\">18:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"9\" style=\"left: 900px;\">19:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"10\" style=\"left: 1000px;\">20:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"11\" style=\"left: 1100px;\">21:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"12\" style=\"left: 1200px;\">22:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"13\" style=\"left: 1300px;\">23:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"14\" style=\"left: 1400px;\">00:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"15\" style=\"left: 1500px;\">01:00<\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"sched-h-content-columns\">\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1550px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/flesh-out\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"FLESH OUT 94&#039; Con la presencia de la directora Michela Occhipinti\" data-event-id=\"468\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 150px;\" data-top=\"150\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\" https:\/\/lamostradevalencia.com\/peliculas\/flesh-out\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"FLESH OUT 94&#039; Con la presencia de la directora Michela Occhipinti\" data-event-id=\"468\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 150px\" data-top=\"150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ff7675; \" data-event-background-image-url=\"\" data-event-id=\"468\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">FLESH OUT 94&#039; Con la presencia de la directora Michela Occhipinti<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"468\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/no-basta-una-vida\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"NO BASTA UNA VIDA 110&#039;\" data-event-id=\"462\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 600px;\" data-top=\"600\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/no-basta-una-vida\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"NO BASTA UNA VIDA 110&#039;\" data-event-id=\"462\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 600px\" data-top=\"600\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #27ae60; \" data-event-background-image-url=\"\" data-event-id=\"462\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">NO BASTA UNA VIDA 110&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"462\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/allacciate-le-cinture\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"ALLACCIATE LE CINTURE 110&#039;\" data-event-id=\"92\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 800px;\" data-top=\"800\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/allacciate-le-cinture\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"ALLACCIATE LE CINTURE 110&#039;\" data-event-id=\"92\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 800px\" data-top=\"800\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #27ae60; \" data-event-background-image-url=\"\" data-event-id=\"92\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">ALLACCIATE LE CINTURE 110&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"92\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-alcalde-el-guardia-y-la-jirafita\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#128997\" title=\"EL ALCALDE, EL GUARDIA Y LA JIRAFITA 100&#039;\" data-event-id=\"457\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 1000px;\" data-top=\"1000\" data-size=\"1\" data-sort-index=\"3\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-alcalde-el-guardia-y-la-jirafita\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#128997\" title=\"EL ALCALDE, EL GUARDIA Y LA JIRAFITA 100&#039;\" data-event-id=\"457\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 1000px\" data-top=\"1000\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"457\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">EL ALCALDE, EL GUARDIA Y LA JIRAFITA 100&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"457\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/celos-a-la-italiana\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#128997\" title=\"CELOS A LA ITALIANA 124&#039;\" data-event-id=\"459\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 200px; left: 1250px;\" data-top=\"1250\" data-size=\"1\" data-sort-index=\"4\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/celos-a-la-italiana\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#128997\" title=\"CELOS A LA ITALIANA 124&#039;\" data-event-id=\"459\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 200px; top: 1250px\" data-top=\"1250\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"459\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">CELOS A LA ITALIANA 124&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"459\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1550px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/guapas-pero-pobres\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#128997\" title=\"GUAPAS, PERO POBRES 99&#039;\" data-event-id=\"460\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 600px;\" data-top=\"600\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/guapas-pero-pobres\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#128997\" title=\"GUAPAS, PERO POBRES 99&#039;\" data-event-id=\"460\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 600px\" data-top=\"600\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"460\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">GUAPAS, PERO POBRES 99&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"460\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/pobre-y-millonario\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#128997\" title=\"POBRE Y MILLONARIO 95&#039;\" data-event-id=\"461\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 800px;\" data-top=\"800\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/pobre-y-millonario\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#128997\" title=\"POBRE Y MILLONARIO 95&#039;\" data-event-id=\"461\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 800px\" data-top=\"800\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"461\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">POBRE Y MILLONARIO 95&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"461\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-ultimo-haren\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"EL \u00daLTIMO HAR\u00c9N 115&#039;\" data-event-id=\"456\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 200px; left: 1000px;\" data-top=\"1000\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-ultimo-haren\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"EL \u00daLTIMO HAR\u00c9N 115&#039;\" data-event-id=\"456\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 200px; top: 1000px\" data-top=\"1000\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #27ae60; \" data-event-background-image-url=\"\" data-event-id=\"456\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">EL \u00daLTIMO HAR\u00c9N 115&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"456\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/rufufu\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#128997\" title=\"RUFUF\u00da 106&#039;\" data-event-id=\"99\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 1250px;\" data-top=\"1250\" data-size=\"1\" data-sort-index=\"3\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/rufufu\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#128997\" title=\"RUFUF\u00da 106&#039;\" data-event-id=\"99\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 1250px\" data-top=\"1250\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"99\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">RUFUF\u00da 106&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"99\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1550px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/freedom-fields\/\" data-onclick=\"link\" data-color=\"#ffc312\" title=\"FREEDOM FIELDS 97&#039;\" data-event-id=\"464\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 600px;\" data-top=\"600\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/freedom-fields\/\"  data-onclick=\"link\" data-color=\"#ffc312\" title=\"FREEDOM FIELDS 97&#039;\" data-event-id=\"464\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 600px\" data-top=\"600\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ffc312; \" data-event-background-image-url=\"\" data-event-id=\"464\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">FREEDOM FIELDS 97&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"464\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/mafak\/\" data-onclick=\"link\" data-color=\"#ffc312\" title=\"MAFAK 108&#039;\" data-event-id=\"465\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 800px;\" data-top=\"800\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/mafak\/\"  data-onclick=\"link\" data-color=\"#ffc312\" title=\"MAFAK 108&#039;\" data-event-id=\"465\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 800px\" data-top=\"800\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ffc312; \" data-event-background-image-url=\"\" data-event-id=\"465\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">MAFAK 108&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"465\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/jalas\/\" data-onclick=\"link\" data-color=\"#0694d6\" title=\"JALAS 30&#039; Con la presencia de la directora, Olga Arias, y el equipo de la pel\u00edcula\" data-event-id=\"466\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 1000px;\" data-top=\"1000\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/jalas\/\"  data-onclick=\"link\" data-color=\"#0694d6\" title=\"JALAS 30&#039; Con la presencia de la directora, Olga Arias, y el equipo de la pel\u00edcula\" data-event-id=\"466\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 1000px\" data-top=\"1000\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #0694d6; \" data-event-background-image-url=\"\" data-event-id=\"466\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">JALAS 30&#039; Con la presencia de la directora, Olga Arias, y el equipo de la pel\u00edcula<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"466\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/zero-impunity\/\" data-onclick=\"link\" data-color=\"#ffc312\" title=\"ZERO IMPUNITY 95&#039; Con la presencia del productor Fran\u00e7ois Le Gall\" data-event-id=\"463\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 1250px;\" data-top=\"1250\" data-size=\"1\" data-sort-index=\"3\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/zero-impunity\/\"  data-onclick=\"link\" data-color=\"#ffc312\" title=\"ZERO IMPUNITY 95&#039; Con la presencia del productor Fran\u00e7ois Le Gall\" data-event-id=\"463\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 1250px\" data-top=\"1250\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ffc312; \" data-event-background-image-url=\"\" data-event-id=\"463\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">ZERO IMPUNITY 95&#039; Con la presencia del productor Fran\u00e7ois Le Gall<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"463\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1550px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/a-shelter-among-the-clouds\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"A SHELTER AMONG THE CLOUDS 85&#039; Con la presencia del director, Robert Budina y del actor Arben Bajraktaraj\" data-event-id=\"469\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 600px;\" data-top=\"600\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\" https:\/\/lamostradevalencia.com\/peliculas\/a-shelter-among-the-clouds\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"A SHELTER AMONG THE CLOUDS 85&#039; Con la presencia del director, Robert Budina y del actor Arben Bajraktaraj\" data-event-id=\"469\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 600px\" data-top=\"600\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ff7675; \" data-event-background-image-url=\"\" data-event-id=\"469\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">A SHELTER AMONG THE CLOUDS 85&#039; Con la presencia del director, Robert Budina y del actor Arben Bajraktaraj<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"469\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/a-herdade\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"A HERDADE 166&#039; Con la presencia del director, Tiago Guedes\" data-event-id=\"470\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 275px; left: 800px;\" data-top=\"800\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\" https:\/\/lamostradevalencia.com\/peliculas\/a-herdade\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"A HERDADE 166&#039; Con la presencia del director, Tiago Guedes\" data-event-id=\"470\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 275px; top: 800px\" data-top=\"800\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ff7675; \" data-event-background-image-url=\"\" data-event-id=\"470\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">A HERDADE 166&#039; Con la presencia del director, Tiago Guedes<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"470\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/the-announcement\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"THE ANNOUNCEMENT 94&#039; Con la presencia del actor \u015eencan G\u00fclery\u00fcz\" data-event-id=\"103\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 1250px;\" data-top=\"1250\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\" https:\/\/lamostradevalencia.com\/peliculas\/the-announcement\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"THE ANNOUNCEMENT 94&#039; Con la presencia del actor \u015eencan G\u00fclery\u00fcz\" data-event-id=\"103\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 1250px\" data-top=\"1250\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ff7675; \" data-event-background-image-url=\"\" data-event-id=\"103\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">THE ANNOUNCEMENT 94&#039; Con la presencia del actor \u015eencan G\u00fclery\u00fcz<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"103\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1550px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"#\" data-onclick=\"popup\" data-color=\"#9980fa\" title=\"PROGRAMA CORTOS GUY DEBORD 68&#039;\" data-event-id=\"471\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 125px; left: 600px;\" data-top=\"600\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"#\"  data-onclick=\"popup\" data-color=\"#9980fa\" title=\"PROGRAMA CORTOS GUY DEBORD 68&#039;\" data-event-id=\"471\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 125px; top: 600px\" data-top=\"600\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #9980fa; \" data-event-background-image-url=\"\" data-event-id=\"471\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">PROGRAMA CORTOS GUY DEBORD 68&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"471\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text\">\n\t\t\r\n\r\nIncluye los siguientes cortometrajes:\r\n<ul>\r\n \t<li><strong>CRITIQUE DE LA S\u00c9PARATION<\/strong> FRANCIA, DINAMARCA. 1961. B\/N. 18\u2019. VOSE<\/li>\r\n \t<li><strong>SUR LE PASSAGE DE QUELQUES PERSONNES \u00c0 TRAVERS UNES ASSEZ COURTE UNIT\u00c9 DE TEMPS<\/strong> FRANCIA. 1959. B\/N. 20\u2019. VOSE<\/li>\r\n \t<li><strong>R\u00c9FUTATION DE TOUS LES JUGEMENTS, TANT \u00c9LOGIEUX QU\u2019HOSTILES, QUI ON \u00c9TE JUSQU\u2019ICI PORT\u00c9S SUR LE FILM \u00abLA SOCI\u00c9T\u00c9 DU ESPECTACLE\u00bb<\/strong> FRANCIA. 1975. B\/N. 22\u2019. VOSE<\/li>\r\n<\/ul>\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/a-day-for-women\/\" data-onclick=\"link\" data-color=\"#d63031\" title=\"A DAY FOR WOMEN 111&#039;\" data-event-id=\"473\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 800px;\" data-top=\"800\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/a-day-for-women\/\"  data-onclick=\"link\" data-color=\"#d63031\" title=\"A DAY FOR WOMEN 111&#039;\" data-event-id=\"473\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 800px\" data-top=\"800\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #d63031; \" data-event-background-image-url=\"\" data-event-id=\"473\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">A DAY FOR WOMEN 111&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"473\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/18-days\/\" data-onclick=\"link\" data-color=\"#d63031\" title=\"18 DAYS 122&#039;\" data-event-id=\"474\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 200px; left: 1000px;\" data-top=\"1000\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/18-days\/\"  data-onclick=\"link\" data-color=\"#d63031\" title=\"18 DAYS 122&#039;\" data-event-id=\"474\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 200px; top: 1000px\" data-top=\"1000\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #d63031; \" data-event-background-image-url=\"\" data-event-id=\"474\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">18 DAYS 122&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"474\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/coming-forth-by-day\/\" data-onclick=\"link\" data-color=\"#d63031\" title=\"COMING FORTH BY DAY 96&#039;\" data-event-id=\"472\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 1250px;\" data-top=\"1250\" data-size=\"1\" data-sort-index=\"3\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/coming-forth-by-day\/\"  data-onclick=\"link\" data-color=\"#d63031\" title=\"COMING FORTH BY DAY 96&#039;\" data-event-id=\"472\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 1250px\" data-top=\"1250\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #d63031; \" data-event-background-image-url=\"\" data-event-id=\"472\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">COMING FORTH BY DAY 96&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"472\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1550px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/circuit-cultural-valencia\/\" data-onclick=\"link\" data-color=\"#833471\" title=\"Jornada de presentaci\u00f3n de largometrajes valencianos en el Circuit Cultural Valenci\u00e0. Sala Luis G. Berlanga. IVC.\" data-event-id=\"481\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 275px; left: 0px;\" data-top=\"0\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/circuit-cultural-valencia\/\"  data-onclick=\"link\" data-color=\"#833471\" title=\"Jornada de presentaci\u00f3n de largometrajes valencianos en el Circuit Cultural Valenci\u00e0. Sala Luis G. Berlanga. IVC.\" data-event-id=\"481\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 275px; top: 0px\" data-top=\"0\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #833471; \" data-event-background-image-url=\"\" data-event-id=\"481\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">Jornada de presentaci\u00f3n de largometrajes valencianos en el Circuit Cultural Valenci\u00e0. Sala Luis G. Berlanga. IVC.<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"481\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/mas-alla-del-bien-y-del-mal\/\" data-onclick=\"link\" data-color=\"#fa983a\" title=\"M\u00c1S ALL\u00c1 DEL BIEN Y DEL MAL 122&#039;\" data-event-id=\"476\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 200px; left: 800px;\" data-top=\"800\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/mas-alla-del-bien-y-del-mal\/\"  data-onclick=\"link\" data-color=\"#fa983a\" title=\"M\u00c1S ALL\u00c1 DEL BIEN Y DEL MAL 122&#039;\" data-event-id=\"476\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 200px; top: 800px\" data-top=\"800\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fa983a; \" data-event-background-image-url=\"\" data-event-id=\"476\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">M\u00c1S ALL\u00c1 DEL BIEN Y DEL MAL 122&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"476\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/milarepa\/\" data-onclick=\"link\" data-color=\"#fa983a\" title=\"MILAREPA 108&#039;\" data-event-id=\"479\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 1025px;\" data-top=\"1025\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/milarepa\/\"  data-onclick=\"link\" data-color=\"#fa983a\" title=\"MILAREPA 108&#039;\" data-event-id=\"479\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 1025px\" data-top=\"1025\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fa983a; \" data-event-background-image-url=\"\" data-event-id=\"479\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">MILAREPA 108&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"479\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/ospite\/\" data-onclick=\"link\" data-color=\"#fa983a\" title=\"L&#039;OSPITE 101&#039;\" data-event-id=\"475\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 1250px;\" data-top=\"1250\" data-size=\"1\" data-sort-index=\"3\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/ospite\/\"  data-onclick=\"link\" data-color=\"#fa983a\" title=\"L&#039;OSPITE 101&#039;\" data-event-id=\"475\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 1250px\" data-top=\"1250\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fa983a; \" data-event-background-image-url=\"\" data-event-id=\"475\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">L&#039;OSPITE 101&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"475\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1550px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/concierto-free-town\/\" data-onclick=\"link\" data-color=\"#833471\" title=\"Concierto FREE TOWN en homenaje a Toni Canet\" data-event-id=\"480\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 900px;\" data-top=\"900\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/concierto-free-town\/\"  data-onclick=\"link\" data-color=\"#833471\" title=\"Concierto FREE TOWN en homenaje a Toni Canet\" data-event-id=\"480\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 900px\" data-top=\"900\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #833471; \" data-event-background-image-url=\"\" data-event-id=\"480\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">Concierto FREE TOWN en homenaje a Toni Canet<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"480\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n<\/div><div class=\" sched-list sched-hidden\" id=\"sched-schedule-6-24027596-list\" data-id-schedule=\"sched-schedule-6-24027596\" data-options=\" {&quot;am_pm&quot;:&quot;0&quot;,&quot;sidebar_width&quot;:&quot;90&quot;,&quot;sidebar_position&quot;:&quot;left&quot;,&quot;event_hover_color&quot;:&quot;lighten&quot;,&quot;event_box_text_align&quot;:&quot;center&quot;,&quot;event_box_time&quot;:&quot;0&quot;,&quot;event_hover_text_color&quot;:&quot;#FFFFFF&quot;,&quot;event_hover_background_color&quot;:&quot;#000000&quot;,&quot;event_box_truncate_title&quot;:&quot;0&quot;,&quot;event_tooltip&quot;:&quot;0&quot;,&quot;event_tooltip_title&quot;:&quot;1&quot;,&quot;event_tooltip_time&quot;:&quot;1&quot;,&quot;event_tooltip_description&quot;:&quot;1&quot;,&quot;event_tooltip_width_type&quot;:&quot;event&quot;,&quot;event_tooltip_width&quot;:&quot;150&quot;,&quot;event_tooltip_color_type&quot;:&quot;event&quot;,&quot;event_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;event_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;column_tooltip&quot;:&quot;0&quot;,&quot;column_tooltip_title&quot;:&quot;1&quot;,&quot;column_tooltip_description&quot;:&quot;1&quot;,&quot;column_tooltip_width_type&quot;:&quot;column&quot;,&quot;column_tooltip_width&quot;:&quot;150&quot;,&quot;column_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;column_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;animations&quot;:&quot;1&quot;,&quot;animations_mobile&quot;:&quot;1&quot;,&quot;animations_speed&quot;:&quot;normal&quot;,&quot;animations_css3&quot;:&quot;1&quot;,&quot;tooltips_mobile&quot;:&quot;1&quot;,&quot;editor_bg&quot;:&quot;#F5F5F5&quot;,&quot;animations_editor&quot;:&quot;1&quot;,&quot;popup_max_width&quot;:&quot;560&quot;,&quot;popup_background_color&quot;:&quot;#ffffff&quot;,&quot;popup_text_color&quot;:&quot;#535353&quot;,&quot;popup_link_color&quot;:&quot;#ff4d00&quot;,&quot;autoplay_videos&quot;:&quot;1&quot;,&quot;column_color_bg&quot;:&quot;#e8e8e8&quot;,&quot;column_color_text&quot;:&quot;#3f3f3f&quot;,&quot;column_color_border&quot;:&quot;#ffffff&quot;,&quot;pattern_color_1&quot;:&quot;#ffffff&quot;,&quot;pattern_color_2&quot;:&quot;#e8e8e8&quot;,&quot;pattern_color_3&quot;:&quot;#ffffff&quot;,&quot;title_text_color&quot;:&quot;#3f3f3f&quot;,&quot;sidebar_text_color&quot;:&quot;#3f3f3f&quot;,&quot;event_box_text_color&quot;:&quot;#ffffff&quot;,&quot;title_attr&quot;:&quot;0&quot;,&quot;column_break&quot;:1,&quot;column_break_width&quot;:&quot;120&quot;,&quot;column_break_hide_sidebar&quot;:&quot;0&quot;,&quot;editor_custom_css&quot;:&quot;1&quot;,&quot;column_title&quot;:&quot;1&quot;,&quot;event_box_description_method&quot;:&quot;short&quot;,&quot;editor_quick_tooltips&quot;:&quot;1&quot;,&quot;editor_timepicker_increments&quot;:&quot;15&quot;,&quot;event_box_style&quot;:&quot;1&quot;,&quot;filter_position&quot;:&quot;right&quot;,&quot;filter_multiple&quot;:&quot;1&quot;,&quot;filter_hidden_events&quot;:&quot;hide&quot;,&quot;filter_hidden_events_opacity&quot;:&quot;30&quot;,&quot;filter_dropdown_width&quot;:&quot;100&quot;,&quot;filter_dropdown_hover_width&quot;:&quot;180&quot;,&quot;filter_dropdown_label&quot;:&quot;Secci\\u00f3n&quot;,&quot;filter_dropdown_show_all_label&quot;:&quot;Mostrar todo&quot;,&quot;hashtag_url&quot;:&quot;1&quot;,&quot;hide_popup_for_empty_events&quot;:&quot;1&quot;,&quot;event_box_padding_break&quot;:&quot;200&quot;,&quot;popup_arrows&quot;:&quot;1&quot;,&quot;filter_visible&quot;:&quot;1&quot;,&quot;column_break_action&quot;:&quot;list&quot;,&quot;list_view_column_title_color&quot;:&quot;#3f3f3f&quot;,&quot;list_view_event_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_hover_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_title_bold&quot;:&quot;1&quot;,&quot;list_view_event_bullets&quot;:&quot;2&quot;,&quot;list_view_event_short_description_method&quot;:&quot;short&quot;,&quot;list_view_event_description_color&quot;:&quot;#ffffff&quot;,&quot;list_view_hide_empty_columns&quot;:&quot;1&quot;,&quot;shortcodes_in_descriptions&quot;:&quot;1&quot;,&quot;columns_sticky_header&quot;:&quot;1&quot;,&quot;columns_sticky_header_offset&quot;:&quot;0&quot;,&quot;h_row_height&quot;:&quot;110&quot;,&quot;h_column_width&quot;:&quot;200&quot;,&quot;h_time_indicator&quot;:&quot;1&quot;,&quot;h_time_indicator_height&quot;:30,&quot;h_column_multiline&quot;:&quot;0&quot;,&quot;h_column_title_position&quot;:&quot;middle&quot;,&quot;h_column_title_align&quot;:&quot;center&quot;,&quot;h_break&quot;:&quot;0&quot;,&quot;h_width_break_point&quot;:&quot;200&quot;,&quot;h_bg_color&quot;:&quot;#f8f8f8&quot;,&quot;pdf_type&quot;:&quot;html&quot;,&quot;pdf_enable&quot;:&quot;0&quot;,&quot;pdf_enable_list&quot;:&quot;0&quot;,&quot;pdf_label&quot;:&quot;Download&quot;,&quot;pdf_css&quot;:&quot;&quot;,&quot;upcoming_type&quot;:&quot;current_datetime&quot;,&quot;upcoming_custom&quot;:&quot;2016-01-01 00:00&quot;,&quot;upcoming_limit&quot;:&quot;5&quot;,&quot;upcoming_title&quot;:&quot;timetable_title&quot;,&quot;upcoming_title_custom&quot;:&quot;Upcoming Events&quot;,&quot;upcoming_title_amount&quot;:&quot;1&quot;}\" data-start=\"10:00\" data-end=\"01:30\" data-timetable-id=\"6\" data-type=\"list\" data-layout=\"horizontal\">\t<div class=\"sched-list-top\">\n\t\t<div class=\"sched-list-title\">Martes 29 de octubre<\/div>\n\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 1<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/flesh-out\/\" data-event-id=\"468\" target=\"_blank\" style=\"background: #ff7675;\" data-color=\"#ff7675\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ff7675;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tFLESH OUT 94&#039; Con la presencia de la directora Michela Occhipinti\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">11:30 - 13:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/no-basta-una-vida\/\" data-event-id=\"462\" target=\"_blank\" style=\"background: #27ae60;\" data-color=\"#27ae60\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #27ae60;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tNO BASTA UNA VIDA 110&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 17:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/allacciate-le-cinture\/\" data-event-id=\"92\" target=\"_blank\" style=\"background: #27ae60;\" data-color=\"#27ae60\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #27ae60;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tALLACCIATE LE CINTURE 110&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-alcalde-el-guardia-y-la-jirafita\/\" data-event-id=\"457\" target=\"_blank\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tEL ALCALDE, EL GUARDIA Y LA JIRAFITA 100&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 21:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/celos-a-la-italiana\/\" data-event-id=\"459\" target=\"_blank\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tCELOS A LA ITALIANA 124&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 2<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/guapas-pero-pobres\/\" data-event-id=\"460\" target=\"_blank\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tGUAPAS, PERO POBRES 99&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 17:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/pobre-y-millonario\/\" data-event-id=\"461\" target=\"_blank\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tPOBRE Y MILLONARIO 95&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-ultimo-haren\/\" data-event-id=\"456\" target=\"_blank\" style=\"background: #27ae60;\" data-color=\"#27ae60\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #27ae60;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tEL \u00daLTIMO HAR\u00c9N 115&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 22:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/rufufu\/\" data-event-id=\"99\" target=\"_blank\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tRUFUF\u00da 106&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 3<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/freedom-fields\/\" data-event-id=\"464\" style=\"background: #ffc312;\" data-color=\"#ffc312\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ffc312;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tFREEDOM FIELDS 97&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 17:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/mafak\/\" data-event-id=\"465\" style=\"background: #ffc312;\" data-color=\"#ffc312\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ffc312;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tMAFAK 108&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/jalas\/\" data-event-id=\"466\" style=\"background: #0694d6;\" data-color=\"#0694d6\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #0694d6;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tJALAS 30&#039; Con la presencia de la directora, Olga Arias, y el equipo de la pel\u00edcula\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 21:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/zero-impunity\/\" data-event-id=\"463\" style=\"background: #ffc312;\" data-color=\"#ffc312\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ffc312;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tZERO IMPUNITY 95&#039; Con la presencia del productor Fran\u00e7ois Le Gall\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 4<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/a-shelter-among-the-clouds\/\" data-event-id=\"469\" target=\"_blank\" style=\"background: #ff7675;\" data-color=\"#ff7675\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ff7675;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tA SHELTER AMONG THE CLOUDS 85&#039; Con la presencia del director, Robert Budina y del actor Arben Bajraktaraj\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 17:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/a-herdade\/\" data-event-id=\"470\" target=\"_blank\" style=\"background: #ff7675;\" data-color=\"#ff7675\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ff7675;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tA HERDADE 166&#039; Con la presencia del director, Tiago Guedes\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 20:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/the-announcement\/\" data-event-id=\"103\" target=\"_blank\" style=\"background: #ff7675;\" data-color=\"#ff7675\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ff7675;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tTHE ANNOUNCEMENT 94&#039; Con la presencia del actor \u015eencan G\u00fclery\u00fcz\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 5<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"#event-471\" data-event-id=\"471\" style=\"background: #9980fa;\" data-color=\"#9980fa\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #9980fa;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tPROGRAMA CORTOS GUY DEBORD 68&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 17:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/a-day-for-women\/\" data-event-id=\"473\" style=\"background: #d63031;\" data-color=\"#d63031\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #d63031;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tA DAY FOR WOMEN 111&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/18-days\/\" data-event-id=\"474\" style=\"background: #d63031;\" data-color=\"#d63031\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #d63031;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\t18 DAYS 122&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 22:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/coming-forth-by-day\/\" data-event-id=\"472\" style=\"background: #d63031;\" data-color=\"#d63031\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #d63031;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tCOMING FORTH BY DAY 96&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">FILMOTECA<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/circuit-cultural-valencia\/\" data-event-id=\"481\" style=\"background: #833471;\" data-color=\"#833471\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #833471;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tJornada de presentaci\u00f3n de largometrajes valencianos en el Circuit Cultural Valenci\u00e0. Sala Luis G. Berlanga. IVC.\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">10:00 - 12:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/mas-alla-del-bien-y-del-mal\/\" data-event-id=\"476\" style=\"background: #fa983a;\" data-color=\"#fa983a\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fa983a;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tM\u00c1S ALL\u00c1 DEL BIEN Y DEL MAL 122&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 20:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/milarepa\/\" data-event-id=\"479\" style=\"background: #fa983a;\" data-color=\"#fa983a\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fa983a;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tMILAREPA 108&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:15 - 22:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/ospite\/\" data-event-id=\"475\" style=\"background: #fa983a;\" data-color=\"#fa983a\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fa983a;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tL&#039;OSPITE 101&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">SGAE<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/concierto-free-town\/\" data-event-id=\"480\" style=\"background: #833471;\" data-color=\"#833471\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #833471;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tConcierto FREE TOWN en homenaje a Toni Canet\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">19:00 - 20:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t<!-- .sched-list-column -->\n\t\n<\/div>[\/vc_column][\/vc_row][vc_row disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1600188404415{padding-right: 40px !important;padding-bottom: 50px !important;padding-left: 40px !important;}&#8221; anchor=&#8221;miercoles-30&#8243;][vc_column]<div class=\"sched-loader\"><div class=\"sched-loader-icon\"><\/div><div class=\"sched-loader-text\"><\/div><\/div>\n<div class=\" sched sched-horizontal sched-horizontal-medium\" id=\"sched-schedule-7-1627341222\" data-options=\" {&quot;am_pm&quot;:&quot;0&quot;,&quot;sidebar_width&quot;:&quot;90&quot;,&quot;sidebar_position&quot;:&quot;left&quot;,&quot;event_hover_color&quot;:&quot;lighten&quot;,&quot;event_box_text_align&quot;:&quot;center&quot;,&quot;event_box_time&quot;:&quot;0&quot;,&quot;event_hover_text_color&quot;:&quot;#FFFFFF&quot;,&quot;event_hover_background_color&quot;:&quot;#000000&quot;,&quot;event_box_truncate_title&quot;:&quot;0&quot;,&quot;event_tooltip&quot;:&quot;0&quot;,&quot;event_tooltip_title&quot;:&quot;1&quot;,&quot;event_tooltip_time&quot;:&quot;1&quot;,&quot;event_tooltip_description&quot;:&quot;1&quot;,&quot;event_tooltip_width_type&quot;:&quot;event&quot;,&quot;event_tooltip_width&quot;:&quot;150&quot;,&quot;event_tooltip_color_type&quot;:&quot;event&quot;,&quot;event_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;event_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;column_tooltip&quot;:&quot;0&quot;,&quot;column_tooltip_title&quot;:&quot;1&quot;,&quot;column_tooltip_description&quot;:&quot;1&quot;,&quot;column_tooltip_width_type&quot;:&quot;column&quot;,&quot;column_tooltip_width&quot;:&quot;150&quot;,&quot;column_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;column_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;animations&quot;:&quot;1&quot;,&quot;animations_mobile&quot;:&quot;1&quot;,&quot;animations_speed&quot;:&quot;normal&quot;,&quot;animations_css3&quot;:&quot;1&quot;,&quot;tooltips_mobile&quot;:&quot;1&quot;,&quot;editor_bg&quot;:&quot;#F5F5F5&quot;,&quot;animations_editor&quot;:&quot;1&quot;,&quot;popup_max_width&quot;:&quot;560&quot;,&quot;popup_background_color&quot;:&quot;#ffffff&quot;,&quot;popup_text_color&quot;:&quot;#535353&quot;,&quot;popup_link_color&quot;:&quot;#ff4d00&quot;,&quot;autoplay_videos&quot;:&quot;1&quot;,&quot;column_color_bg&quot;:&quot;#e8e8e8&quot;,&quot;column_color_text&quot;:&quot;#3f3f3f&quot;,&quot;column_color_border&quot;:&quot;#ffffff&quot;,&quot;pattern_color_1&quot;:&quot;#ffffff&quot;,&quot;pattern_color_2&quot;:&quot;#e8e8e8&quot;,&quot;pattern_color_3&quot;:&quot;#ffffff&quot;,&quot;title_text_color&quot;:&quot;#3f3f3f&quot;,&quot;sidebar_text_color&quot;:&quot;#3f3f3f&quot;,&quot;event_box_text_color&quot;:&quot;#ffffff&quot;,&quot;title_attr&quot;:&quot;0&quot;,&quot;column_break&quot;:1,&quot;column_break_width&quot;:&quot;120&quot;,&quot;column_break_hide_sidebar&quot;:&quot;0&quot;,&quot;editor_custom_css&quot;:&quot;1&quot;,&quot;column_title&quot;:&quot;1&quot;,&quot;event_box_description_method&quot;:&quot;short&quot;,&quot;editor_quick_tooltips&quot;:&quot;1&quot;,&quot;editor_timepicker_increments&quot;:&quot;15&quot;,&quot;event_box_style&quot;:&quot;1&quot;,&quot;filter_position&quot;:&quot;right&quot;,&quot;filter_multiple&quot;:&quot;1&quot;,&quot;filter_hidden_events&quot;:&quot;hide&quot;,&quot;filter_hidden_events_opacity&quot;:&quot;30&quot;,&quot;filter_dropdown_width&quot;:&quot;100&quot;,&quot;filter_dropdown_hover_width&quot;:&quot;180&quot;,&quot;filter_dropdown_label&quot;:&quot;Secci\\u00f3n&quot;,&quot;filter_dropdown_show_all_label&quot;:&quot;Mostrar todo&quot;,&quot;hashtag_url&quot;:&quot;1&quot;,&quot;hide_popup_for_empty_events&quot;:&quot;1&quot;,&quot;event_box_padding_break&quot;:&quot;200&quot;,&quot;popup_arrows&quot;:&quot;1&quot;,&quot;filter_visible&quot;:&quot;1&quot;,&quot;column_break_action&quot;:&quot;list&quot;,&quot;list_view_column_title_color&quot;:&quot;#3f3f3f&quot;,&quot;list_view_event_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_hover_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_title_bold&quot;:&quot;1&quot;,&quot;list_view_event_bullets&quot;:&quot;2&quot;,&quot;list_view_event_short_description_method&quot;:&quot;short&quot;,&quot;list_view_event_description_color&quot;:&quot;#ffffff&quot;,&quot;list_view_hide_empty_columns&quot;:&quot;1&quot;,&quot;shortcodes_in_descriptions&quot;:&quot;1&quot;,&quot;columns_sticky_header&quot;:&quot;1&quot;,&quot;columns_sticky_header_offset&quot;:&quot;0&quot;,&quot;h_row_height&quot;:&quot;110&quot;,&quot;h_column_width&quot;:&quot;200&quot;,&quot;h_time_indicator&quot;:&quot;1&quot;,&quot;h_time_indicator_height&quot;:30,&quot;h_column_multiline&quot;:&quot;0&quot;,&quot;h_column_title_position&quot;:&quot;middle&quot;,&quot;h_column_title_align&quot;:&quot;center&quot;,&quot;h_break&quot;:&quot;0&quot;,&quot;h_width_break_point&quot;:&quot;200&quot;,&quot;h_bg_color&quot;:&quot;#f8f8f8&quot;,&quot;pdf_type&quot;:&quot;html&quot;,&quot;pdf_enable&quot;:&quot;0&quot;,&quot;pdf_enable_list&quot;:&quot;0&quot;,&quot;pdf_label&quot;:&quot;Download&quot;,&quot;pdf_css&quot;:&quot;&quot;,&quot;upcoming_type&quot;:&quot;current_datetime&quot;,&quot;upcoming_custom&quot;:&quot;2016-01-01 00:00&quot;,&quot;upcoming_limit&quot;:&quot;5&quot;,&quot;upcoming_title&quot;:&quot;timetable_title&quot;,&quot;upcoming_title_custom&quot;:&quot;Upcoming Events&quot;,&quot;upcoming_title_amount&quot;:&quot;1&quot;}\" data-start=\"11:00\" data-end=\"01:30\" data-timetable-id=\"7\" data-type=\"full\" data-list-id=\"#sched-schedule-7-1627341222-list\" data-layout=\"horizontal\">\t<div class=\"sched-style\"><style type=\"text\/css\">\/*\n * Custom CSS For Timetable\n*\/\n\n#sched-schedule-7-1627341222 .sched-column-header,\n#sched-schedule-7-1627341222 .sched-column-header-sticky {\n\tbackground: #e8e8e8;\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-7-1627341222 .sched-column-header:after,\n#sched-schedule-7-1627341222 .sched-column-header-sticky:after {\n\tbackground: #ffffff;\n}\n\n#sched-schedule-7-1627341222 .sched-columns .sched-column:last-child .sched-column-header:after,\n#sched-schedule-7-1627341222 .sched-columns .sched-column:last-child .sched-column-header-sticky:after {\n\tbackground: #e8e8e8;\n}\n\n#sched-schedule-7-1627341222 .sched-column-bg-block {\n\tbackground: #ffffff;\n\tborder-color: #e8e8e8;\n}\n\n#sched-schedule-7-1627341222 .sched-column-bg-block:after {\n\tbackground: #ffffff;\n}\n\n#sched-schedule-7-1627341222 .sched-row-no-title .sched-column .sched-column-bg {\n\tbox-shadow: 0 -1px 0 #e8e8e8;\n}\n\n#sched-schedule-7-1627341222 .sched-title {\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-7-1627341222 .sched-time-value {\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-7-1627341222 .sched-event .sched-event-inner {\n\tcolor: #ffffff;\n\ttext-align: center;\n}\n\n#sched-schedule-7-1627341222 .sched-event.sched-event-invert .sched-event-inner {\n\t<!-- background: #999; -->\n}\n\n\n\n\/*#sched-schedule-7-1627341222 a.sched-event.sched-event-sort-hidden {\n\topacity: 0;\n}*\/\n\n#sched-schedule-7-1627341222 .sched-sort .sched-sort-current .sched-sort-current-label {\n\twidth: 100px;\n}\n\n#sched-schedule-7-1627341222 .sched-sort.sched-sort-open .sched-sort-dropdown .sched-sort-current .sched-sort-current-label {\n\twidth: 180px;\n}\n\n\/*\n * Custom CSS Event Popup\n *\/\n\n#sched-schedule-7-1627341222-popup .sched-popup-description {\n\t\n}\n\n#sched-schedule-7-1627341222-popup .sched-popup-description .sched-meta a,\n#sched-schedule-7-1627341222-popup .sched-popup-description .sched-popup-description-text a {\n\tcolor: #ff4d00;\n}\n\n#sched-schedule-7-1627341222-popup .sched-popup-description .sched-meta,\n#sched-schedule-7-1627341222-popup .sched-popup-description .sched-popup-description-text {\n\tcolor: #535353;\n\tbackground: #ffffff;\n}\n\n\/*\n * List\n *\/\n\n#sched-schedule-7-1627341222-list .sched-list-title {\n\tcolor: #3f3f3f;\n}\n\n\n\n#sched-schedule-7-1627341222-list .sched-list-column-title {\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-7-1627341222-list .sched-list-event {\n\tcolor: #ffffff;\n\t\n\t\n}\n\n#sched-schedule-7-1627341222-list .sched-list-event:hover {\n\tcolor: #ffffff;\n}\n\n#sched-schedule-7-1627341222-list .sched-list-event-description {\n\tcolor: #ffffff;\n}\n\n#sched-schedule-7-1627341222-list .sched-list-event-title {\n\t\tfont-weight: bold;\n\t;\n}\n\n\/*\n * Horizontal\n *\/\n\n\n\n#sched-schedule-7-1627341222 .sched-h-columns {\n\tmargin-top: 30px;\n}\n\n#sched-schedule-7-1627341222 .sched-h-content-columns {\n\t\/*margin-top: 30px;*\/\n}\n\n\n#sched-schedule-7-1627341222 .sched-h-columns {\n\twidth: 200px;\n}\n\n#sched-schedule-7-1627341222 .sched-h-content {\n\tmargin-left: 200px;\n}\n\n#sched-schedule-7-1627341222 .sched-h-column-title {\n\ttext-align: center;\n}\n\n#sched-schedule-7-1627341222 .sched-h-column {\n\tbackground: #e8e8e8;\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-7-1627341222 .sched-h-row {\n\tbackground-color: #f8f8f8;\n}\n<\/style><\/div>\n\t<div class=\"sched-top\">\n\t\t\t<h2 class=\"sched-title\">Mi\u00e9rcoles 30 de octubre<\/h2>\n\t\t<div class=\"sched-top-buttons sched-top-buttons-right\">\n\t\t\t\n\t\t\t<\/div><!-- .sched-top-buttons -->\n<\/div><!-- .sched-top -->\t<div class=\"sched-row\">\n\t\t\t\t\t<!-- <div class=\"sched-sidebar\" style=\"width: 90px;\">\n\t\t\t\t<div class=\"sched-time\">\n\t\t\t\t\t<div class=\"sched-time-value\" style=\"padding-bottom: 36px\">11:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">12:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">13:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">14:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">15:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">16:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">17:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">18:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">19:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">20:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">21:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">22:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">23:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">00:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">01:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">02:00<\/div>\t\t\t\t<\/div>\n\t\t\t<\/div> -->\n\t\t\t\t\t\t<div class=\"sched-h-columns\">\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 1\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 2\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 3\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 4\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 5\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tFILMOTECA\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBARREIRA ARTE + DISE\u00d1O\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"sched-h-content\">\n\t\t\t<div class=\"sched-h-content-scroll\">\n\t\t\t\t\t\t\t\t<div class=\"sched-h-content-scroll-time\">\n\t\t\t\t\t<div class=\"sched-h-content-scroll-time-value\" data-i=\"0\" style=\"left: 0px;\">11:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"1\" style=\"left: 100px;\">12:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"2\" style=\"left: 200px;\">13:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"3\" style=\"left: 300px;\">14:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"4\" style=\"left: 400px;\">15:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"5\" style=\"left: 500px;\">16:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"6\" style=\"left: 600px;\">17:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"7\" style=\"left: 700px;\">18:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"8\" style=\"left: 800px;\">19:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"9\" style=\"left: 900px;\">20:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"10\" style=\"left: 1000px;\">21:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"11\" style=\"left: 1100px;\">22:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"12\" style=\"left: 1200px;\">23:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"13\" style=\"left: 1300px;\">00:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"14\" style=\"left: 1400px;\">01:00<\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"sched-h-content-columns\">\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/zero\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"ZER\u00d8 94&#039; Con la presencia del director, I\u00f1aki S\u00e1nchez y el equipo de la pel\u00edcula\" data-event-id=\"487\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 50px;\" data-top=\"50\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/zero\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"ZER\u00d8 94&#039; Con la presencia del director, I\u00f1aki S\u00e1nchez y el equipo de la pel\u00edcula\" data-event-id=\"487\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 50px\" data-top=\"50\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ff7675; \" data-event-background-image-url=\"\" data-event-id=\"487\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">ZER\u00d8 94&#039; Con la presencia del director, I\u00f1aki S\u00e1nchez y el equipo de la pel\u00edcula<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"487\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-viudo\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#128997\" title=\"EL VIUDO 87&#039;\" data-event-id=\"488\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 500px;\" data-top=\"500\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-viudo\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#128997\" title=\"EL VIUDO 87&#039;\" data-event-id=\"488\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 500px\" data-top=\"500\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"488\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">EL VIUDO 87&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"488\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/gli-anni-ruggenti\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#128997\" title=\"GLI ANNI RUGGENTI 110&#039;\" data-event-id=\"491\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 700px;\" data-top=\"700\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/gli-anni-ruggenti\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#128997\" title=\"GLI ANNI RUGGENTI 110&#039;\" data-event-id=\"491\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 700px\" data-top=\"700\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"491\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">GLI ANNI RUGGENTI 110&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"491\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/cuore-sacro\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"CUORE SACRO 117&#039;\" data-event-id=\"492\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 200px; left: 900px;\" data-top=\"900\" data-size=\"1\" data-sort-index=\"3\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/cuore-sacro\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"CUORE SACRO 117&#039;\" data-event-id=\"492\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 200px; top: 900px\" data-top=\"900\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #27ae60; \" data-event-background-image-url=\"\" data-event-id=\"492\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">CUORE SACRO 117&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"492\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-ventana-de-enfrente\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"LA VENTANA DE ENFRENTE 106&#039;\" data-event-id=\"493\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"4\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-ventana-de-enfrente\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"LA VENTANA DE ENFRENTE 106&#039;\" data-event-id=\"493\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #27ae60; \" data-event-background-image-url=\"\" data-event-id=\"493\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">LA VENTANA DE ENFRENTE 106&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"493\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-hada-ignorante\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"EL HADA IGNORANTE 106&#039;\" data-event-id=\"494\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 500px;\" data-top=\"500\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-hada-ignorante\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"EL HADA IGNORANTE 106&#039;\" data-event-id=\"494\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 500px\" data-top=\"500\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #27ae60; \" data-event-background-image-url=\"\" data-event-id=\"494\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">EL HADA IGNORANTE 106&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"494\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/magnifica-presenza\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"MAGNIFICA PRESENZA 105&#039;\" data-event-id=\"499\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 700px;\" data-top=\"700\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/magnifica-presenza\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"MAGNIFICA PRESENZA 105&#039;\" data-event-id=\"499\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 700px\" data-top=\"700\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #27ae60; \" data-event-background-image-url=\"\" data-event-id=\"499\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">MAGNIFICA PRESENZA 105&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"499\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/rufufu\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#128997\" title=\"RUFUF\u00da 106&#039;\" data-event-id=\"490\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 200px; left: 900px;\" data-top=\"900\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/rufufu\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#128997\" title=\"RUFUF\u00da 106&#039;\" data-event-id=\"490\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 200px; top: 900px\" data-top=\"900\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"490\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">RUFUF\u00da 106&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"490\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-escapada\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#128997\" title=\"LA ESCAPADA 105&#039;\" data-event-id=\"482\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"3\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-escapada\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#128997\" title=\"LA ESCAPADA 105&#039;\" data-event-id=\"482\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"482\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">LA ESCAPADA 105&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"482\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/mafak\/\" data-onclick=\"link\" data-color=\"#fcc312\" title=\"MAFAK 108&#039;\" data-event-id=\"496\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 500px;\" data-top=\"500\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/mafak\/\"  data-onclick=\"link\" data-color=\"#fcc312\" title=\"MAFAK 108&#039;\" data-event-id=\"496\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 500px\" data-top=\"500\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fcc312; \" data-event-background-image-url=\"\" data-event-id=\"496\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">MAFAK 108&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"496\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/are-you-glad-im-here\/\" data-onclick=\"link\" data-color=\"#fcc312\" title=\"ARE YOU GLAD I&#039;M HERE 85&#039;\" data-event-id=\"497\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 700px;\" data-top=\"700\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/are-you-glad-im-here\/\"  data-onclick=\"link\" data-color=\"#fcc312\" title=\"ARE YOU GLAD I&#039;M HERE 85&#039;\" data-event-id=\"497\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 700px\" data-top=\"700\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fcc312; \" data-event-background-image-url=\"\" data-event-id=\"497\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">ARE YOU GLAD I&#039;M HERE 85&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"497\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/zero-impunity\/\" data-onclick=\"link\" data-color=\"#fcc312\" title=\"ZERO IMPUNITY 95&#039; Con la presencia del productor, Fran\u00e7ois Le Gall\" data-event-id=\"498\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 900px;\" data-top=\"900\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/zero-impunity\/\"  data-onclick=\"link\" data-color=\"#fcc312\" title=\"ZERO IMPUNITY 95&#039; Con la presencia del productor, Fran\u00e7ois Le Gall\" data-event-id=\"498\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 900px\" data-top=\"900\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fcc312; \" data-event-background-image-url=\"\" data-event-id=\"498\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">ZERO IMPUNITY 95&#039; Con la presencia del productor, Fran\u00e7ois Le Gall<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"498\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/danzantes\/\" data-onclick=\"link\" data-color=\"#0694d6\" title=\"DANZANTES 82&#039; Con la presencia del director, Juan Vicente Chuli\u00e1, de la bailarina Anouscka Brodacz y el compositor Antonio Lioci &quot;Globster&quot;\" data-event-id=\"495\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"3\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/danzantes\/\"  data-onclick=\"link\" data-color=\"#0694d6\" title=\"DANZANTES 82&#039; Con la presencia del director, Juan Vicente Chuli\u00e1, de la bailarina Anouscka Brodacz y el compositor Antonio Lioci &quot;Globster&quot;\" data-event-id=\"495\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #0694d6; \" data-event-background-image-url=\"\" data-event-id=\"495\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">DANZANTES 82&#039; Con la presencia del director, Juan Vicente Chuli\u00e1, de la bailarina Anouscka Brodacz y el compositor Antonio Lioci &quot;Globster&quot;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"495\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/between-two-seas\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"BETWEEN TWO SEAS 87&#039; Con la presencia de la actriz Yara Gobran y el productor Abdulrahman El-Garawany\" data-event-id=\"485\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 500px;\" data-top=\"500\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/between-two-seas\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"BETWEEN TWO SEAS 87&#039; Con la presencia de la actriz Yara Gobran y el productor Abdulrahman El-Garawany\" data-event-id=\"485\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 500px\" data-top=\"500\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ff7675; \" data-event-background-image-url=\"\" data-event-id=\"485\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">BETWEEN TWO SEAS 87&#039; Con la presencia de la actriz Yara Gobran y el productor Abdulrahman El-Garawany<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"485\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/napoli-velata\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"NAPOLI VELATA 113&#039;\" data-event-id=\"489\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 700px;\" data-top=\"700\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/napoli-velata\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"NAPOLI VELATA 113&#039;\" data-event-id=\"489\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 700px\" data-top=\"700\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #27ae60; \" data-event-background-image-url=\"\" data-event-id=\"489\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">NAPOLI VELATA 113&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"489\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/a-shelter-among-the-clouds\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"A SHELTER AMONG THE CLOUDS 85&#039; Con la presencia del director, Robert Budina y del actor Arben Bajraktaraj\" data-event-id=\"486\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 900px;\" data-top=\"900\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\" https:\/\/lamostradevalencia.com\/peliculas\/a-shelter-among-the-clouds\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"A SHELTER AMONG THE CLOUDS 85&#039; Con la presencia del director, Robert Budina y del actor Arben Bajraktaraj\" data-event-id=\"486\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 900px\" data-top=\"900\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ff7675; \" data-event-background-image-url=\"\" data-event-id=\"486\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">A SHELTER AMONG THE CLOUDS 85&#039; Con la presencia del director, Robert Budina y del actor Arben Bajraktaraj<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"486\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/flesh-out\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"FLESH OUT 94&#039; Con la presencia de la directora, Michela Occhipinti\" data-event-id=\"115\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"3\"><!-- <a class=\"sched-event   \" href=\" https:\/\/lamostradevalencia.com\/peliculas\/flesh-out\/\" target=\"_blank\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"FLESH OUT 94&#039; Con la presencia de la directora, Michela Occhipinti\" data-event-id=\"115\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ff7675; \" data-event-background-image-url=\"\" data-event-id=\"115\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">FLESH OUT 94&#039; Con la presencia de la directora, Michela Occhipinti<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"115\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/one-zero\/\" data-onclick=\"link\" data-color=\"#d63031\" title=\"ONE-ZERO 105&#039;\" data-event-id=\"501\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 500px;\" data-top=\"500\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/one-zero\/\"  data-onclick=\"link\" data-color=\"#d63031\" title=\"ONE-ZERO 105&#039;\" data-event-id=\"501\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 500px\" data-top=\"500\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #d63031; \" data-event-background-image-url=\"\" data-event-id=\"501\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">ONE-ZERO 105&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"501\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/coming-forth-by-day\/\" data-onclick=\"link\" data-color=\"#d63031\" title=\"COMING FORTH BY DAY 96&#039;\" data-event-id=\"502\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 700px;\" data-top=\"700\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/coming-forth-by-day\/\"  data-onclick=\"link\" data-color=\"#d63031\" title=\"COMING FORTH BY DAY 96&#039;\" data-event-id=\"502\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 700px\" data-top=\"700\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #d63031; \" data-event-background-image-url=\"\" data-event-id=\"502\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">COMING FORTH BY DAY 96&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"502\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/villa-69\/\" data-onclick=\"link\" data-color=\"#d63031\" title=\"VILLA 69 120&#039;\" data-event-id=\"500\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 200px; left: 900px;\" data-top=\"900\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/villa-69\/\"  data-onclick=\"link\" data-color=\"#d63031\" title=\"VILLA 69 120&#039;\" data-event-id=\"500\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 200px; top: 900px\" data-top=\"900\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #d63031; \" data-event-background-image-url=\"\" data-event-id=\"500\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">VILLA 69 120&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"500\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-sociedad-del-espectaculo\/\" data-onclick=\"link\" data-color=\"#9980fa\" title=\"LA SOCIEDAD DEL ESPECT\u00c1CULO 88&#039;\" data-event-id=\"503\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"3\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-sociedad-del-espectaculo\/\"  data-onclick=\"link\" data-color=\"#9980fa\" title=\"LA SOCIEDAD DEL ESPECT\u00c1CULO 88&#039;\" data-event-id=\"503\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #9980fa; \" data-event-background-image-url=\"\" data-event-id=\"503\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">LA SOCIEDAD DEL ESPECT\u00c1CULO 88&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"503\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-piel\/\" data-onclick=\"link\" data-color=\"#fa983a\" title=\"LA PIEL 130&#039;\" data-event-id=\"505\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 225px; left: 700px;\" data-top=\"700\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-piel\/\"  data-onclick=\"link\" data-color=\"#fa983a\" title=\"LA PIEL 130&#039;\" data-event-id=\"505\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 225px; top: 700px\" data-top=\"700\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fa983a; \" data-event-background-image-url=\"\" data-event-id=\"505\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">LA PIEL 130&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"505\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/berlin-interior\/\" data-onclick=\"link\" data-color=\"#fa983a\" title=\"BERL\u00cdN INTERIOR 110&#039;\" data-event-id=\"506\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 950px;\" data-top=\"950\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/berlin-interior\/\"  data-onclick=\"link\" data-color=\"#fa983a\" title=\"BERL\u00cdN INTERIOR 110&#039;\" data-event-id=\"506\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 950px\" data-top=\"950\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fa983a; \" data-event-background-image-url=\"\" data-event-id=\"506\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">BERL\u00cdN INTERIOR 110&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"506\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/detras-de-la-puerta\/\" data-onclick=\"link\" data-color=\"#fa983a\" title=\"DETR\u00c1S DE LA PUERTA 110&#039;\" data-event-id=\"504\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/detras-de-la-puerta\/\"  data-onclick=\"link\" data-color=\"#fa983a\" title=\"DETR\u00c1S DE LA PUERTA 110&#039;\" data-event-id=\"504\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fa983a; \" data-event-background-image-url=\"\" data-event-id=\"504\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">DETR\u00c1S DE LA PUERTA 110&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"504\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/coproducir-con-italia\/\" data-onclick=\"link\" data-color=\"#833471\" title=\"ABRIENDO FRONTERAS: COPRODUCIR CON ITALIA\" data-event-id=\"1016\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 250px; left: 0px;\" data-top=\"0\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/coproducir-con-italia\/\"  data-onclick=\"link\" data-color=\"#833471\" title=\"ABRIENDO FRONTERAS: COPRODUCIR CON ITALIA\" data-event-id=\"1016\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 250px; top: 0px\" data-top=\"0\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #833471; \" data-event-background-image-url=\"\" data-event-id=\"1016\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">ABRIENDO FRONTERAS: COPRODUCIR CON ITALIA<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"Sala La Cepiller\u00eda\">Sala La Cepiller\u00eda<\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"1016\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n<\/div><div class=\" sched-list sched-hidden\" id=\"sched-schedule-7-1627341222-list\" data-id-schedule=\"sched-schedule-7-1627341222\" data-options=\" {&quot;am_pm&quot;:&quot;0&quot;,&quot;sidebar_width&quot;:&quot;90&quot;,&quot;sidebar_position&quot;:&quot;left&quot;,&quot;event_hover_color&quot;:&quot;lighten&quot;,&quot;event_box_text_align&quot;:&quot;center&quot;,&quot;event_box_time&quot;:&quot;0&quot;,&quot;event_hover_text_color&quot;:&quot;#FFFFFF&quot;,&quot;event_hover_background_color&quot;:&quot;#000000&quot;,&quot;event_box_truncate_title&quot;:&quot;0&quot;,&quot;event_tooltip&quot;:&quot;0&quot;,&quot;event_tooltip_title&quot;:&quot;1&quot;,&quot;event_tooltip_time&quot;:&quot;1&quot;,&quot;event_tooltip_description&quot;:&quot;1&quot;,&quot;event_tooltip_width_type&quot;:&quot;event&quot;,&quot;event_tooltip_width&quot;:&quot;150&quot;,&quot;event_tooltip_color_type&quot;:&quot;event&quot;,&quot;event_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;event_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;column_tooltip&quot;:&quot;0&quot;,&quot;column_tooltip_title&quot;:&quot;1&quot;,&quot;column_tooltip_description&quot;:&quot;1&quot;,&quot;column_tooltip_width_type&quot;:&quot;column&quot;,&quot;column_tooltip_width&quot;:&quot;150&quot;,&quot;column_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;column_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;animations&quot;:&quot;1&quot;,&quot;animations_mobile&quot;:&quot;1&quot;,&quot;animations_speed&quot;:&quot;normal&quot;,&quot;animations_css3&quot;:&quot;1&quot;,&quot;tooltips_mobile&quot;:&quot;1&quot;,&quot;editor_bg&quot;:&quot;#F5F5F5&quot;,&quot;animations_editor&quot;:&quot;1&quot;,&quot;popup_max_width&quot;:&quot;560&quot;,&quot;popup_background_color&quot;:&quot;#ffffff&quot;,&quot;popup_text_color&quot;:&quot;#535353&quot;,&quot;popup_link_color&quot;:&quot;#ff4d00&quot;,&quot;autoplay_videos&quot;:&quot;1&quot;,&quot;column_color_bg&quot;:&quot;#e8e8e8&quot;,&quot;column_color_text&quot;:&quot;#3f3f3f&quot;,&quot;column_color_border&quot;:&quot;#ffffff&quot;,&quot;pattern_color_1&quot;:&quot;#ffffff&quot;,&quot;pattern_color_2&quot;:&quot;#e8e8e8&quot;,&quot;pattern_color_3&quot;:&quot;#ffffff&quot;,&quot;title_text_color&quot;:&quot;#3f3f3f&quot;,&quot;sidebar_text_color&quot;:&quot;#3f3f3f&quot;,&quot;event_box_text_color&quot;:&quot;#ffffff&quot;,&quot;title_attr&quot;:&quot;0&quot;,&quot;column_break&quot;:1,&quot;column_break_width&quot;:&quot;120&quot;,&quot;column_break_hide_sidebar&quot;:&quot;0&quot;,&quot;editor_custom_css&quot;:&quot;1&quot;,&quot;column_title&quot;:&quot;1&quot;,&quot;event_box_description_method&quot;:&quot;short&quot;,&quot;editor_quick_tooltips&quot;:&quot;1&quot;,&quot;editor_timepicker_increments&quot;:&quot;15&quot;,&quot;event_box_style&quot;:&quot;1&quot;,&quot;filter_position&quot;:&quot;right&quot;,&quot;filter_multiple&quot;:&quot;1&quot;,&quot;filter_hidden_events&quot;:&quot;hide&quot;,&quot;filter_hidden_events_opacity&quot;:&quot;30&quot;,&quot;filter_dropdown_width&quot;:&quot;100&quot;,&quot;filter_dropdown_hover_width&quot;:&quot;180&quot;,&quot;filter_dropdown_label&quot;:&quot;Secci\\u00f3n&quot;,&quot;filter_dropdown_show_all_label&quot;:&quot;Mostrar todo&quot;,&quot;hashtag_url&quot;:&quot;1&quot;,&quot;hide_popup_for_empty_events&quot;:&quot;1&quot;,&quot;event_box_padding_break&quot;:&quot;200&quot;,&quot;popup_arrows&quot;:&quot;1&quot;,&quot;filter_visible&quot;:&quot;1&quot;,&quot;column_break_action&quot;:&quot;list&quot;,&quot;list_view_column_title_color&quot;:&quot;#3f3f3f&quot;,&quot;list_view_event_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_hover_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_title_bold&quot;:&quot;1&quot;,&quot;list_view_event_bullets&quot;:&quot;2&quot;,&quot;list_view_event_short_description_method&quot;:&quot;short&quot;,&quot;list_view_event_description_color&quot;:&quot;#ffffff&quot;,&quot;list_view_hide_empty_columns&quot;:&quot;1&quot;,&quot;shortcodes_in_descriptions&quot;:&quot;1&quot;,&quot;columns_sticky_header&quot;:&quot;1&quot;,&quot;columns_sticky_header_offset&quot;:&quot;0&quot;,&quot;h_row_height&quot;:&quot;110&quot;,&quot;h_column_width&quot;:&quot;200&quot;,&quot;h_time_indicator&quot;:&quot;1&quot;,&quot;h_time_indicator_height&quot;:30,&quot;h_column_multiline&quot;:&quot;0&quot;,&quot;h_column_title_position&quot;:&quot;middle&quot;,&quot;h_column_title_align&quot;:&quot;center&quot;,&quot;h_break&quot;:&quot;0&quot;,&quot;h_width_break_point&quot;:&quot;200&quot;,&quot;h_bg_color&quot;:&quot;#f8f8f8&quot;,&quot;pdf_type&quot;:&quot;html&quot;,&quot;pdf_enable&quot;:&quot;0&quot;,&quot;pdf_enable_list&quot;:&quot;0&quot;,&quot;pdf_label&quot;:&quot;Download&quot;,&quot;pdf_css&quot;:&quot;&quot;,&quot;upcoming_type&quot;:&quot;current_datetime&quot;,&quot;upcoming_custom&quot;:&quot;2016-01-01 00:00&quot;,&quot;upcoming_limit&quot;:&quot;5&quot;,&quot;upcoming_title&quot;:&quot;timetable_title&quot;,&quot;upcoming_title_custom&quot;:&quot;Upcoming Events&quot;,&quot;upcoming_title_amount&quot;:&quot;1&quot;}\" data-start=\"11:00\" data-end=\"01:30\" data-timetable-id=\"7\" data-type=\"list\" data-layout=\"horizontal\">\t<div class=\"sched-list-top\">\n\t\t<div class=\"sched-list-title\">Mi\u00e9rcoles 30 de octubre<\/div>\n\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 1<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/zero\/\" data-event-id=\"487\" target=\"_blank\" style=\"background: #ff7675;\" data-color=\"#ff7675\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ff7675;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tZER\u00d8 94&#039; Con la presencia del director, I\u00f1aki S\u00e1nchez y el equipo de la pel\u00edcula\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">11:30 - 13:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-viudo\/\" data-event-id=\"488\" target=\"_blank\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tEL VIUDO 87&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 17:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/gli-anni-ruggenti\/\" data-event-id=\"491\" target=\"_blank\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tGLI ANNI RUGGENTI 110&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/cuore-sacro\/\" data-event-id=\"492\" target=\"_blank\" style=\"background: #27ae60;\" data-color=\"#27ae60\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #27ae60;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tCUORE SACRO 117&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 22:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-ventana-de-enfrente\/\" data-event-id=\"493\" target=\"_blank\" style=\"background: #27ae60;\" data-color=\"#27ae60\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #27ae60;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tLA VENTANA DE ENFRENTE 106&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 2<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-hada-ignorante\/\" data-event-id=\"494\" target=\"_blank\" style=\"background: #27ae60;\" data-color=\"#27ae60\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #27ae60;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tEL HADA IGNORANTE 106&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 17:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/magnifica-presenza\/\" data-event-id=\"499\" target=\"_blank\" style=\"background: #27ae60;\" data-color=\"#27ae60\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #27ae60;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tMAGNIFICA PRESENZA 105&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/rufufu\/\" data-event-id=\"490\" target=\"_blank\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tRUFUF\u00da 106&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 22:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-escapada\/\" data-event-id=\"482\" target=\"_blank\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tLA ESCAPADA 105&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 3<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/mafak\/\" data-event-id=\"496\" style=\"background: #fcc312;\" data-color=\"#fcc312\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fcc312;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tMAFAK 108&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 17:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/are-you-glad-im-here\/\" data-event-id=\"497\" style=\"background: #fcc312;\" data-color=\"#fcc312\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fcc312;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tARE YOU GLAD I&#039;M HERE 85&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/zero-impunity\/\" data-event-id=\"498\" style=\"background: #fcc312;\" data-color=\"#fcc312\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fcc312;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tZERO IMPUNITY 95&#039; Con la presencia del productor, Fran\u00e7ois Le Gall\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 21:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/danzantes\/\" data-event-id=\"495\" style=\"background: #0694d6;\" data-color=\"#0694d6\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #0694d6;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tDANZANTES 82&#039; Con la presencia del director, Juan Vicente Chuli\u00e1, de la bailarina Anouscka Brodacz y el compositor Antonio Lioci &quot;Globster&quot;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 4<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/between-two-seas\/\" data-event-id=\"485\" target=\"_blank\" style=\"background: #ff7675;\" data-color=\"#ff7675\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ff7675;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tBETWEEN TWO SEAS 87&#039; Con la presencia de la actriz Yara Gobran y el productor Abdulrahman El-Garawany\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 17:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/napoli-velata\/\" data-event-id=\"489\" target=\"_blank\" style=\"background: #27ae60;\" data-color=\"#27ae60\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #27ae60;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tNAPOLI VELATA 113&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/a-shelter-among-the-clouds\/\" data-event-id=\"486\" target=\"_blank\" style=\"background: #ff7675;\" data-color=\"#ff7675\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ff7675;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tA SHELTER AMONG THE CLOUDS 85&#039; Con la presencia del director, Robert Budina y del actor Arben Bajraktaraj\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 21:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\" https:\/\/lamostradevalencia.com\/peliculas\/flesh-out\/\" data-event-id=\"115\" target=\"_blank\" style=\"background: #ff7675;\" data-color=\"#ff7675\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ff7675;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tFLESH OUT 94&#039; Con la presencia de la directora, Michela Occhipinti\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 5<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/one-zero\/\" data-event-id=\"501\" style=\"background: #d63031;\" data-color=\"#d63031\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #d63031;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tONE-ZERO 105&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 17:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/coming-forth-by-day\/\" data-event-id=\"502\" style=\"background: #d63031;\" data-color=\"#d63031\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #d63031;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tCOMING FORTH BY DAY 96&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/villa-69\/\" data-event-id=\"500\" style=\"background: #d63031;\" data-color=\"#d63031\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #d63031;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tVILLA 69 120&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 22:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-sociedad-del-espectaculo\/\" data-event-id=\"503\" style=\"background: #9980fa;\" data-color=\"#9980fa\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #9980fa;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tLA SOCIEDAD DEL ESPECT\u00c1CULO 88&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">FILMOTECA<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-piel\/\" data-event-id=\"505\" style=\"background: #fa983a;\" data-color=\"#fa983a\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fa983a;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tLA PIEL 130&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 20:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/berlin-interior\/\" data-event-id=\"506\" style=\"background: #fa983a;\" data-color=\"#fa983a\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fa983a;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tBERL\u00cdN INTERIOR 110&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:30 - 22:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/detras-de-la-puerta\/\" data-event-id=\"504\" style=\"background: #fa983a;\" data-color=\"#fa983a\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fa983a;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tDETR\u00c1S DE LA PUERTA 110&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BARREIRA ARTE + DISE\u00d1O<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/coproducir-con-italia\/\" data-event-id=\"1016\" style=\"background: #833471;\" data-color=\"#833471\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #833471;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tABRIENDO FRONTERAS: COPRODUCIR CON ITALIA\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\tSala La Cepiller\u00eda\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">11:00 - 13:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t<!-- .sched-list-column -->\n\t\n<\/div>[\/vc_column][\/vc_row][vc_row disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1600188409928{padding-right: 40px !important;padding-bottom: 50px !important;padding-left: 40px !important;}&#8221; anchor=&#8221;jueves-31&#8243;][vc_column]<div class=\"sched-loader\"><div class=\"sched-loader-icon\"><\/div><div class=\"sched-loader-text\"><\/div><\/div>\n<div class=\" sched sched-horizontal sched-horizontal-medium\" id=\"sched-schedule-8-408296781\" data-options=\" {&quot;am_pm&quot;:&quot;0&quot;,&quot;sidebar_width&quot;:&quot;90&quot;,&quot;sidebar_position&quot;:&quot;left&quot;,&quot;event_hover_color&quot;:&quot;lighten&quot;,&quot;event_box_text_align&quot;:&quot;center&quot;,&quot;event_box_time&quot;:&quot;0&quot;,&quot;event_hover_text_color&quot;:&quot;#FFFFFF&quot;,&quot;event_hover_background_color&quot;:&quot;#000000&quot;,&quot;event_box_truncate_title&quot;:&quot;0&quot;,&quot;event_tooltip&quot;:&quot;0&quot;,&quot;event_tooltip_title&quot;:&quot;1&quot;,&quot;event_tooltip_time&quot;:&quot;1&quot;,&quot;event_tooltip_description&quot;:&quot;1&quot;,&quot;event_tooltip_width_type&quot;:&quot;event&quot;,&quot;event_tooltip_width&quot;:&quot;150&quot;,&quot;event_tooltip_color_type&quot;:&quot;event&quot;,&quot;event_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;event_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;column_tooltip&quot;:&quot;0&quot;,&quot;column_tooltip_title&quot;:&quot;1&quot;,&quot;column_tooltip_description&quot;:&quot;1&quot;,&quot;column_tooltip_width_type&quot;:&quot;column&quot;,&quot;column_tooltip_width&quot;:&quot;150&quot;,&quot;column_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;column_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;animations&quot;:&quot;1&quot;,&quot;animations_mobile&quot;:&quot;1&quot;,&quot;animations_speed&quot;:&quot;normal&quot;,&quot;animations_css3&quot;:&quot;1&quot;,&quot;tooltips_mobile&quot;:&quot;1&quot;,&quot;editor_bg&quot;:&quot;#F5F5F5&quot;,&quot;animations_editor&quot;:&quot;1&quot;,&quot;popup_max_width&quot;:&quot;560&quot;,&quot;popup_background_color&quot;:&quot;#ffffff&quot;,&quot;popup_text_color&quot;:&quot;#535353&quot;,&quot;popup_link_color&quot;:&quot;#ff4d00&quot;,&quot;autoplay_videos&quot;:&quot;1&quot;,&quot;column_color_bg&quot;:&quot;#e8e8e8&quot;,&quot;column_color_text&quot;:&quot;#3f3f3f&quot;,&quot;column_color_border&quot;:&quot;#ffffff&quot;,&quot;pattern_color_1&quot;:&quot;#ffffff&quot;,&quot;pattern_color_2&quot;:&quot;#e8e8e8&quot;,&quot;pattern_color_3&quot;:&quot;#ffffff&quot;,&quot;title_text_color&quot;:&quot;#3f3f3f&quot;,&quot;sidebar_text_color&quot;:&quot;#3f3f3f&quot;,&quot;event_box_text_color&quot;:&quot;#ffffff&quot;,&quot;title_attr&quot;:&quot;0&quot;,&quot;column_break&quot;:1,&quot;column_break_width&quot;:&quot;120&quot;,&quot;column_break_hide_sidebar&quot;:&quot;0&quot;,&quot;editor_custom_css&quot;:&quot;1&quot;,&quot;column_title&quot;:&quot;1&quot;,&quot;event_box_description_method&quot;:&quot;short&quot;,&quot;editor_quick_tooltips&quot;:&quot;1&quot;,&quot;editor_timepicker_increments&quot;:&quot;15&quot;,&quot;event_box_style&quot;:&quot;1&quot;,&quot;filter_position&quot;:&quot;right&quot;,&quot;filter_multiple&quot;:&quot;1&quot;,&quot;filter_hidden_events&quot;:&quot;hide&quot;,&quot;filter_hidden_events_opacity&quot;:&quot;30&quot;,&quot;filter_dropdown_width&quot;:&quot;100&quot;,&quot;filter_dropdown_hover_width&quot;:&quot;180&quot;,&quot;filter_dropdown_label&quot;:&quot;Secci\\u00f3n&quot;,&quot;filter_dropdown_show_all_label&quot;:&quot;Mostrar todo&quot;,&quot;hashtag_url&quot;:&quot;1&quot;,&quot;hide_popup_for_empty_events&quot;:&quot;1&quot;,&quot;event_box_padding_break&quot;:&quot;200&quot;,&quot;popup_arrows&quot;:&quot;1&quot;,&quot;filter_visible&quot;:&quot;1&quot;,&quot;column_break_action&quot;:&quot;list&quot;,&quot;list_view_column_title_color&quot;:&quot;#3f3f3f&quot;,&quot;list_view_event_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_hover_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_title_bold&quot;:&quot;1&quot;,&quot;list_view_event_bullets&quot;:&quot;2&quot;,&quot;list_view_event_short_description_method&quot;:&quot;short&quot;,&quot;list_view_event_description_color&quot;:&quot;#ffffff&quot;,&quot;list_view_hide_empty_columns&quot;:&quot;1&quot;,&quot;shortcodes_in_descriptions&quot;:&quot;1&quot;,&quot;columns_sticky_header&quot;:&quot;1&quot;,&quot;columns_sticky_header_offset&quot;:&quot;0&quot;,&quot;h_row_height&quot;:&quot;110&quot;,&quot;h_column_width&quot;:&quot;200&quot;,&quot;h_time_indicator&quot;:&quot;1&quot;,&quot;h_time_indicator_height&quot;:30,&quot;h_column_multiline&quot;:&quot;0&quot;,&quot;h_column_title_position&quot;:&quot;middle&quot;,&quot;h_column_title_align&quot;:&quot;center&quot;,&quot;h_break&quot;:&quot;0&quot;,&quot;h_width_break_point&quot;:&quot;200&quot;,&quot;h_bg_color&quot;:&quot;#f8f8f8&quot;,&quot;pdf_type&quot;:&quot;html&quot;,&quot;pdf_enable&quot;:&quot;0&quot;,&quot;pdf_enable_list&quot;:&quot;0&quot;,&quot;pdf_label&quot;:&quot;Download&quot;,&quot;pdf_css&quot;:&quot;&quot;,&quot;upcoming_type&quot;:&quot;current_datetime&quot;,&quot;upcoming_custom&quot;:&quot;2016-01-01 00:00&quot;,&quot;upcoming_limit&quot;:&quot;5&quot;,&quot;upcoming_title&quot;:&quot;timetable_title&quot;,&quot;upcoming_title_custom&quot;:&quot;Upcoming Events&quot;,&quot;upcoming_title_amount&quot;:&quot;1&quot;}\" data-start=\"11:00\" data-end=\"01:45\" data-timetable-id=\"8\" data-type=\"full\" data-list-id=\"#sched-schedule-8-408296781-list\" data-layout=\"horizontal\">\t<div class=\"sched-style\"><style type=\"text\/css\">\/*\n * Custom CSS For Timetable\n*\/\n\n#sched-schedule-8-408296781 .sched-column-header,\n#sched-schedule-8-408296781 .sched-column-header-sticky {\n\tbackground: #e8e8e8;\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-8-408296781 .sched-column-header:after,\n#sched-schedule-8-408296781 .sched-column-header-sticky:after {\n\tbackground: #ffffff;\n}\n\n#sched-schedule-8-408296781 .sched-columns .sched-column:last-child .sched-column-header:after,\n#sched-schedule-8-408296781 .sched-columns .sched-column:last-child .sched-column-header-sticky:after {\n\tbackground: #e8e8e8;\n}\n\n#sched-schedule-8-408296781 .sched-column-bg-block {\n\tbackground: #ffffff;\n\tborder-color: #e8e8e8;\n}\n\n#sched-schedule-8-408296781 .sched-column-bg-block:after {\n\tbackground: #ffffff;\n}\n\n#sched-schedule-8-408296781 .sched-row-no-title .sched-column .sched-column-bg {\n\tbox-shadow: 0 -1px 0 #e8e8e8;\n}\n\n#sched-schedule-8-408296781 .sched-title {\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-8-408296781 .sched-time-value {\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-8-408296781 .sched-event .sched-event-inner {\n\tcolor: #ffffff;\n\ttext-align: center;\n}\n\n#sched-schedule-8-408296781 .sched-event.sched-event-invert .sched-event-inner {\n\t<!-- background: #999; -->\n}\n\n\n\n\/*#sched-schedule-8-408296781 a.sched-event.sched-event-sort-hidden {\n\topacity: 0;\n}*\/\n\n#sched-schedule-8-408296781 .sched-sort .sched-sort-current .sched-sort-current-label {\n\twidth: 100px;\n}\n\n#sched-schedule-8-408296781 .sched-sort.sched-sort-open .sched-sort-dropdown .sched-sort-current .sched-sort-current-label {\n\twidth: 180px;\n}\n\n\/*\n * Custom CSS Event Popup\n *\/\n\n#sched-schedule-8-408296781-popup .sched-popup-description {\n\t\n}\n\n#sched-schedule-8-408296781-popup .sched-popup-description .sched-meta a,\n#sched-schedule-8-408296781-popup .sched-popup-description .sched-popup-description-text a {\n\tcolor: #ff4d00;\n}\n\n#sched-schedule-8-408296781-popup .sched-popup-description .sched-meta,\n#sched-schedule-8-408296781-popup .sched-popup-description .sched-popup-description-text {\n\tcolor: #535353;\n\tbackground: #ffffff;\n}\n\n\/*\n * List\n *\/\n\n#sched-schedule-8-408296781-list .sched-list-title {\n\tcolor: #3f3f3f;\n}\n\n\n\n#sched-schedule-8-408296781-list .sched-list-column-title {\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-8-408296781-list .sched-list-event {\n\tcolor: #ffffff;\n\t\n\t\n}\n\n#sched-schedule-8-408296781-list .sched-list-event:hover {\n\tcolor: #ffffff;\n}\n\n#sched-schedule-8-408296781-list .sched-list-event-description {\n\tcolor: #ffffff;\n}\n\n#sched-schedule-8-408296781-list .sched-list-event-title {\n\t\tfont-weight: bold;\n\t;\n}\n\n\/*\n * Horizontal\n *\/\n\n\n\n#sched-schedule-8-408296781 .sched-h-columns {\n\tmargin-top: 30px;\n}\n\n#sched-schedule-8-408296781 .sched-h-content-columns {\n\t\/*margin-top: 30px;*\/\n}\n\n\n#sched-schedule-8-408296781 .sched-h-columns {\n\twidth: 200px;\n}\n\n#sched-schedule-8-408296781 .sched-h-content {\n\tmargin-left: 200px;\n}\n\n#sched-schedule-8-408296781 .sched-h-column-title {\n\ttext-align: center;\n}\n\n#sched-schedule-8-408296781 .sched-h-column {\n\tbackground: #e8e8e8;\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-8-408296781 .sched-h-row {\n\tbackground-color: #f8f8f8;\n}\n<\/style><\/div>\n\t<div class=\"sched-top\">\n\t\t\t<h2 class=\"sched-title\">Jueves 31 de octubre<\/h2>\n\t\t<div class=\"sched-top-buttons sched-top-buttons-right\">\n\t\t\t\n\t\t\t<\/div><!-- .sched-top-buttons -->\n<\/div><!-- .sched-top -->\t<div class=\"sched-row\">\n\t\t\t\t\t<!-- <div class=\"sched-sidebar\" style=\"width: 90px;\">\n\t\t\t\t<div class=\"sched-time\">\n\t\t\t\t\t<div class=\"sched-time-value\" style=\"padding-bottom: 36px\">11:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">12:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">13:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">14:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">15:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">16:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">17:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">18:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">19:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">20:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">21:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">22:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">23:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">00:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">01:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">02:00<\/div>\t\t\t\t<\/div>\n\t\t\t<\/div> -->\n\t\t\t\t\t\t<div class=\"sched-h-columns\">\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 1\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 2\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 3\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 4\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 5\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tFILMOTECA\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tFUNDACI\u00d3 BANCAIXA\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"sched-h-content\">\n\t\t\t<div class=\"sched-h-content-scroll\">\n\t\t\t\t\t\t\t\t<div class=\"sched-h-content-scroll-time\">\n\t\t\t\t\t<div class=\"sched-h-content-scroll-time-value\" data-i=\"0\" style=\"left: 0px;\">11:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"1\" style=\"left: 100px;\">12:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"2\" style=\"left: 200px;\">13:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"3\" style=\"left: 300px;\">14:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"4\" style=\"left: 400px;\">15:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"5\" style=\"left: 500px;\">16:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"6\" style=\"left: 600px;\">17:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"7\" style=\"left: 700px;\">18:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"8\" style=\"left: 800px;\">19:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"9\" style=\"left: 900px;\">20:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"10\" style=\"left: 1000px;\">21:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"11\" style=\"left: 1100px;\">22:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"12\" style=\"left: 1200px;\">23:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"13\" style=\"left: 1300px;\">00:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"14\" style=\"left: 1400px;\">01:00<\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"sched-h-content-columns\">\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1475px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/amanece-como-puedas-benifotrem\/\" data-onclick=\"link\" data-color=\"#aecb38\" title=\"AMANECE COMO PUEDAS 86&#039;\" data-event-id=\"509\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 500px;\" data-top=\"500\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/amanece-como-puedas-benifotrem\/\"  data-onclick=\"link\" data-color=\"#aecb38\" title=\"AMANECE COMO PUEDAS 86&#039;\" data-event-id=\"509\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 500px\" data-top=\"500\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #aecb38; \" data-event-background-image-url=\"\" data-event-id=\"509\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">AMANECE COMO PUEDAS 86&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"509\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-viudo\/\" data-onclick=\"link\" data-color=\"#128997\" title=\"EL VIUDO 86&#039;\" data-event-id=\"510\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 700px;\" data-top=\"700\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-viudo\/\"  data-onclick=\"link\" data-color=\"#128997\" title=\"EL VIUDO 86&#039;\" data-event-id=\"510\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 700px\" data-top=\"700\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"510\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">EL VIUDO 86&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"510\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-marcha-sobre-roma\/\" data-onclick=\"link\" data-color=\"#128997\" title=\"LA MARCHA HACIA ROMA 94&#039;\" data-event-id=\"511\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 900px;\" data-top=\"900\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-marcha-sobre-roma\/\"  data-onclick=\"link\" data-color=\"#128997\" title=\"LA MARCHA HACIA ROMA 94&#039;\" data-event-id=\"511\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 900px\" data-top=\"900\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"511\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">LA MARCHA HACIA ROMA 94&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"511\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/rufufu-da-el-golpe\/\" data-onclick=\"link\" data-color=\"#128997\" title=\"RUFUF\u00da DA EL GOLPE 100&#039;\" data-event-id=\"512\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"3\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/rufufu-da-el-golpe\/\"  data-onclick=\"link\" data-color=\"#128997\" title=\"RUFUF\u00da DA EL GOLPE 100&#039;\" data-event-id=\"512\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"512\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">RUFUF\u00da DA EL GOLPE 100&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"512\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1475px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-ventana-de-enfrente\/\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"LA VENTANA DE ENFRENTE 106&#039;\" data-event-id=\"516\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 500px;\" data-top=\"500\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-ventana-de-enfrente\/\"  data-onclick=\"link\" data-color=\"#27ae60\" title=\"LA VENTANA DE ENFRENTE 106&#039;\" data-event-id=\"516\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 500px\" data-top=\"500\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #27ae60; \" data-event-background-image-url=\"\" data-event-id=\"516\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">LA VENTANA DE ENFRENTE 106&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"516\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-hada-ignorante\/\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"EL HADA IGNORANTE 106&#039;\" data-event-id=\"517\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 700px;\" data-top=\"700\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-hada-ignorante\/\"  data-onclick=\"link\" data-color=\"#27ae60\" title=\"EL HADA IGNORANTE 106&#039;\" data-event-id=\"517\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 700px\" data-top=\"700\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #27ae60; \" data-event-background-image-url=\"\" data-event-id=\"517\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">EL HADA IGNORANTE 106&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"517\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/seducida-y-abandonada\/\" data-onclick=\"link\" data-color=\"#128997\" title=\"SEDUCIDA Y ABANDONADA 118&#039;\" data-event-id=\"515\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 200px; left: 900px;\" data-top=\"900\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/seducida-y-abandonada\/\"  data-onclick=\"link\" data-color=\"#128997\" title=\"SEDUCIDA Y ABANDONADA 118&#039;\" data-event-id=\"515\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 200px; top: 900px\" data-top=\"900\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"515\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">SEDUCIDA Y ABANDONADA 118&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"515\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/pajaritos-y-pajarracos\/\" data-onclick=\"link\" data-color=\"#128997\" title=\"PAJARITOS Y PAJARRACOS 84&#039;\" data-event-id=\"507\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"3\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/pajaritos-y-pajarracos\/\"  data-onclick=\"link\" data-color=\"#128997\" title=\"PAJARITOS Y PAJARRACOS 84&#039;\" data-event-id=\"507\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"507\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">PAJARITOS Y PAJARRACOS 84&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"507\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/cuerdas\/\" data-onclick=\"link\" data-color=\"#0694d6\" title=\"SESI\u00d3N GOLFA HALLOWEEN: CUERDAS 87&#039;. Con la presencia del director, Jos\u00e9 Luis Montesinos, y el equipo de la pel\u00edcula\" data-event-id=\"519\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 1300px;\" data-top=\"1300\" data-size=\"1\" data-sort-index=\"4\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/cuerdas\/\"  data-onclick=\"link\" data-color=\"#0694d6\" title=\"SESI\u00d3N GOLFA HALLOWEEN: CUERDAS 87&#039;. Con la presencia del director, Jos\u00e9 Luis Montesinos, y el equipo de la pel\u00edcula\" data-event-id=\"519\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 1300px\" data-top=\"1300\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #0694d6; \" data-event-background-image-url=\"\" data-event-id=\"519\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">SESI\u00d3N GOLFA HALLOWEEN: CUERDAS 87&#039;. Con la presencia del director, Jos\u00e9 Luis Montesinos, y el equipo de la pel\u00edcula<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"519\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1475px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/are-you-glad-im-here\/\" data-onclick=\"link\" data-color=\"#fcc312\" title=\"ARE YOU GLAD I&#039;M HERE 85&#039;\" data-event-id=\"521\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 500px;\" data-top=\"500\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/are-you-glad-im-here\/\"  data-onclick=\"link\" data-color=\"#fcc312\" title=\"ARE YOU GLAD I&#039;M HERE 85&#039;\" data-event-id=\"521\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 500px\" data-top=\"500\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fcc312; \" data-event-background-image-url=\"\" data-event-id=\"521\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">ARE YOU GLAD I&#039;M HERE 85&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"521\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/dafne\/\" data-onclick=\"link\" data-color=\"#fcc312\" title=\"DAFNE 94&#039;\" data-event-id=\"522\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 700px;\" data-top=\"700\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/dafne\/\"  data-onclick=\"link\" data-color=\"#fcc312\" title=\"DAFNE 94&#039;\" data-event-id=\"522\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 700px\" data-top=\"700\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fcc312; \" data-event-background-image-url=\"\" data-event-id=\"522\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">DAFNE 94&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"522\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/una-dona-amb-unes-ales-tremendes\/\" data-onclick=\"link\" data-color=\"#fcc312\" title=\"UNA DONA AMB UNES ALES TREMENDES 85&#039; Con la presencia del director, Pedro Rosado, y del equipo de la pel\u00edcula\" data-event-id=\"523\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 900px;\" data-top=\"900\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/una-dona-amb-unes-ales-tremendes\/\"  data-onclick=\"link\" data-color=\"#fcc312\" title=\"UNA DONA AMB UNES ALES TREMENDES 85&#039; Con la presencia del director, Pedro Rosado, y del equipo de la pel\u00edcula\" data-event-id=\"523\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 900px\" data-top=\"900\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fcc312; \" data-event-background-image-url=\"\" data-event-id=\"523\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">UNA DONA AMB UNES ALES TREMENDES 85&#039; Con la presencia del director, Pedro Rosado, y del equipo de la pel\u00edcula<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"523\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/matar-al-rey\/\" data-onclick=\"link\" data-color=\"#fcc312\" title=\"MATAR AL REY 90&#039; Con la presencia del director, Vicente Monson\u00eds, y el equipo de la pel\u00edcula\" data-event-id=\"520\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"3\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/matar-al-rey\/\"  data-onclick=\"link\" data-color=\"#fcc312\" title=\"MATAR AL REY 90&#039; Con la presencia del director, Vicente Monson\u00eds, y el equipo de la pel\u00edcula\" data-event-id=\"520\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fcc312; \" data-event-background-image-url=\"\" data-event-id=\"520\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">MATAR AL REY 90&#039; Con la presencia del director, Vicente Monson\u00eds, y el equipo de la pel\u00edcula<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"520\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1475px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/tengo-algo-que-deciros\/\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"TENGO ALGO QUE DECIROS 112&#039;\" data-event-id=\"518\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 500px;\" data-top=\"500\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/tengo-algo-que-deciros\/\"  data-onclick=\"link\" data-color=\"#27ae60\" title=\"TENGO ALGO QUE DECIROS 112&#039;\" data-event-id=\"518\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 500px\" data-top=\"500\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #27ae60; \" data-event-background-image-url=\"\" data-event-id=\"518\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">TENGO ALGO QUE DECIROS 112&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"518\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/allacciate-le-cinture\/\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"ALLACCIATE LE CINTURE 110&#039;\" data-event-id=\"513\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 700px;\" data-top=\"700\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/allacciate-le-cinture\/\"  data-onclick=\"link\" data-color=\"#27ae60\" title=\"ALLACCIATE LE CINTURE 110&#039;\" data-event-id=\"513\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 700px\" data-top=\"700\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #27ae60; \" data-event-background-image-url=\"\" data-event-id=\"513\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">ALLACCIATE LE CINTURE 110&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"513\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/zero\/\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"ZER\u00d8 94&#039; Con la presencia del director, I\u00f1aki S\u00e1nchez, y el equipo de la pel\u00edcula\" data-event-id=\"525\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 900px;\" data-top=\"900\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/zero\/\"  data-onclick=\"link\" data-color=\"#ff7675\" title=\"ZER\u00d8 94&#039; Con la presencia del director, I\u00f1aki S\u00e1nchez, y el equipo de la pel\u00edcula\" data-event-id=\"525\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 900px\" data-top=\"900\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ff7675; \" data-event-background-image-url=\"\" data-event-id=\"525\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">ZER\u00d8 94&#039; Con la presencia del director, I\u00f1aki S\u00e1nchez, y el equipo de la pel\u00edcula<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"525\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/between-two-seas\/\" data-onclick=\"link\" data-color=\"#ff7675\" title=\"BETWEEN TWO SEAS 87&#039; Con la presencia de la actriz Yara Gobran y del productor Abdulrahman El-Garawany\" data-event-id=\"524\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"3\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/between-two-seas\/\"  data-onclick=\"link\" data-color=\"#ff7675\" title=\"BETWEEN TWO SEAS 87&#039; Con la presencia de la actriz Yara Gobran y del productor Abdulrahman El-Garawany\" data-event-id=\"524\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ff7675; \" data-event-background-image-url=\"\" data-event-id=\"524\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">BETWEEN TWO SEAS 87&#039; Con la presencia de la actriz Yara Gobran y del productor Abdulrahman El-Garawany<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"524\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1475px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/a-day-for-women\/\" data-onclick=\"link\" data-color=\"#d63031\" title=\"A DAY FOR WOMEN 111&#039;\" data-event-id=\"527\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 900px;\" data-top=\"900\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/a-day-for-women\/\"  data-onclick=\"link\" data-color=\"#d63031\" title=\"A DAY FOR WOMEN 111&#039;\" data-event-id=\"527\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 900px\" data-top=\"900\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #d63031; \" data-event-background-image-url=\"\" data-event-id=\"527\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">A DAY FOR WOMEN 111&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"527\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/villa-69\/\" data-onclick=\"link\" data-color=\"#d63031\" title=\"VILLA 69 120&#039;\" data-event-id=\"526\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 200px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/villa-69\/\"  data-onclick=\"link\" data-color=\"#d63031\" title=\"VILLA 69 120&#039;\" data-event-id=\"526\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 200px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #d63031; \" data-event-background-image-url=\"\" data-event-id=\"526\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">VILLA 69 120&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"526\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1475px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/dove-siete-sono-qui\/\" data-onclick=\"link\" data-color=\"#fa983a\" title=\"DOVE SIETE? IO SONO QUI 148&#039;\" data-event-id=\"529\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 250px; left: 700px;\" data-top=\"700\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/dove-siete-sono-qui\/\"  data-onclick=\"link\" data-color=\"#fa983a\" title=\"DOVE SIETE? IO SONO QUI 148&#039;\" data-event-id=\"529\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 250px; top: 700px\" data-top=\"700\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fa983a; \" data-event-background-image-url=\"\" data-event-id=\"529\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">DOVE SIETE? IO SONO QUI 148&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"529\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/francesco\/\" data-onclick=\"link\" data-color=\"#fa983a\" title=\"FRANCESCO 157&#039;\" data-event-id=\"528\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 250px; left: 975px;\" data-top=\"975\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/francesco\/\"  data-onclick=\"link\" data-color=\"#fa983a\" title=\"FRANCESCO 157&#039;\" data-event-id=\"528\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 250px; top: 975px\" data-top=\"975\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fa983a; \" data-event-background-image-url=\"\" data-event-id=\"528\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">FRANCESCO 157&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"528\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1475px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/masterclass-ferzan-ozpetek\/\" data-onclick=\"link\" data-color=\"#833471\" title=\"MASTERCLASS FERZAN OZPETEK\" data-event-id=\"530\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 850px;\" data-top=\"850\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/masterclass-ferzan-ozpetek\/\"  data-onclick=\"link\" data-color=\"#833471\" title=\"MASTERCLASS FERZAN OZPETEK\" data-event-id=\"530\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 850px\" data-top=\"850\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #833471; \" data-event-background-image-url=\"\" data-event-id=\"530\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">MASTERCLASS FERZAN OZPETEK<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"530\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n<\/div><div class=\" sched-list sched-hidden\" id=\"sched-schedule-8-408296781-list\" data-id-schedule=\"sched-schedule-8-408296781\" data-options=\" {&quot;am_pm&quot;:&quot;0&quot;,&quot;sidebar_width&quot;:&quot;90&quot;,&quot;sidebar_position&quot;:&quot;left&quot;,&quot;event_hover_color&quot;:&quot;lighten&quot;,&quot;event_box_text_align&quot;:&quot;center&quot;,&quot;event_box_time&quot;:&quot;0&quot;,&quot;event_hover_text_color&quot;:&quot;#FFFFFF&quot;,&quot;event_hover_background_color&quot;:&quot;#000000&quot;,&quot;event_box_truncate_title&quot;:&quot;0&quot;,&quot;event_tooltip&quot;:&quot;0&quot;,&quot;event_tooltip_title&quot;:&quot;1&quot;,&quot;event_tooltip_time&quot;:&quot;1&quot;,&quot;event_tooltip_description&quot;:&quot;1&quot;,&quot;event_tooltip_width_type&quot;:&quot;event&quot;,&quot;event_tooltip_width&quot;:&quot;150&quot;,&quot;event_tooltip_color_type&quot;:&quot;event&quot;,&quot;event_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;event_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;column_tooltip&quot;:&quot;0&quot;,&quot;column_tooltip_title&quot;:&quot;1&quot;,&quot;column_tooltip_description&quot;:&quot;1&quot;,&quot;column_tooltip_width_type&quot;:&quot;column&quot;,&quot;column_tooltip_width&quot;:&quot;150&quot;,&quot;column_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;column_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;animations&quot;:&quot;1&quot;,&quot;animations_mobile&quot;:&quot;1&quot;,&quot;animations_speed&quot;:&quot;normal&quot;,&quot;animations_css3&quot;:&quot;1&quot;,&quot;tooltips_mobile&quot;:&quot;1&quot;,&quot;editor_bg&quot;:&quot;#F5F5F5&quot;,&quot;animations_editor&quot;:&quot;1&quot;,&quot;popup_max_width&quot;:&quot;560&quot;,&quot;popup_background_color&quot;:&quot;#ffffff&quot;,&quot;popup_text_color&quot;:&quot;#535353&quot;,&quot;popup_link_color&quot;:&quot;#ff4d00&quot;,&quot;autoplay_videos&quot;:&quot;1&quot;,&quot;column_color_bg&quot;:&quot;#e8e8e8&quot;,&quot;column_color_text&quot;:&quot;#3f3f3f&quot;,&quot;column_color_border&quot;:&quot;#ffffff&quot;,&quot;pattern_color_1&quot;:&quot;#ffffff&quot;,&quot;pattern_color_2&quot;:&quot;#e8e8e8&quot;,&quot;pattern_color_3&quot;:&quot;#ffffff&quot;,&quot;title_text_color&quot;:&quot;#3f3f3f&quot;,&quot;sidebar_text_color&quot;:&quot;#3f3f3f&quot;,&quot;event_box_text_color&quot;:&quot;#ffffff&quot;,&quot;title_attr&quot;:&quot;0&quot;,&quot;column_break&quot;:1,&quot;column_break_width&quot;:&quot;120&quot;,&quot;column_break_hide_sidebar&quot;:&quot;0&quot;,&quot;editor_custom_css&quot;:&quot;1&quot;,&quot;column_title&quot;:&quot;1&quot;,&quot;event_box_description_method&quot;:&quot;short&quot;,&quot;editor_quick_tooltips&quot;:&quot;1&quot;,&quot;editor_timepicker_increments&quot;:&quot;15&quot;,&quot;event_box_style&quot;:&quot;1&quot;,&quot;filter_position&quot;:&quot;right&quot;,&quot;filter_multiple&quot;:&quot;1&quot;,&quot;filter_hidden_events&quot;:&quot;hide&quot;,&quot;filter_hidden_events_opacity&quot;:&quot;30&quot;,&quot;filter_dropdown_width&quot;:&quot;100&quot;,&quot;filter_dropdown_hover_width&quot;:&quot;180&quot;,&quot;filter_dropdown_label&quot;:&quot;Secci\\u00f3n&quot;,&quot;filter_dropdown_show_all_label&quot;:&quot;Mostrar todo&quot;,&quot;hashtag_url&quot;:&quot;1&quot;,&quot;hide_popup_for_empty_events&quot;:&quot;1&quot;,&quot;event_box_padding_break&quot;:&quot;200&quot;,&quot;popup_arrows&quot;:&quot;1&quot;,&quot;filter_visible&quot;:&quot;1&quot;,&quot;column_break_action&quot;:&quot;list&quot;,&quot;list_view_column_title_color&quot;:&quot;#3f3f3f&quot;,&quot;list_view_event_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_hover_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_title_bold&quot;:&quot;1&quot;,&quot;list_view_event_bullets&quot;:&quot;2&quot;,&quot;list_view_event_short_description_method&quot;:&quot;short&quot;,&quot;list_view_event_description_color&quot;:&quot;#ffffff&quot;,&quot;list_view_hide_empty_columns&quot;:&quot;1&quot;,&quot;shortcodes_in_descriptions&quot;:&quot;1&quot;,&quot;columns_sticky_header&quot;:&quot;1&quot;,&quot;columns_sticky_header_offset&quot;:&quot;0&quot;,&quot;h_row_height&quot;:&quot;110&quot;,&quot;h_column_width&quot;:&quot;200&quot;,&quot;h_time_indicator&quot;:&quot;1&quot;,&quot;h_time_indicator_height&quot;:30,&quot;h_column_multiline&quot;:&quot;0&quot;,&quot;h_column_title_position&quot;:&quot;middle&quot;,&quot;h_column_title_align&quot;:&quot;center&quot;,&quot;h_break&quot;:&quot;0&quot;,&quot;h_width_break_point&quot;:&quot;200&quot;,&quot;h_bg_color&quot;:&quot;#f8f8f8&quot;,&quot;pdf_type&quot;:&quot;html&quot;,&quot;pdf_enable&quot;:&quot;0&quot;,&quot;pdf_enable_list&quot;:&quot;0&quot;,&quot;pdf_label&quot;:&quot;Download&quot;,&quot;pdf_css&quot;:&quot;&quot;,&quot;upcoming_type&quot;:&quot;current_datetime&quot;,&quot;upcoming_custom&quot;:&quot;2016-01-01 00:00&quot;,&quot;upcoming_limit&quot;:&quot;5&quot;,&quot;upcoming_title&quot;:&quot;timetable_title&quot;,&quot;upcoming_title_custom&quot;:&quot;Upcoming Events&quot;,&quot;upcoming_title_amount&quot;:&quot;1&quot;}\" data-start=\"11:00\" data-end=\"01:45\" data-timetable-id=\"8\" data-type=\"list\" data-layout=\"horizontal\">\t<div class=\"sched-list-top\">\n\t\t<div class=\"sched-list-title\">Jueves 31 de octubre<\/div>\n\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 1<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/amanece-como-puedas-benifotrem\/\" data-event-id=\"509\" style=\"background: #aecb38;\" data-color=\"#aecb38\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #aecb38;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tAMANECE COMO PUEDAS 86&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 17:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-viudo\/\" data-event-id=\"510\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tEL VIUDO 86&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-marcha-sobre-roma\/\" data-event-id=\"511\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tLA MARCHA HACIA ROMA 94&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 21:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/rufufu-da-el-golpe\/\" data-event-id=\"512\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tRUFUF\u00da DA EL GOLPE 100&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 2<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-ventana-de-enfrente\/\" data-event-id=\"516\" style=\"background: #27ae60;\" data-color=\"#27ae60\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #27ae60;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tLA VENTANA DE ENFRENTE 106&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 17:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-hada-ignorante\/\" data-event-id=\"517\" style=\"background: #27ae60;\" data-color=\"#27ae60\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #27ae60;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tEL HADA IGNORANTE 106&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/seducida-y-abandonada\/\" data-event-id=\"515\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tSEDUCIDA Y ABANDONADA 118&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 22:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/pajaritos-y-pajarracos\/\" data-event-id=\"507\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tPAJARITOS Y PAJARRACOS 84&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/cuerdas\/\" data-event-id=\"519\" style=\"background: #0694d6;\" data-color=\"#0694d6\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #0694d6;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tSESI\u00d3N GOLFA HALLOWEEN: CUERDAS 87&#039;. Con la presencia del director, Jos\u00e9 Luis Montesinos, y el equipo de la pel\u00edcula\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">00:00 - 01:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 3<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/are-you-glad-im-here\/\" data-event-id=\"521\" style=\"background: #fcc312;\" data-color=\"#fcc312\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fcc312;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tARE YOU GLAD I&#039;M HERE 85&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 17:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/dafne\/\" data-event-id=\"522\" style=\"background: #fcc312;\" data-color=\"#fcc312\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fcc312;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tDAFNE 94&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/una-dona-amb-unes-ales-tremendes\/\" data-event-id=\"523\" style=\"background: #fcc312;\" data-color=\"#fcc312\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fcc312;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tUNA DONA AMB UNES ALES TREMENDES 85&#039; Con la presencia del director, Pedro Rosado, y del equipo de la pel\u00edcula\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 21:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/matar-al-rey\/\" data-event-id=\"520\" style=\"background: #fcc312;\" data-color=\"#fcc312\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fcc312;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tMATAR AL REY 90&#039; Con la presencia del director, Vicente Monson\u00eds, y el equipo de la pel\u00edcula\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 4<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/tengo-algo-que-deciros\/\" data-event-id=\"518\" style=\"background: #27ae60;\" data-color=\"#27ae60\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #27ae60;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tTENGO ALGO QUE DECIROS 112&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 17:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/allacciate-le-cinture\/\" data-event-id=\"513\" style=\"background: #27ae60;\" data-color=\"#27ae60\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #27ae60;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tALLACCIATE LE CINTURE 110&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/zero\/\" data-event-id=\"525\" style=\"background: #ff7675;\" data-color=\"#ff7675\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ff7675;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tZER\u00d8 94&#039; Con la presencia del director, I\u00f1aki S\u00e1nchez, y el equipo de la pel\u00edcula\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 21:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/between-two-seas\/\" data-event-id=\"524\" style=\"background: #ff7675;\" data-color=\"#ff7675\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ff7675;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tBETWEEN TWO SEAS 87&#039; Con la presencia de la actriz Yara Gobran y del productor Abdulrahman El-Garawany\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 5<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/a-day-for-women\/\" data-event-id=\"527\" style=\"background: #d63031;\" data-color=\"#d63031\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #d63031;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tA DAY FOR WOMEN 111&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 21:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/villa-69\/\" data-event-id=\"526\" style=\"background: #d63031;\" data-color=\"#d63031\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #d63031;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tVILLA 69 120&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">FILMOTECA<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/dove-siete-sono-qui\/\" data-event-id=\"529\" style=\"background: #fa983a;\" data-color=\"#fa983a\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fa983a;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tDOVE SIETE? IO SONO QUI 148&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 20:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/francesco\/\" data-event-id=\"528\" style=\"background: #fa983a;\" data-color=\"#fa983a\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fa983a;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tFRANCESCO 157&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:45 - 23:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">FUNDACI\u00d3 BANCAIXA<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/masterclass-ferzan-ozpetek\/\" data-event-id=\"530\" style=\"background: #833471;\" data-color=\"#833471\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #833471;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tMASTERCLASS FERZAN OZPETEK\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">19:30 - 21:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t<!-- .sched-list-column -->\n\t\n<\/div>[\/vc_column][\/vc_row][vc_row disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1600188416284{padding-right: 40px !important;padding-bottom: 50px !important;padding-left: 40px !important;}&#8221; anchor=&#8221;viernes-1&#8243;][vc_column]<div class=\"sched-loader\"><div class=\"sched-loader-icon\"><\/div><div class=\"sched-loader-text\"><\/div><\/div>\n<div class=\" sched sched-horizontal sched-horizontal-medium\" id=\"sched-schedule-1-1740895996\" data-options=\" {&quot;am_pm&quot;:&quot;0&quot;,&quot;sidebar_width&quot;:&quot;90&quot;,&quot;sidebar_position&quot;:&quot;left&quot;,&quot;event_hover_color&quot;:&quot;lighten&quot;,&quot;event_box_text_align&quot;:&quot;center&quot;,&quot;event_box_time&quot;:&quot;0&quot;,&quot;event_hover_text_color&quot;:&quot;#FFFFFF&quot;,&quot;event_hover_background_color&quot;:&quot;#000000&quot;,&quot;event_box_truncate_title&quot;:&quot;0&quot;,&quot;event_tooltip&quot;:&quot;0&quot;,&quot;event_tooltip_title&quot;:&quot;1&quot;,&quot;event_tooltip_time&quot;:&quot;1&quot;,&quot;event_tooltip_description&quot;:&quot;1&quot;,&quot;event_tooltip_width_type&quot;:&quot;event&quot;,&quot;event_tooltip_width&quot;:&quot;150&quot;,&quot;event_tooltip_color_type&quot;:&quot;event&quot;,&quot;event_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;event_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;column_tooltip&quot;:&quot;0&quot;,&quot;column_tooltip_title&quot;:&quot;1&quot;,&quot;column_tooltip_description&quot;:&quot;1&quot;,&quot;column_tooltip_width_type&quot;:&quot;column&quot;,&quot;column_tooltip_width&quot;:&quot;150&quot;,&quot;column_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;column_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;animations&quot;:&quot;1&quot;,&quot;animations_mobile&quot;:&quot;1&quot;,&quot;animations_speed&quot;:&quot;normal&quot;,&quot;animations_css3&quot;:&quot;1&quot;,&quot;tooltips_mobile&quot;:&quot;1&quot;,&quot;editor_bg&quot;:&quot;#F5F5F5&quot;,&quot;animations_editor&quot;:&quot;1&quot;,&quot;popup_max_width&quot;:&quot;560&quot;,&quot;popup_background_color&quot;:&quot;#ffffff&quot;,&quot;popup_text_color&quot;:&quot;#535353&quot;,&quot;popup_link_color&quot;:&quot;#ff4d00&quot;,&quot;autoplay_videos&quot;:&quot;1&quot;,&quot;column_color_bg&quot;:&quot;#e8e8e8&quot;,&quot;column_color_text&quot;:&quot;#3f3f3f&quot;,&quot;column_color_border&quot;:&quot;#ffffff&quot;,&quot;pattern_color_1&quot;:&quot;#ffffff&quot;,&quot;pattern_color_2&quot;:&quot;#e8e8e8&quot;,&quot;pattern_color_3&quot;:&quot;#ffffff&quot;,&quot;title_text_color&quot;:&quot;#3f3f3f&quot;,&quot;sidebar_text_color&quot;:&quot;#3f3f3f&quot;,&quot;event_box_text_color&quot;:&quot;#ffffff&quot;,&quot;title_attr&quot;:&quot;0&quot;,&quot;column_break&quot;:1,&quot;column_break_width&quot;:&quot;120&quot;,&quot;column_break_hide_sidebar&quot;:&quot;0&quot;,&quot;editor_custom_css&quot;:&quot;1&quot;,&quot;column_title&quot;:&quot;1&quot;,&quot;event_box_description_method&quot;:&quot;short&quot;,&quot;editor_quick_tooltips&quot;:&quot;1&quot;,&quot;editor_timepicker_increments&quot;:&quot;15&quot;,&quot;event_box_style&quot;:&quot;1&quot;,&quot;filter_position&quot;:&quot;right&quot;,&quot;filter_multiple&quot;:&quot;1&quot;,&quot;filter_hidden_events&quot;:&quot;hide&quot;,&quot;filter_hidden_events_opacity&quot;:&quot;30&quot;,&quot;filter_dropdown_width&quot;:&quot;100&quot;,&quot;filter_dropdown_hover_width&quot;:&quot;180&quot;,&quot;filter_dropdown_label&quot;:&quot;Secci\\u00f3n&quot;,&quot;filter_dropdown_show_all_label&quot;:&quot;Mostrar todo&quot;,&quot;hashtag_url&quot;:&quot;1&quot;,&quot;hide_popup_for_empty_events&quot;:&quot;1&quot;,&quot;event_box_padding_break&quot;:&quot;200&quot;,&quot;popup_arrows&quot;:&quot;1&quot;,&quot;filter_visible&quot;:&quot;1&quot;,&quot;column_break_action&quot;:&quot;list&quot;,&quot;list_view_column_title_color&quot;:&quot;#3f3f3f&quot;,&quot;list_view_event_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_hover_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_title_bold&quot;:&quot;1&quot;,&quot;list_view_event_bullets&quot;:&quot;2&quot;,&quot;list_view_event_short_description_method&quot;:&quot;short&quot;,&quot;list_view_event_description_color&quot;:&quot;#ffffff&quot;,&quot;list_view_hide_empty_columns&quot;:&quot;1&quot;,&quot;shortcodes_in_descriptions&quot;:&quot;1&quot;,&quot;columns_sticky_header&quot;:&quot;1&quot;,&quot;columns_sticky_header_offset&quot;:&quot;0&quot;,&quot;h_row_height&quot;:&quot;110&quot;,&quot;h_column_width&quot;:&quot;200&quot;,&quot;h_time_indicator&quot;:&quot;1&quot;,&quot;h_time_indicator_height&quot;:30,&quot;h_column_multiline&quot;:&quot;0&quot;,&quot;h_column_title_position&quot;:&quot;middle&quot;,&quot;h_column_title_align&quot;:&quot;center&quot;,&quot;h_break&quot;:&quot;0&quot;,&quot;h_width_break_point&quot;:&quot;200&quot;,&quot;h_bg_color&quot;:&quot;#f8f8f8&quot;,&quot;pdf_type&quot;:&quot;html&quot;,&quot;pdf_enable&quot;:&quot;0&quot;,&quot;pdf_enable_list&quot;:&quot;0&quot;,&quot;pdf_label&quot;:&quot;Download&quot;,&quot;pdf_css&quot;:&quot;&quot;,&quot;upcoming_type&quot;:&quot;current_datetime&quot;,&quot;upcoming_custom&quot;:&quot;2016-01-01 00:00&quot;,&quot;upcoming_limit&quot;:&quot;5&quot;,&quot;upcoming_title&quot;:&quot;timetable_title&quot;,&quot;upcoming_title_custom&quot;:&quot;Upcoming Events&quot;,&quot;upcoming_title_amount&quot;:&quot;1&quot;}\" data-start=\"11:00\" data-end=\"01:30\" data-timetable-id=\"1\" data-type=\"full\" data-list-id=\"#sched-schedule-1-1740895996-list\" data-layout=\"horizontal\">\t<div class=\"sched-style\"><style type=\"text\/css\">\/*\n * Custom CSS For Timetable\n*\/\n\n#sched-schedule-1-1740895996 .sched-column-header,\n#sched-schedule-1-1740895996 .sched-column-header-sticky {\n\tbackground: #e8e8e8;\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-1-1740895996 .sched-column-header:after,\n#sched-schedule-1-1740895996 .sched-column-header-sticky:after {\n\tbackground: #ffffff;\n}\n\n#sched-schedule-1-1740895996 .sched-columns .sched-column:last-child .sched-column-header:after,\n#sched-schedule-1-1740895996 .sched-columns .sched-column:last-child .sched-column-header-sticky:after {\n\tbackground: #e8e8e8;\n}\n\n#sched-schedule-1-1740895996 .sched-column-bg-block {\n\tbackground: #ffffff;\n\tborder-color: #e8e8e8;\n}\n\n#sched-schedule-1-1740895996 .sched-column-bg-block:after {\n\tbackground: #ffffff;\n}\n\n#sched-schedule-1-1740895996 .sched-row-no-title .sched-column .sched-column-bg {\n\tbox-shadow: 0 -1px 0 #e8e8e8;\n}\n\n#sched-schedule-1-1740895996 .sched-title {\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-1-1740895996 .sched-time-value {\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-1-1740895996 .sched-event .sched-event-inner {\n\tcolor: #ffffff;\n\ttext-align: center;\n}\n\n#sched-schedule-1-1740895996 .sched-event.sched-event-invert .sched-event-inner {\n\t<!-- background: #999; -->\n}\n\n\n\n\/*#sched-schedule-1-1740895996 a.sched-event.sched-event-sort-hidden {\n\topacity: 0;\n}*\/\n\n#sched-schedule-1-1740895996 .sched-sort .sched-sort-current .sched-sort-current-label {\n\twidth: 100px;\n}\n\n#sched-schedule-1-1740895996 .sched-sort.sched-sort-open .sched-sort-dropdown .sched-sort-current .sched-sort-current-label {\n\twidth: 180px;\n}\n\n\/*\n * Custom CSS Event Popup\n *\/\n\n#sched-schedule-1-1740895996-popup .sched-popup-description {\n\t\n}\n\n#sched-schedule-1-1740895996-popup .sched-popup-description .sched-meta a,\n#sched-schedule-1-1740895996-popup .sched-popup-description .sched-popup-description-text a {\n\tcolor: #ff4d00;\n}\n\n#sched-schedule-1-1740895996-popup .sched-popup-description .sched-meta,\n#sched-schedule-1-1740895996-popup .sched-popup-description .sched-popup-description-text {\n\tcolor: #535353;\n\tbackground: #ffffff;\n}\n\n\/*\n * List\n *\/\n\n#sched-schedule-1-1740895996-list .sched-list-title {\n\tcolor: #3f3f3f;\n}\n\n\n\n#sched-schedule-1-1740895996-list .sched-list-column-title {\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-1-1740895996-list .sched-list-event {\n\tcolor: #ffffff;\n\t\n\t\n}\n\n#sched-schedule-1-1740895996-list .sched-list-event:hover {\n\tcolor: #ffffff;\n}\n\n#sched-schedule-1-1740895996-list .sched-list-event-description {\n\tcolor: #ffffff;\n}\n\n#sched-schedule-1-1740895996-list .sched-list-event-title {\n\t\tfont-weight: bold;\n\t;\n}\n\n\/*\n * Horizontal\n *\/\n\n\n\n#sched-schedule-1-1740895996 .sched-h-columns {\n\tmargin-top: 30px;\n}\n\n#sched-schedule-1-1740895996 .sched-h-content-columns {\n\t\/*margin-top: 30px;*\/\n}\n\n\n#sched-schedule-1-1740895996 .sched-h-columns {\n\twidth: 200px;\n}\n\n#sched-schedule-1-1740895996 .sched-h-content {\n\tmargin-left: 200px;\n}\n\n#sched-schedule-1-1740895996 .sched-h-column-title {\n\ttext-align: center;\n}\n\n#sched-schedule-1-1740895996 .sched-h-column {\n\tbackground: #e8e8e8;\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-1-1740895996 .sched-h-row {\n\tbackground-color: #f8f8f8;\n}\n<\/style><\/div>\n\t<div class=\"sched-top\">\n\t\t\t<h2 class=\"sched-title\">Viernes 1 de noviembre<\/h2>\n\t\t<div class=\"sched-top-buttons sched-top-buttons-right\">\n\t\t\t\n\t\t\t<\/div><!-- .sched-top-buttons -->\n<\/div><!-- .sched-top -->\t<div class=\"sched-row\">\n\t\t\t\t\t<!-- <div class=\"sched-sidebar\" style=\"width: 90px;\">\n\t\t\t\t<div class=\"sched-time\">\n\t\t\t\t\t<div class=\"sched-time-value\" style=\"padding-bottom: 36px\">11:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">12:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">13:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">14:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">15:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">16:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">17:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">18:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">19:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">20:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">21:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">22:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">23:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">00:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">01:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">02:00<\/div>\t\t\t\t<\/div>\n\t\t\t<\/div> -->\n\t\t\t\t\t\t<div class=\"sched-h-columns\">\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 1\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 2\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 3\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 4\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 5\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tFILMOTECA\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tOTROS ESPACIOS\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"sched-h-content\">\n\t\t\t<div class=\"sched-h-content-scroll\">\n\t\t\t\t\t\t\t\t<div class=\"sched-h-content-scroll-time\">\n\t\t\t\t\t<div class=\"sched-h-content-scroll-time-value\" data-i=\"0\" style=\"left: 0px;\">11:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"1\" style=\"left: 100px;\">12:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"2\" style=\"left: 200px;\">13:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"3\" style=\"left: 300px;\">14:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"4\" style=\"left: 400px;\">15:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"5\" style=\"left: 500px;\">16:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"6\" style=\"left: 600px;\">17:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"7\" style=\"left: 700px;\">18:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"8\" style=\"left: 800px;\">19:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"9\" style=\"left: 900px;\">20:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"10\" style=\"left: 1000px;\">21:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"11\" style=\"left: 1100px;\">22:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"12\" style=\"left: 1200px;\">23:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"13\" style=\"left: 1300px;\">00:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"14\" style=\"left: 1400px;\">01:00<\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"sched-h-content-columns\">\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/rufufu-da-el-golpe\/\" data-onclick=\"link\" data-color=\"#128997\" title=\"RUFUF\u00da DA EL GOLPE 100&#039;\" data-event-id=\"537\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 500px;\" data-top=\"500\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/rufufu-da-el-golpe\/\"  data-onclick=\"link\" data-color=\"#128997\" title=\"RUFUF\u00da DA EL GOLPE 100&#039;\" data-event-id=\"537\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 500px\" data-top=\"500\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"537\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">RUFUF\u00da DA EL GOLPE 100&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"537\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/amanece-como-puedas-benifotrem\/\" data-onclick=\"link\" data-color=\"#a3cb38\" title=\"AMANECE COMO PUEDAS 86&#039;\" data-event-id=\"532\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 700px;\" data-top=\"700\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/amanece-como-puedas-benifotrem\/\"  data-onclick=\"link\" data-color=\"#a3cb38\" title=\"AMANECE COMO PUEDAS 86&#039;\" data-event-id=\"532\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 700px\" data-top=\"700\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #a3cb38; \" data-event-background-image-url=\"\" data-event-id=\"532\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">AMANECE COMO PUEDAS 86&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"532\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/gli-anni-ruggenti\/\" data-onclick=\"link\" data-color=\"#128997\" title=\"GLI ANNI RUGGENTI 106&#039;\" data-event-id=\"534\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 900px;\" data-top=\"900\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/gli-anni-ruggenti\/\"  data-onclick=\"link\" data-color=\"#128997\" title=\"GLI ANNI RUGGENTI 106&#039;\" data-event-id=\"534\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 900px\" data-top=\"900\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"534\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">GLI ANNI RUGGENTI 106&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"534\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-marcha-sobre-roma\/\" data-onclick=\"link\" data-color=\"#128997\" title=\"LA MARCHA SOBRE ROMA 94&#039;\" data-event-id=\"531\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"3\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-marcha-sobre-roma\/\"  data-onclick=\"link\" data-color=\"#128997\" title=\"LA MARCHA SOBRE ROMA 94&#039;\" data-event-id=\"531\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"531\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">LA MARCHA SOBRE ROMA 94&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"531\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-escapada\/\" data-onclick=\"link\" data-color=\"#128997\" title=\"LA ESCAPADA 105&#039;\" data-event-id=\"535\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 700px;\" data-top=\"700\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-escapada\/\"  data-onclick=\"link\" data-color=\"#128997\" title=\"LA ESCAPADA 105&#039;\" data-event-id=\"535\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 700px\" data-top=\"700\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"535\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">LA ESCAPADA 105&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"535\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/pajaritos-y-pajarracos\/\" data-onclick=\"link\" data-color=\"#128997\" title=\"PAJARITOS Y PAJARRACOS 84&#039;\" data-event-id=\"536\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 900px;\" data-top=\"900\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/pajaritos-y-pajarracos\/\"  data-onclick=\"link\" data-color=\"#128997\" title=\"PAJARITOS Y PAJARRACOS 84&#039;\" data-event-id=\"536\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 900px\" data-top=\"900\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"536\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">PAJARITOS Y PAJARRACOS 84&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"536\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/seducida-y-abandonada\/\" data-onclick=\"link\" data-color=\"#128997\" title=\"SEDUCIDA Y ABANDONADA 118&#039;\" data-event-id=\"533\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 200px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/seducida-y-abandonada\/\"  data-onclick=\"link\" data-color=\"#128997\" title=\"SEDUCIDA Y ABANDONADA 118&#039;\" data-event-id=\"533\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 200px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #128997; \" data-event-background-image-url=\"\" data-event-id=\"533\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">SEDUCIDA Y ABANDONADA 118&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"533\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/diamond-dust-2\/\" data-onclick=\"link\" data-color=\"#ffc312\" title=\"DIAMOND DUST 162&#039;\" data-event-id=\"539\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 275px; left: 500px;\" data-top=\"500\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/diamond-dust-2\/\"  data-onclick=\"link\" data-color=\"#ffc312\" title=\"DIAMOND DUST 162&#039;\" data-event-id=\"539\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 275px; top: 500px\" data-top=\"500\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ffc312; \" data-event-background-image-url=\"\" data-event-id=\"539\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">DIAMOND DUST 162&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"539\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/mar\/\" data-onclick=\"link\" data-color=\"#ffc312\" title=\"MAR 103&#039;\" data-event-id=\"540\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 900px;\" data-top=\"900\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/mar\/\"  data-onclick=\"link\" data-color=\"#ffc312\" title=\"MAR 103&#039;\" data-event-id=\"540\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 900px\" data-top=\"900\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ffc312; \" data-event-background-image-url=\"\" data-event-id=\"540\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">MAR 103&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"540\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/head-above-water\/\" data-onclick=\"link\" data-color=\"#ffc312\" title=\"HEAD ABOVE WATER 85&#039;\" data-event-id=\"538\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/head-above-water\/\"  data-onclick=\"link\" data-color=\"#ffc312\" title=\"HEAD ABOVE WATER 85&#039;\" data-event-id=\"538\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ffc312; \" data-event-background-image-url=\"\" data-event-id=\"538\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">HEAD ABOVE WATER 85&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"538\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/istanbul-kirmizisi\/\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"ISTAMBUL KIRMIZISI 110&#039;\" data-event-id=\"542\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 500px;\" data-top=\"500\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/istanbul-kirmizisi\/\"  data-onclick=\"link\" data-color=\"#27ae60\" title=\"ISTAMBUL KIRMIZISI 110&#039;\" data-event-id=\"542\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 500px\" data-top=\"500\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #27ae60; \" data-event-background-image-url=\"\" data-event-id=\"542\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">ISTAMBUL KIRMIZISI 110&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"542\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/un-giorno-perfetto\/\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"UN GIORNO PERFETTO 105&#039;\" data-event-id=\"543\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 700px;\" data-top=\"700\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/un-giorno-perfetto\/\"  data-onclick=\"link\" data-color=\"#27ae60\" title=\"UN GIORNO PERFETTO 105&#039;\" data-event-id=\"543\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 700px\" data-top=\"700\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #27ae60; \" data-event-background-image-url=\"\" data-event-id=\"543\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">UN GIORNO PERFETTO 105&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"543\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/tengo-algo-que-deciros\/\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"TENGO ALGO QUE DECIROS 112&#039;\" data-event-id=\"544\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 900px;\" data-top=\"900\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/tengo-algo-que-deciros\/\"  data-onclick=\"link\" data-color=\"#27ae60\" title=\"TENGO ALGO QUE DECIROS 112&#039;\" data-event-id=\"544\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 900px\" data-top=\"900\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #27ae60; \" data-event-background-image-url=\"\" data-event-id=\"544\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">TENGO ALGO QUE DECIROS 112&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"544\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/cuore-sacro\/\" data-onclick=\"link\" data-color=\"#27ae60\" title=\"CUORE SACRO 117&#039;\" data-event-id=\"541\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 200px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"3\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/cuore-sacro\/\"  data-onclick=\"link\" data-color=\"#27ae60\" title=\"CUORE SACRO 117&#039;\" data-event-id=\"541\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 200px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #27ae60; \" data-event-background-image-url=\"\" data-event-id=\"541\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">CUORE SACRO 117&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"541\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/hurlements-en-faveur-de-sade\/\" data-onclick=\"link\" data-color=\"#9980fa\" title=\"HURLEMENT EN FAVEUR DE SADE 63&#039;\" data-event-id=\"546\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 125px; left: 500px;\" data-top=\"500\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/hurlements-en-faveur-de-sade\/\"  data-onclick=\"link\" data-color=\"#9980fa\" title=\"HURLEMENT EN FAVEUR DE SADE 63&#039;\" data-event-id=\"546\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 125px; top: 500px\" data-top=\"500\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #9980fa; \" data-event-background-image-url=\"\" data-event-id=\"546\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">HURLEMENT EN FAVEUR DE SADE 63&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"546\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/in-girum-imus-nocte-et-consumimur-igni\/\" data-onclick=\"link\" data-color=\"#9980fa\" title=\"IN GIRUM IMUS NOCTE ET CONSUMIMUR IGNI 95&#039;\" data-event-id=\"547\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 150px; left: 700px;\" data-top=\"700\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/in-girum-imus-nocte-et-consumimur-igni\/\"  data-onclick=\"link\" data-color=\"#9980fa\" title=\"IN GIRUM IMUS NOCTE ET CONSUMIMUR IGNI 95&#039;\" data-event-id=\"547\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 150px; top: 700px\" data-top=\"700\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #9980fa; \" data-event-background-image-url=\"\" data-event-id=\"547\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">IN GIRUM IMUS NOCTE ET CONSUMIMUR IGNI 95&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"547\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/women-who-loved-cinema\/\" data-onclick=\"link\" data-color=\"#d63031\" title=\"WOMEN WHO LOVED CINEMA 120&#039;\" data-event-id=\"545\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 200px; left: 900px;\" data-top=\"900\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/women-who-loved-cinema\/\"  data-onclick=\"link\" data-color=\"#d63031\" title=\"WOMEN WHO LOVED CINEMA 120&#039;\" data-event-id=\"545\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 200px; top: 900px\" data-top=\"900\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #d63031; \" data-event-background-image-url=\"\" data-event-id=\"545\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">WOMEN WHO LOVED CINEMA 120&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"545\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/ospite\/\" data-onclick=\"link\" data-color=\"#fa983a\" title=\"L&#039;OSPITE 101&#039;\" data-event-id=\"549\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 700px;\" data-top=\"700\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/ospite\/\"  data-onclick=\"link\" data-color=\"#fa983a\" title=\"L&#039;OSPITE 101&#039;\" data-event-id=\"549\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 700px\" data-top=\"700\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fa983a; \" data-event-background-image-url=\"\" data-event-id=\"549\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">L&#039;OSPITE 101&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"549\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/detras-de-la-puerta\/\" data-onclick=\"link\" data-color=\"#fa983a\" title=\"DETR\u00c1S DE LA PUERTA 110&#039;\" data-event-id=\"550\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 925px;\" data-top=\"925\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/detras-de-la-puerta\/\"  data-onclick=\"link\" data-color=\"#fa983a\" title=\"DETR\u00c1S DE LA PUERTA 110&#039;\" data-event-id=\"550\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 925px\" data-top=\"925\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fa983a; \" data-event-background-image-url=\"\" data-event-id=\"550\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">DETR\u00c1S DE LA PUERTA 110&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"550\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-juego-de-ripley\/\" data-onclick=\"link\" data-color=\"#fa983a\" title=\"EL JUEGO DE RIPLEY 110&#039;\" data-event-id=\"548\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-juego-de-ripley\/\"  data-onclick=\"link\" data-color=\"#fa983a\" title=\"EL JUEGO DE RIPLEY 110&#039;\" data-event-id=\"548\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fa983a; \" data-event-background-image-url=\"\" data-event-id=\"548\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">EL JUEGO DE RIPLEY 110&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"548\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/poetas-del-cielo\/\" data-onclick=\"link\" data-color=\"#12cbc4\" title=\"CLAUSURA. POETAS DEL CIELO. 102&#039; TEATRO PRINCIPAL. Con la presencia de Carlos de Miguel (director de fotograf\u00eda) y Octavio Iturbe (montador)\" data-event-id=\"551\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 225px; left: 800px;\" data-top=\"800\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/poetas-del-cielo\/\"  data-onclick=\"link\" data-color=\"#12cbc4\" title=\"CLAUSURA. POETAS DEL CIELO. 102&#039; TEATRO PRINCIPAL. Con la presencia de Carlos de Miguel (director de fotograf\u00eda) y Octavio Iturbe (montador)\" data-event-id=\"551\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 225px; top: 800px\" data-top=\"800\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #12cbc4; \" data-event-background-image-url=\"\" data-event-id=\"551\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">CLAUSURA. POETAS DEL CIELO. 102&#039; TEATRO PRINCIPAL. Con la presencia de Carlos de Miguel (director de fotograf\u00eda) y Octavio Iturbe (montador)<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"551\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n<\/div><div class=\" sched-list sched-hidden\" id=\"sched-schedule-1-1740895996-list\" data-id-schedule=\"sched-schedule-1-1740895996\" data-options=\" {&quot;am_pm&quot;:&quot;0&quot;,&quot;sidebar_width&quot;:&quot;90&quot;,&quot;sidebar_position&quot;:&quot;left&quot;,&quot;event_hover_color&quot;:&quot;lighten&quot;,&quot;event_box_text_align&quot;:&quot;center&quot;,&quot;event_box_time&quot;:&quot;0&quot;,&quot;event_hover_text_color&quot;:&quot;#FFFFFF&quot;,&quot;event_hover_background_color&quot;:&quot;#000000&quot;,&quot;event_box_truncate_title&quot;:&quot;0&quot;,&quot;event_tooltip&quot;:&quot;0&quot;,&quot;event_tooltip_title&quot;:&quot;1&quot;,&quot;event_tooltip_time&quot;:&quot;1&quot;,&quot;event_tooltip_description&quot;:&quot;1&quot;,&quot;event_tooltip_width_type&quot;:&quot;event&quot;,&quot;event_tooltip_width&quot;:&quot;150&quot;,&quot;event_tooltip_color_type&quot;:&quot;event&quot;,&quot;event_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;event_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;column_tooltip&quot;:&quot;0&quot;,&quot;column_tooltip_title&quot;:&quot;1&quot;,&quot;column_tooltip_description&quot;:&quot;1&quot;,&quot;column_tooltip_width_type&quot;:&quot;column&quot;,&quot;column_tooltip_width&quot;:&quot;150&quot;,&quot;column_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;column_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;animations&quot;:&quot;1&quot;,&quot;animations_mobile&quot;:&quot;1&quot;,&quot;animations_speed&quot;:&quot;normal&quot;,&quot;animations_css3&quot;:&quot;1&quot;,&quot;tooltips_mobile&quot;:&quot;1&quot;,&quot;editor_bg&quot;:&quot;#F5F5F5&quot;,&quot;animations_editor&quot;:&quot;1&quot;,&quot;popup_max_width&quot;:&quot;560&quot;,&quot;popup_background_color&quot;:&quot;#ffffff&quot;,&quot;popup_text_color&quot;:&quot;#535353&quot;,&quot;popup_link_color&quot;:&quot;#ff4d00&quot;,&quot;autoplay_videos&quot;:&quot;1&quot;,&quot;column_color_bg&quot;:&quot;#e8e8e8&quot;,&quot;column_color_text&quot;:&quot;#3f3f3f&quot;,&quot;column_color_border&quot;:&quot;#ffffff&quot;,&quot;pattern_color_1&quot;:&quot;#ffffff&quot;,&quot;pattern_color_2&quot;:&quot;#e8e8e8&quot;,&quot;pattern_color_3&quot;:&quot;#ffffff&quot;,&quot;title_text_color&quot;:&quot;#3f3f3f&quot;,&quot;sidebar_text_color&quot;:&quot;#3f3f3f&quot;,&quot;event_box_text_color&quot;:&quot;#ffffff&quot;,&quot;title_attr&quot;:&quot;0&quot;,&quot;column_break&quot;:1,&quot;column_break_width&quot;:&quot;120&quot;,&quot;column_break_hide_sidebar&quot;:&quot;0&quot;,&quot;editor_custom_css&quot;:&quot;1&quot;,&quot;column_title&quot;:&quot;1&quot;,&quot;event_box_description_method&quot;:&quot;short&quot;,&quot;editor_quick_tooltips&quot;:&quot;1&quot;,&quot;editor_timepicker_increments&quot;:&quot;15&quot;,&quot;event_box_style&quot;:&quot;1&quot;,&quot;filter_position&quot;:&quot;right&quot;,&quot;filter_multiple&quot;:&quot;1&quot;,&quot;filter_hidden_events&quot;:&quot;hide&quot;,&quot;filter_hidden_events_opacity&quot;:&quot;30&quot;,&quot;filter_dropdown_width&quot;:&quot;100&quot;,&quot;filter_dropdown_hover_width&quot;:&quot;180&quot;,&quot;filter_dropdown_label&quot;:&quot;Secci\\u00f3n&quot;,&quot;filter_dropdown_show_all_label&quot;:&quot;Mostrar todo&quot;,&quot;hashtag_url&quot;:&quot;1&quot;,&quot;hide_popup_for_empty_events&quot;:&quot;1&quot;,&quot;event_box_padding_break&quot;:&quot;200&quot;,&quot;popup_arrows&quot;:&quot;1&quot;,&quot;filter_visible&quot;:&quot;1&quot;,&quot;column_break_action&quot;:&quot;list&quot;,&quot;list_view_column_title_color&quot;:&quot;#3f3f3f&quot;,&quot;list_view_event_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_hover_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_title_bold&quot;:&quot;1&quot;,&quot;list_view_event_bullets&quot;:&quot;2&quot;,&quot;list_view_event_short_description_method&quot;:&quot;short&quot;,&quot;list_view_event_description_color&quot;:&quot;#ffffff&quot;,&quot;list_view_hide_empty_columns&quot;:&quot;1&quot;,&quot;shortcodes_in_descriptions&quot;:&quot;1&quot;,&quot;columns_sticky_header&quot;:&quot;1&quot;,&quot;columns_sticky_header_offset&quot;:&quot;0&quot;,&quot;h_row_height&quot;:&quot;110&quot;,&quot;h_column_width&quot;:&quot;200&quot;,&quot;h_time_indicator&quot;:&quot;1&quot;,&quot;h_time_indicator_height&quot;:30,&quot;h_column_multiline&quot;:&quot;0&quot;,&quot;h_column_title_position&quot;:&quot;middle&quot;,&quot;h_column_title_align&quot;:&quot;center&quot;,&quot;h_break&quot;:&quot;0&quot;,&quot;h_width_break_point&quot;:&quot;200&quot;,&quot;h_bg_color&quot;:&quot;#f8f8f8&quot;,&quot;pdf_type&quot;:&quot;html&quot;,&quot;pdf_enable&quot;:&quot;0&quot;,&quot;pdf_enable_list&quot;:&quot;0&quot;,&quot;pdf_label&quot;:&quot;Download&quot;,&quot;pdf_css&quot;:&quot;&quot;,&quot;upcoming_type&quot;:&quot;current_datetime&quot;,&quot;upcoming_custom&quot;:&quot;2016-01-01 00:00&quot;,&quot;upcoming_limit&quot;:&quot;5&quot;,&quot;upcoming_title&quot;:&quot;timetable_title&quot;,&quot;upcoming_title_custom&quot;:&quot;Upcoming Events&quot;,&quot;upcoming_title_amount&quot;:&quot;1&quot;}\" data-start=\"11:00\" data-end=\"01:30\" data-timetable-id=\"1\" data-type=\"list\" data-layout=\"horizontal\">\t<div class=\"sched-list-top\">\n\t\t<div class=\"sched-list-title\">Viernes 1 de noviembre<\/div>\n\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 1<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/rufufu-da-el-golpe\/\" data-event-id=\"537\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tRUFUF\u00da DA EL GOLPE 100&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 17:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/amanece-como-puedas-benifotrem\/\" data-event-id=\"532\" style=\"background: #a3cb38;\" data-color=\"#a3cb38\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #a3cb38;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tAMANECE COMO PUEDAS 86&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/gli-anni-ruggenti\/\" data-event-id=\"534\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tGLI ANNI RUGGENTI 106&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 21:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-marcha-sobre-roma\/\" data-event-id=\"531\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tLA MARCHA SOBRE ROMA 94&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 2<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-escapada\/\" data-event-id=\"535\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tLA ESCAPADA 105&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/pajaritos-y-pajarracos\/\" data-event-id=\"536\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tPAJARITOS Y PAJARRACOS 84&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 21:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/seducida-y-abandonada\/\" data-event-id=\"533\" style=\"background: #128997;\" data-color=\"#128997\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #128997;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tSEDUCIDA Y ABANDONADA 118&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 3<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/diamond-dust-2\/\" data-event-id=\"539\" style=\"background: #ffc312;\" data-color=\"#ffc312\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ffc312;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tDIAMOND DUST 162&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 18:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/mar\/\" data-event-id=\"540\" style=\"background: #ffc312;\" data-color=\"#ffc312\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ffc312;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tMAR 103&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 21:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/head-above-water\/\" data-event-id=\"538\" style=\"background: #ffc312;\" data-color=\"#ffc312\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ffc312;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tHEAD ABOVE WATER 85&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 4<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/istanbul-kirmizisi\/\" data-event-id=\"542\" style=\"background: #27ae60;\" data-color=\"#27ae60\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #27ae60;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tISTAMBUL KIRMIZISI 110&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 17:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/un-giorno-perfetto\/\" data-event-id=\"543\" style=\"background: #27ae60;\" data-color=\"#27ae60\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #27ae60;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tUN GIORNO PERFETTO 105&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/tengo-algo-que-deciros\/\" data-event-id=\"544\" style=\"background: #27ae60;\" data-color=\"#27ae60\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #27ae60;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tTENGO ALGO QUE DECIROS 112&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 21:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/cuore-sacro\/\" data-event-id=\"541\" style=\"background: #27ae60;\" data-color=\"#27ae60\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #27ae60;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tCUORE SACRO 117&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 5<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/hurlements-en-faveur-de-sade\/\" data-event-id=\"546\" style=\"background: #9980fa;\" data-color=\"#9980fa\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #9980fa;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tHURLEMENT EN FAVEUR DE SADE 63&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">16:00 - 17:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/in-girum-imus-nocte-et-consumimur-igni\/\" data-event-id=\"547\" style=\"background: #9980fa;\" data-color=\"#9980fa\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #9980fa;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tIN GIRUM IMUS NOCTE ET CONSUMIMUR IGNI 95&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/women-who-loved-cinema\/\" data-event-id=\"545\" style=\"background: #d63031;\" data-color=\"#d63031\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #d63031;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tWOMEN WHO LOVED CINEMA 120&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 22:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">FILMOTECA<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/ospite\/\" data-event-id=\"549\" style=\"background: #fa983a;\" data-color=\"#fa983a\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fa983a;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tL&#039;OSPITE 101&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/detras-de-la-puerta\/\" data-event-id=\"550\" style=\"background: #fa983a;\" data-color=\"#fa983a\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fa983a;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tDETR\u00c1S DE LA PUERTA 110&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:15 - 22:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-juego-de-ripley\/\" data-event-id=\"548\" style=\"background: #fa983a;\" data-color=\"#fa983a\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fa983a;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tEL JUEGO DE RIPLEY 110&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">OTROS ESPACIOS<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/poetas-del-cielo\/\" data-event-id=\"551\" style=\"background: #12cbc4;\" data-color=\"#12cbc4\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #12cbc4;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tCLAUSURA. POETAS DEL CIELO. 102&#039; TEATRO PRINCIPAL. Con la presencia de Carlos de Miguel (director de fotograf\u00eda) y Octavio Iturbe (montador)\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">19:00 - 21:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t<!-- .sched-list-column -->\n\t\n<\/div>[\/vc_column][\/vc_row][vc_row disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1600188422574{padding-right: 40px !important;padding-bottom: 50px !important;padding-left: 40px !important;}&#8221; anchor=&#8221;sabado-2&#8243;][vc_column]<div class=\"sched-loader\"><div class=\"sched-loader-icon\"><\/div><div class=\"sched-loader-text\"><\/div><\/div>\n<div class=\" sched sched-horizontal sched-horizontal-medium\" id=\"sched-schedule-3-1621949079\" data-options=\" {&quot;am_pm&quot;:&quot;0&quot;,&quot;sidebar_width&quot;:&quot;90&quot;,&quot;sidebar_position&quot;:&quot;left&quot;,&quot;event_hover_color&quot;:&quot;lighten&quot;,&quot;event_box_text_align&quot;:&quot;center&quot;,&quot;event_box_time&quot;:&quot;0&quot;,&quot;event_hover_text_color&quot;:&quot;#FFFFFF&quot;,&quot;event_hover_background_color&quot;:&quot;#000000&quot;,&quot;event_box_truncate_title&quot;:&quot;0&quot;,&quot;event_tooltip&quot;:&quot;0&quot;,&quot;event_tooltip_title&quot;:&quot;1&quot;,&quot;event_tooltip_time&quot;:&quot;1&quot;,&quot;event_tooltip_description&quot;:&quot;1&quot;,&quot;event_tooltip_width_type&quot;:&quot;event&quot;,&quot;event_tooltip_width&quot;:&quot;150&quot;,&quot;event_tooltip_color_type&quot;:&quot;event&quot;,&quot;event_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;event_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;column_tooltip&quot;:&quot;0&quot;,&quot;column_tooltip_title&quot;:&quot;1&quot;,&quot;column_tooltip_description&quot;:&quot;1&quot;,&quot;column_tooltip_width_type&quot;:&quot;column&quot;,&quot;column_tooltip_width&quot;:&quot;150&quot;,&quot;column_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;column_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;animations&quot;:&quot;1&quot;,&quot;animations_mobile&quot;:&quot;1&quot;,&quot;animations_speed&quot;:&quot;normal&quot;,&quot;animations_css3&quot;:&quot;1&quot;,&quot;tooltips_mobile&quot;:&quot;1&quot;,&quot;editor_bg&quot;:&quot;#F5F5F5&quot;,&quot;animations_editor&quot;:&quot;1&quot;,&quot;popup_max_width&quot;:&quot;560&quot;,&quot;popup_background_color&quot;:&quot;#ffffff&quot;,&quot;popup_text_color&quot;:&quot;#535353&quot;,&quot;popup_link_color&quot;:&quot;#ff4d00&quot;,&quot;autoplay_videos&quot;:&quot;1&quot;,&quot;column_color_bg&quot;:&quot;#e8e8e8&quot;,&quot;column_color_text&quot;:&quot;#3f3f3f&quot;,&quot;column_color_border&quot;:&quot;#ffffff&quot;,&quot;pattern_color_1&quot;:&quot;#ffffff&quot;,&quot;pattern_color_2&quot;:&quot;#e8e8e8&quot;,&quot;pattern_color_3&quot;:&quot;#ffffff&quot;,&quot;title_text_color&quot;:&quot;#3f3f3f&quot;,&quot;sidebar_text_color&quot;:&quot;#3f3f3f&quot;,&quot;event_box_text_color&quot;:&quot;#ffffff&quot;,&quot;title_attr&quot;:&quot;0&quot;,&quot;column_break&quot;:1,&quot;column_break_width&quot;:&quot;120&quot;,&quot;column_break_hide_sidebar&quot;:&quot;0&quot;,&quot;editor_custom_css&quot;:&quot;1&quot;,&quot;column_title&quot;:&quot;1&quot;,&quot;event_box_description_method&quot;:&quot;short&quot;,&quot;editor_quick_tooltips&quot;:&quot;1&quot;,&quot;editor_timepicker_increments&quot;:&quot;15&quot;,&quot;event_box_style&quot;:&quot;1&quot;,&quot;filter_position&quot;:&quot;right&quot;,&quot;filter_multiple&quot;:&quot;1&quot;,&quot;filter_hidden_events&quot;:&quot;hide&quot;,&quot;filter_hidden_events_opacity&quot;:&quot;30&quot;,&quot;filter_dropdown_width&quot;:&quot;100&quot;,&quot;filter_dropdown_hover_width&quot;:&quot;180&quot;,&quot;filter_dropdown_label&quot;:&quot;Secci\\u00f3n&quot;,&quot;filter_dropdown_show_all_label&quot;:&quot;Mostrar todo&quot;,&quot;hashtag_url&quot;:&quot;1&quot;,&quot;hide_popup_for_empty_events&quot;:&quot;1&quot;,&quot;event_box_padding_break&quot;:&quot;200&quot;,&quot;popup_arrows&quot;:&quot;1&quot;,&quot;filter_visible&quot;:&quot;1&quot;,&quot;column_break_action&quot;:&quot;list&quot;,&quot;list_view_column_title_color&quot;:&quot;#3f3f3f&quot;,&quot;list_view_event_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_hover_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_title_bold&quot;:&quot;1&quot;,&quot;list_view_event_bullets&quot;:&quot;2&quot;,&quot;list_view_event_short_description_method&quot;:&quot;short&quot;,&quot;list_view_event_description_color&quot;:&quot;#ffffff&quot;,&quot;list_view_hide_empty_columns&quot;:&quot;1&quot;,&quot;shortcodes_in_descriptions&quot;:&quot;1&quot;,&quot;columns_sticky_header&quot;:&quot;1&quot;,&quot;columns_sticky_header_offset&quot;:&quot;0&quot;,&quot;h_row_height&quot;:&quot;110&quot;,&quot;h_column_width&quot;:&quot;200&quot;,&quot;h_time_indicator&quot;:&quot;1&quot;,&quot;h_time_indicator_height&quot;:30,&quot;h_column_multiline&quot;:&quot;0&quot;,&quot;h_column_title_position&quot;:&quot;middle&quot;,&quot;h_column_title_align&quot;:&quot;center&quot;,&quot;h_break&quot;:&quot;0&quot;,&quot;h_width_break_point&quot;:&quot;200&quot;,&quot;h_bg_color&quot;:&quot;#f8f8f8&quot;,&quot;pdf_type&quot;:&quot;html&quot;,&quot;pdf_enable&quot;:&quot;0&quot;,&quot;pdf_enable_list&quot;:&quot;0&quot;,&quot;pdf_label&quot;:&quot;Download&quot;,&quot;pdf_css&quot;:&quot;&quot;,&quot;upcoming_type&quot;:&quot;current_datetime&quot;,&quot;upcoming_custom&quot;:&quot;2016-01-01 00:00&quot;,&quot;upcoming_limit&quot;:&quot;5&quot;,&quot;upcoming_title&quot;:&quot;timetable_title&quot;,&quot;upcoming_title_custom&quot;:&quot;Upcoming Events&quot;,&quot;upcoming_title_amount&quot;:&quot;1&quot;}\" data-start=\"11:00\" data-end=\"01:30\" data-timetable-id=\"3\" data-type=\"full\" data-list-id=\"#sched-schedule-3-1621949079-list\" data-layout=\"horizontal\">\t<div class=\"sched-style\"><style type=\"text\/css\">\/*\n * Custom CSS For Timetable\n*\/\n\n#sched-schedule-3-1621949079 .sched-column-header,\n#sched-schedule-3-1621949079 .sched-column-header-sticky {\n\tbackground: #e8e8e8;\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-3-1621949079 .sched-column-header:after,\n#sched-schedule-3-1621949079 .sched-column-header-sticky:after {\n\tbackground: #ffffff;\n}\n\n#sched-schedule-3-1621949079 .sched-columns .sched-column:last-child .sched-column-header:after,\n#sched-schedule-3-1621949079 .sched-columns .sched-column:last-child .sched-column-header-sticky:after {\n\tbackground: #e8e8e8;\n}\n\n#sched-schedule-3-1621949079 .sched-column-bg-block {\n\tbackground: #ffffff;\n\tborder-color: #e8e8e8;\n}\n\n#sched-schedule-3-1621949079 .sched-column-bg-block:after {\n\tbackground: #ffffff;\n}\n\n#sched-schedule-3-1621949079 .sched-row-no-title .sched-column .sched-column-bg {\n\tbox-shadow: 0 -1px 0 #e8e8e8;\n}\n\n#sched-schedule-3-1621949079 .sched-title {\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-3-1621949079 .sched-time-value {\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-3-1621949079 .sched-event .sched-event-inner {\n\tcolor: #ffffff;\n\ttext-align: center;\n}\n\n#sched-schedule-3-1621949079 .sched-event.sched-event-invert .sched-event-inner {\n\t<!-- background: #999; -->\n}\n\n\n\n\/*#sched-schedule-3-1621949079 a.sched-event.sched-event-sort-hidden {\n\topacity: 0;\n}*\/\n\n#sched-schedule-3-1621949079 .sched-sort .sched-sort-current .sched-sort-current-label {\n\twidth: 100px;\n}\n\n#sched-schedule-3-1621949079 .sched-sort.sched-sort-open .sched-sort-dropdown .sched-sort-current .sched-sort-current-label {\n\twidth: 180px;\n}\n\n\/*\n * Custom CSS Event Popup\n *\/\n\n#sched-schedule-3-1621949079-popup .sched-popup-description {\n\t\n}\n\n#sched-schedule-3-1621949079-popup .sched-popup-description .sched-meta a,\n#sched-schedule-3-1621949079-popup .sched-popup-description .sched-popup-description-text a {\n\tcolor: #ff4d00;\n}\n\n#sched-schedule-3-1621949079-popup .sched-popup-description .sched-meta,\n#sched-schedule-3-1621949079-popup .sched-popup-description .sched-popup-description-text {\n\tcolor: #535353;\n\tbackground: #ffffff;\n}\n\n\/*\n * List\n *\/\n\n#sched-schedule-3-1621949079-list .sched-list-title {\n\tcolor: #3f3f3f;\n}\n\n\n\n#sched-schedule-3-1621949079-list .sched-list-column-title {\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-3-1621949079-list .sched-list-event {\n\tcolor: #ffffff;\n\t\n\t\n}\n\n#sched-schedule-3-1621949079-list .sched-list-event:hover {\n\tcolor: #ffffff;\n}\n\n#sched-schedule-3-1621949079-list .sched-list-event-description {\n\tcolor: #ffffff;\n}\n\n#sched-schedule-3-1621949079-list .sched-list-event-title {\n\t\tfont-weight: bold;\n\t;\n}\n\n\/*\n * Horizontal\n *\/\n\n\n\n#sched-schedule-3-1621949079 .sched-h-columns {\n\tmargin-top: 30px;\n}\n\n#sched-schedule-3-1621949079 .sched-h-content-columns {\n\t\/*margin-top: 30px;*\/\n}\n\n\n#sched-schedule-3-1621949079 .sched-h-columns {\n\twidth: 200px;\n}\n\n#sched-schedule-3-1621949079 .sched-h-content {\n\tmargin-left: 200px;\n}\n\n#sched-schedule-3-1621949079 .sched-h-column-title {\n\ttext-align: center;\n}\n\n#sched-schedule-3-1621949079 .sched-h-column {\n\tbackground: #e8e8e8;\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-3-1621949079 .sched-h-row {\n\tbackground-color: #f8f8f8;\n}\n<\/style><\/div>\n\t<div class=\"sched-top\">\n\t\t\t<h2 class=\"sched-title\">S\u00c1BADO 2 DE NOVIEMBRE<\/h2>\n\t\t<div class=\"sched-top-buttons sched-top-buttons-right\">\n\t\t\t\n\t\t\t<\/div><!-- .sched-top-buttons -->\n<\/div><!-- .sched-top -->\t<div class=\"sched-row\">\n\t\t\t\t\t<!-- <div class=\"sched-sidebar\" style=\"width: 90px;\">\n\t\t\t\t<div class=\"sched-time\">\n\t\t\t\t\t<div class=\"sched-time-value\" style=\"padding-bottom: 36px\">11:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">12:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">13:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">14:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">15:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">16:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">17:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">18:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">19:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">20:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">21:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">22:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">23:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">00:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">01:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">02:00<\/div>\t\t\t\t<\/div>\n\t\t\t<\/div> -->\n\t\t\t\t\t\t<div class=\"sched-h-columns\">\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 4\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tFILMOTECA\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"sched-h-content\">\n\t\t\t<div class=\"sched-h-content-scroll\">\n\t\t\t\t\t\t\t\t<div class=\"sched-h-content-scroll-time\">\n\t\t\t\t\t<div class=\"sched-h-content-scroll-time-value\" data-i=\"0\" style=\"left: 0px;\">11:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"1\" style=\"left: 100px;\">12:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"2\" style=\"left: 200px;\">13:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"3\" style=\"left: 300px;\">14:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"4\" style=\"left: 400px;\">15:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"5\" style=\"left: 500px;\">16:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"6\" style=\"left: 600px;\">17:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"7\" style=\"left: 700px;\">18:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"8\" style=\"left: 800px;\">19:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"9\" style=\"left: 900px;\">20:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"10\" style=\"left: 1000px;\">21:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"11\" style=\"left: 1100px;\">22:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"12\" style=\"left: 1200px;\">23:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"13\" style=\"left: 1300px;\">00:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"14\" style=\"left: 1400px;\">01:00<\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"sched-h-content-columns\">\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/www.reservaentradas.com\/sesiones\/valencia\/cinesbabel\/palmera-de-bronce\/332?proximamente=true&amp;\" data-onclick=\"link\" data-color=\"#ef50b3\" title=\"PALMERA DE BRONCE\" data-event-id=\"553\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 200px; left: 700px;\" data-top=\"700\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/www.reservaentradas.com\/sesiones\/valencia\/cinesbabel\/palmera-de-bronce\/332?proximamente=true&\"  data-onclick=\"link\" data-color=\"#ef50b3\" title=\"PALMERA DE BRONCE\" data-event-id=\"553\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 200px; top: 700px\" data-top=\"700\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ef50b3; \" data-event-background-image-url=\"\" data-event-id=\"553\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">PALMERA DE BRONCE<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"553\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/www.reservaentradas.com\/sesiones\/valencia\/cinesbabel\/palmera-de-plata\/333\/\" data-onclick=\"link\" data-color=\"#ef50b3\" title=\"PALMERA DE PLATA\" data-event-id=\"554\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 200px; left: 900px;\" data-top=\"900\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/www.reservaentradas.com\/sesiones\/valencia\/cinesbabel\/palmera-de-plata\/333\/\"  data-onclick=\"link\" data-color=\"#ef50b3\" title=\"PALMERA DE PLATA\" data-event-id=\"554\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 200px; top: 900px\" data-top=\"900\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ef50b3; \" data-event-background-image-url=\"\" data-event-id=\"554\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">PALMERA DE PLATA<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"554\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/www.reservaentradas.com\/sesiones\/valencia\/cinesbabel\/palmera-de-oro\/334?proximamente=true&amp;\" data-onclick=\"link\" data-color=\"#ef50b3\" title=\"PALMERA DE ORO\" data-event-id=\"552\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 250px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/www.reservaentradas.com\/sesiones\/valencia\/cinesbabel\/palmera-de-oro\/334?proximamente=true&\"  data-onclick=\"link\" data-color=\"#ef50b3\" title=\"PALMERA DE ORO\" data-event-id=\"552\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 250px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ef50b3; \" data-event-background-image-url=\"\" data-event-id=\"552\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">PALMERA DE ORO<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"552\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/francesco\/\" data-onclick=\"link\" data-color=\"#fa983a\" title=\"FRANCESCO 155&#039;\" data-event-id=\"556\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 250px; left: 700px;\" data-top=\"700\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/francesco\/\"  data-onclick=\"link\" data-color=\"#fa983a\" title=\"FRANCESCO 155&#039;\" data-event-id=\"556\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 250px; top: 700px\" data-top=\"700\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fa983a; \" data-event-background-image-url=\"\" data-event-id=\"556\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">FRANCESCO 155&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"556\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-piel\/\" data-onclick=\"link\" data-color=\"#fa983a\" title=\"LA PIEL 130&#039;\" data-event-id=\"555\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 225px; left: 1000px;\" data-top=\"1000\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-piel\/\"  data-onclick=\"link\" data-color=\"#fa983a\" title=\"LA PIEL 130&#039;\" data-event-id=\"555\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 225px; top: 1000px\" data-top=\"1000\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fa983a; \" data-event-background-image-url=\"\" data-event-id=\"555\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">LA PIEL 130&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"555\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n<\/div><div class=\" sched-list sched-hidden\" id=\"sched-schedule-3-1621949079-list\" data-id-schedule=\"sched-schedule-3-1621949079\" data-options=\" {&quot;am_pm&quot;:&quot;0&quot;,&quot;sidebar_width&quot;:&quot;90&quot;,&quot;sidebar_position&quot;:&quot;left&quot;,&quot;event_hover_color&quot;:&quot;lighten&quot;,&quot;event_box_text_align&quot;:&quot;center&quot;,&quot;event_box_time&quot;:&quot;0&quot;,&quot;event_hover_text_color&quot;:&quot;#FFFFFF&quot;,&quot;event_hover_background_color&quot;:&quot;#000000&quot;,&quot;event_box_truncate_title&quot;:&quot;0&quot;,&quot;event_tooltip&quot;:&quot;0&quot;,&quot;event_tooltip_title&quot;:&quot;1&quot;,&quot;event_tooltip_time&quot;:&quot;1&quot;,&quot;event_tooltip_description&quot;:&quot;1&quot;,&quot;event_tooltip_width_type&quot;:&quot;event&quot;,&quot;event_tooltip_width&quot;:&quot;150&quot;,&quot;event_tooltip_color_type&quot;:&quot;event&quot;,&quot;event_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;event_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;column_tooltip&quot;:&quot;0&quot;,&quot;column_tooltip_title&quot;:&quot;1&quot;,&quot;column_tooltip_description&quot;:&quot;1&quot;,&quot;column_tooltip_width_type&quot;:&quot;column&quot;,&quot;column_tooltip_width&quot;:&quot;150&quot;,&quot;column_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;column_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;animations&quot;:&quot;1&quot;,&quot;animations_mobile&quot;:&quot;1&quot;,&quot;animations_speed&quot;:&quot;normal&quot;,&quot;animations_css3&quot;:&quot;1&quot;,&quot;tooltips_mobile&quot;:&quot;1&quot;,&quot;editor_bg&quot;:&quot;#F5F5F5&quot;,&quot;animations_editor&quot;:&quot;1&quot;,&quot;popup_max_width&quot;:&quot;560&quot;,&quot;popup_background_color&quot;:&quot;#ffffff&quot;,&quot;popup_text_color&quot;:&quot;#535353&quot;,&quot;popup_link_color&quot;:&quot;#ff4d00&quot;,&quot;autoplay_videos&quot;:&quot;1&quot;,&quot;column_color_bg&quot;:&quot;#e8e8e8&quot;,&quot;column_color_text&quot;:&quot;#3f3f3f&quot;,&quot;column_color_border&quot;:&quot;#ffffff&quot;,&quot;pattern_color_1&quot;:&quot;#ffffff&quot;,&quot;pattern_color_2&quot;:&quot;#e8e8e8&quot;,&quot;pattern_color_3&quot;:&quot;#ffffff&quot;,&quot;title_text_color&quot;:&quot;#3f3f3f&quot;,&quot;sidebar_text_color&quot;:&quot;#3f3f3f&quot;,&quot;event_box_text_color&quot;:&quot;#ffffff&quot;,&quot;title_attr&quot;:&quot;0&quot;,&quot;column_break&quot;:1,&quot;column_break_width&quot;:&quot;120&quot;,&quot;column_break_hide_sidebar&quot;:&quot;0&quot;,&quot;editor_custom_css&quot;:&quot;1&quot;,&quot;column_title&quot;:&quot;1&quot;,&quot;event_box_description_method&quot;:&quot;short&quot;,&quot;editor_quick_tooltips&quot;:&quot;1&quot;,&quot;editor_timepicker_increments&quot;:&quot;15&quot;,&quot;event_box_style&quot;:&quot;1&quot;,&quot;filter_position&quot;:&quot;right&quot;,&quot;filter_multiple&quot;:&quot;1&quot;,&quot;filter_hidden_events&quot;:&quot;hide&quot;,&quot;filter_hidden_events_opacity&quot;:&quot;30&quot;,&quot;filter_dropdown_width&quot;:&quot;100&quot;,&quot;filter_dropdown_hover_width&quot;:&quot;180&quot;,&quot;filter_dropdown_label&quot;:&quot;Secci\\u00f3n&quot;,&quot;filter_dropdown_show_all_label&quot;:&quot;Mostrar todo&quot;,&quot;hashtag_url&quot;:&quot;1&quot;,&quot;hide_popup_for_empty_events&quot;:&quot;1&quot;,&quot;event_box_padding_break&quot;:&quot;200&quot;,&quot;popup_arrows&quot;:&quot;1&quot;,&quot;filter_visible&quot;:&quot;1&quot;,&quot;column_break_action&quot;:&quot;list&quot;,&quot;list_view_column_title_color&quot;:&quot;#3f3f3f&quot;,&quot;list_view_event_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_hover_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_title_bold&quot;:&quot;1&quot;,&quot;list_view_event_bullets&quot;:&quot;2&quot;,&quot;list_view_event_short_description_method&quot;:&quot;short&quot;,&quot;list_view_event_description_color&quot;:&quot;#ffffff&quot;,&quot;list_view_hide_empty_columns&quot;:&quot;1&quot;,&quot;shortcodes_in_descriptions&quot;:&quot;1&quot;,&quot;columns_sticky_header&quot;:&quot;1&quot;,&quot;columns_sticky_header_offset&quot;:&quot;0&quot;,&quot;h_row_height&quot;:&quot;110&quot;,&quot;h_column_width&quot;:&quot;200&quot;,&quot;h_time_indicator&quot;:&quot;1&quot;,&quot;h_time_indicator_height&quot;:30,&quot;h_column_multiline&quot;:&quot;0&quot;,&quot;h_column_title_position&quot;:&quot;middle&quot;,&quot;h_column_title_align&quot;:&quot;center&quot;,&quot;h_break&quot;:&quot;0&quot;,&quot;h_width_break_point&quot;:&quot;200&quot;,&quot;h_bg_color&quot;:&quot;#f8f8f8&quot;,&quot;pdf_type&quot;:&quot;html&quot;,&quot;pdf_enable&quot;:&quot;0&quot;,&quot;pdf_enable_list&quot;:&quot;0&quot;,&quot;pdf_label&quot;:&quot;Download&quot;,&quot;pdf_css&quot;:&quot;&quot;,&quot;upcoming_type&quot;:&quot;current_datetime&quot;,&quot;upcoming_custom&quot;:&quot;2016-01-01 00:00&quot;,&quot;upcoming_limit&quot;:&quot;5&quot;,&quot;upcoming_title&quot;:&quot;timetable_title&quot;,&quot;upcoming_title_custom&quot;:&quot;Upcoming Events&quot;,&quot;upcoming_title_amount&quot;:&quot;1&quot;}\" data-start=\"11:00\" data-end=\"01:30\" data-timetable-id=\"3\" data-type=\"list\" data-layout=\"horizontal\">\t<div class=\"sched-list-top\">\n\t\t<div class=\"sched-list-title\">S\u00c1BADO 2 DE NOVIEMBRE<\/div>\n\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 4<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/www.reservaentradas.com\/sesiones\/valencia\/cinesbabel\/palmera-de-bronce\/332?proximamente=true&amp;\" data-event-id=\"553\" style=\"background: #ef50b3;\" data-color=\"#ef50b3\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ef50b3;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tPALMERA DE BRONCE\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 20:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/www.reservaentradas.com\/sesiones\/valencia\/cinesbabel\/palmera-de-plata\/333\/\" data-event-id=\"554\" style=\"background: #ef50b3;\" data-color=\"#ef50b3\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ef50b3;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tPALMERA DE PLATA\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 22:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/www.reservaentradas.com\/sesiones\/valencia\/cinesbabel\/palmera-de-oro\/334?proximamente=true&amp;\" data-event-id=\"552\" style=\"background: #ef50b3;\" data-color=\"#ef50b3\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ef50b3;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tPALMERA DE ORO\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 01:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">FILMOTECA<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/francesco\/\" data-event-id=\"556\" style=\"background: #fa983a;\" data-color=\"#fa983a\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fa983a;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tFRANCESCO 155&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 20:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/la-piel\/\" data-event-id=\"555\" style=\"background: #fa983a;\" data-color=\"#fa983a\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fa983a;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tLA PIEL 130&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">21:00 - 23:15<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t<!-- .sched-list-column -->\n\t\n<\/div>[\/vc_column][\/vc_row][vc_row disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1600188428738{padding-right: 40px !important;padding-bottom: 50px !important;padding-left: 40px !important;}&#8221; anchor=&#8221;domingo-3&#8243;][vc_column]<div class=\"sched-loader\"><div class=\"sched-loader-icon\"><\/div><div class=\"sched-loader-text\"><\/div><\/div>\n<div class=\" sched sched-horizontal sched-horizontal-medium\" id=\"sched-schedule-4-2050182180\" data-options=\" {&quot;am_pm&quot;:&quot;0&quot;,&quot;sidebar_width&quot;:&quot;90&quot;,&quot;sidebar_position&quot;:&quot;left&quot;,&quot;event_hover_color&quot;:&quot;lighten&quot;,&quot;event_box_text_align&quot;:&quot;center&quot;,&quot;event_box_time&quot;:&quot;0&quot;,&quot;event_hover_text_color&quot;:&quot;#FFFFFF&quot;,&quot;event_hover_background_color&quot;:&quot;#000000&quot;,&quot;event_box_truncate_title&quot;:&quot;0&quot;,&quot;event_tooltip&quot;:&quot;0&quot;,&quot;event_tooltip_title&quot;:&quot;1&quot;,&quot;event_tooltip_time&quot;:&quot;1&quot;,&quot;event_tooltip_description&quot;:&quot;1&quot;,&quot;event_tooltip_width_type&quot;:&quot;event&quot;,&quot;event_tooltip_width&quot;:&quot;150&quot;,&quot;event_tooltip_color_type&quot;:&quot;event&quot;,&quot;event_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;event_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;column_tooltip&quot;:&quot;0&quot;,&quot;column_tooltip_title&quot;:&quot;1&quot;,&quot;column_tooltip_description&quot;:&quot;1&quot;,&quot;column_tooltip_width_type&quot;:&quot;column&quot;,&quot;column_tooltip_width&quot;:&quot;150&quot;,&quot;column_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;column_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;animations&quot;:&quot;1&quot;,&quot;animations_mobile&quot;:&quot;1&quot;,&quot;animations_speed&quot;:&quot;normal&quot;,&quot;animations_css3&quot;:&quot;1&quot;,&quot;tooltips_mobile&quot;:&quot;1&quot;,&quot;editor_bg&quot;:&quot;#F5F5F5&quot;,&quot;animations_editor&quot;:&quot;1&quot;,&quot;popup_max_width&quot;:&quot;560&quot;,&quot;popup_background_color&quot;:&quot;#ffffff&quot;,&quot;popup_text_color&quot;:&quot;#535353&quot;,&quot;popup_link_color&quot;:&quot;#ff4d00&quot;,&quot;autoplay_videos&quot;:&quot;1&quot;,&quot;column_color_bg&quot;:&quot;#e8e8e8&quot;,&quot;column_color_text&quot;:&quot;#3f3f3f&quot;,&quot;column_color_border&quot;:&quot;#ffffff&quot;,&quot;pattern_color_1&quot;:&quot;#ffffff&quot;,&quot;pattern_color_2&quot;:&quot;#e8e8e8&quot;,&quot;pattern_color_3&quot;:&quot;#ffffff&quot;,&quot;title_text_color&quot;:&quot;#3f3f3f&quot;,&quot;sidebar_text_color&quot;:&quot;#3f3f3f&quot;,&quot;event_box_text_color&quot;:&quot;#ffffff&quot;,&quot;title_attr&quot;:&quot;0&quot;,&quot;column_break&quot;:1,&quot;column_break_width&quot;:&quot;120&quot;,&quot;column_break_hide_sidebar&quot;:&quot;0&quot;,&quot;editor_custom_css&quot;:&quot;1&quot;,&quot;column_title&quot;:&quot;1&quot;,&quot;event_box_description_method&quot;:&quot;short&quot;,&quot;editor_quick_tooltips&quot;:&quot;1&quot;,&quot;editor_timepicker_increments&quot;:&quot;15&quot;,&quot;event_box_style&quot;:&quot;1&quot;,&quot;filter_position&quot;:&quot;right&quot;,&quot;filter_multiple&quot;:&quot;1&quot;,&quot;filter_hidden_events&quot;:&quot;hide&quot;,&quot;filter_hidden_events_opacity&quot;:&quot;30&quot;,&quot;filter_dropdown_width&quot;:&quot;100&quot;,&quot;filter_dropdown_hover_width&quot;:&quot;180&quot;,&quot;filter_dropdown_label&quot;:&quot;Secci\\u00f3n&quot;,&quot;filter_dropdown_show_all_label&quot;:&quot;Mostrar todo&quot;,&quot;hashtag_url&quot;:&quot;1&quot;,&quot;hide_popup_for_empty_events&quot;:&quot;1&quot;,&quot;event_box_padding_break&quot;:&quot;200&quot;,&quot;popup_arrows&quot;:&quot;1&quot;,&quot;filter_visible&quot;:&quot;1&quot;,&quot;column_break_action&quot;:&quot;list&quot;,&quot;list_view_column_title_color&quot;:&quot;#3f3f3f&quot;,&quot;list_view_event_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_hover_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_title_bold&quot;:&quot;1&quot;,&quot;list_view_event_bullets&quot;:&quot;2&quot;,&quot;list_view_event_short_description_method&quot;:&quot;short&quot;,&quot;list_view_event_description_color&quot;:&quot;#ffffff&quot;,&quot;list_view_hide_empty_columns&quot;:&quot;1&quot;,&quot;shortcodes_in_descriptions&quot;:&quot;1&quot;,&quot;columns_sticky_header&quot;:&quot;1&quot;,&quot;columns_sticky_header_offset&quot;:&quot;0&quot;,&quot;h_row_height&quot;:&quot;110&quot;,&quot;h_column_width&quot;:&quot;200&quot;,&quot;h_time_indicator&quot;:&quot;1&quot;,&quot;h_time_indicator_height&quot;:30,&quot;h_column_multiline&quot;:&quot;0&quot;,&quot;h_column_title_position&quot;:&quot;middle&quot;,&quot;h_column_title_align&quot;:&quot;center&quot;,&quot;h_break&quot;:&quot;0&quot;,&quot;h_width_break_point&quot;:&quot;200&quot;,&quot;h_bg_color&quot;:&quot;#f8f8f8&quot;,&quot;pdf_type&quot;:&quot;html&quot;,&quot;pdf_enable&quot;:&quot;0&quot;,&quot;pdf_enable_list&quot;:&quot;0&quot;,&quot;pdf_label&quot;:&quot;Download&quot;,&quot;pdf_css&quot;:&quot;&quot;,&quot;upcoming_type&quot;:&quot;current_datetime&quot;,&quot;upcoming_custom&quot;:&quot;2016-01-01 00:00&quot;,&quot;upcoming_limit&quot;:&quot;5&quot;,&quot;upcoming_title&quot;:&quot;timetable_title&quot;,&quot;upcoming_title_custom&quot;:&quot;Upcoming Events&quot;,&quot;upcoming_title_amount&quot;:&quot;1&quot;}\" data-start=\"11:00\" data-end=\"01:30\" data-timetable-id=\"4\" data-type=\"full\" data-list-id=\"#sched-schedule-4-2050182180-list\" data-layout=\"horizontal\">\t<div class=\"sched-style\"><style type=\"text\/css\">\/*\n * Custom CSS For Timetable\n*\/\n\n#sched-schedule-4-2050182180 .sched-column-header,\n#sched-schedule-4-2050182180 .sched-column-header-sticky {\n\tbackground: #e8e8e8;\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-4-2050182180 .sched-column-header:after,\n#sched-schedule-4-2050182180 .sched-column-header-sticky:after {\n\tbackground: #ffffff;\n}\n\n#sched-schedule-4-2050182180 .sched-columns .sched-column:last-child .sched-column-header:after,\n#sched-schedule-4-2050182180 .sched-columns .sched-column:last-child .sched-column-header-sticky:after {\n\tbackground: #e8e8e8;\n}\n\n#sched-schedule-4-2050182180 .sched-column-bg-block {\n\tbackground: #ffffff;\n\tborder-color: #e8e8e8;\n}\n\n#sched-schedule-4-2050182180 .sched-column-bg-block:after {\n\tbackground: #ffffff;\n}\n\n#sched-schedule-4-2050182180 .sched-row-no-title .sched-column .sched-column-bg {\n\tbox-shadow: 0 -1px 0 #e8e8e8;\n}\n\n#sched-schedule-4-2050182180 .sched-title {\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-4-2050182180 .sched-time-value {\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-4-2050182180 .sched-event .sched-event-inner {\n\tcolor: #ffffff;\n\ttext-align: center;\n}\n\n#sched-schedule-4-2050182180 .sched-event.sched-event-invert .sched-event-inner {\n\t<!-- background: #999; -->\n}\n\n\n\n\/*#sched-schedule-4-2050182180 a.sched-event.sched-event-sort-hidden {\n\topacity: 0;\n}*\/\n\n#sched-schedule-4-2050182180 .sched-sort .sched-sort-current .sched-sort-current-label {\n\twidth: 100px;\n}\n\n#sched-schedule-4-2050182180 .sched-sort.sched-sort-open .sched-sort-dropdown .sched-sort-current .sched-sort-current-label {\n\twidth: 180px;\n}\n\n\/*\n * Custom CSS Event Popup\n *\/\n\n#sched-schedule-4-2050182180-popup .sched-popup-description {\n\t\n}\n\n#sched-schedule-4-2050182180-popup .sched-popup-description .sched-meta a,\n#sched-schedule-4-2050182180-popup .sched-popup-description .sched-popup-description-text a {\n\tcolor: #ff4d00;\n}\n\n#sched-schedule-4-2050182180-popup .sched-popup-description .sched-meta,\n#sched-schedule-4-2050182180-popup .sched-popup-description .sched-popup-description-text {\n\tcolor: #535353;\n\tbackground: #ffffff;\n}\n\n\/*\n * List\n *\/\n\n#sched-schedule-4-2050182180-list .sched-list-title {\n\tcolor: #3f3f3f;\n}\n\n\n\n#sched-schedule-4-2050182180-list .sched-list-column-title {\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-4-2050182180-list .sched-list-event {\n\tcolor: #ffffff;\n\t\n\t\n}\n\n#sched-schedule-4-2050182180-list .sched-list-event:hover {\n\tcolor: #ffffff;\n}\n\n#sched-schedule-4-2050182180-list .sched-list-event-description {\n\tcolor: #ffffff;\n}\n\n#sched-schedule-4-2050182180-list .sched-list-event-title {\n\t\tfont-weight: bold;\n\t;\n}\n\n\/*\n * Horizontal\n *\/\n\n\n\n#sched-schedule-4-2050182180 .sched-h-columns {\n\tmargin-top: 30px;\n}\n\n#sched-schedule-4-2050182180 .sched-h-content-columns {\n\t\/*margin-top: 30px;*\/\n}\n\n\n#sched-schedule-4-2050182180 .sched-h-columns {\n\twidth: 200px;\n}\n\n#sched-schedule-4-2050182180 .sched-h-content {\n\tmargin-left: 200px;\n}\n\n#sched-schedule-4-2050182180 .sched-h-column-title {\n\ttext-align: center;\n}\n\n#sched-schedule-4-2050182180 .sched-h-column {\n\tbackground: #e8e8e8;\n\tcolor: #3f3f3f;\n}\n\n#sched-schedule-4-2050182180 .sched-h-row {\n\tbackground-color: #f8f8f8;\n}\n<\/style><\/div>\n\t<div class=\"sched-top\">\n\t\t\t<h2 class=\"sched-title\">DOMINGO 3 DE NOVIEMBRE<\/h2>\n\t\t<div class=\"sched-top-buttons sched-top-buttons-right\">\n\t\t\t\n\t\t\t<\/div><!-- .sched-top-buttons -->\n<\/div><!-- .sched-top -->\t<div class=\"sched-row\">\n\t\t\t\t\t<!-- <div class=\"sched-sidebar\" style=\"width: 90px;\">\n\t\t\t\t<div class=\"sched-time\">\n\t\t\t\t\t<div class=\"sched-time-value\" style=\"padding-bottom: 36px\">11:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">12:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">13:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">14:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">15:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">16:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">17:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">18:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">19:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">20:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">21:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">22:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">23:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">00:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">01:00<\/div><div class=\"sched-time-value\" style=\"padding-bottom: 36px\">02:00<\/div>\t\t\t\t<\/div>\n\t\t\t<\/div> -->\n\t\t\t\t\t\t<div class=\"sched-h-columns\">\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tBABEL 4\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"sched-h-column\" style=\"height: 78px; line-height: 78px; width: 168px\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-h-column-title\">\n\t\t\t\t\t\tFILMOTECA\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"sched-h-content\">\n\t\t\t<div class=\"sched-h-content-scroll\">\n\t\t\t\t\t\t\t\t<div class=\"sched-h-content-scroll-time\">\n\t\t\t\t\t<div class=\"sched-h-content-scroll-time-value\" data-i=\"0\" style=\"left: 0px;\">11:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"1\" style=\"left: 100px;\">12:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"2\" style=\"left: 200px;\">13:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"3\" style=\"left: 300px;\">14:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"4\" style=\"left: 400px;\">15:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"5\" style=\"left: 500px;\">16:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"6\" style=\"left: 600px;\">17:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"7\" style=\"left: 700px;\">18:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"8\" style=\"left: 800px;\">19:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"9\" style=\"left: 900px;\">20:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"10\" style=\"left: 1000px;\">21:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"11\" style=\"left: 1100px;\">22:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"12\" style=\"left: 1200px;\">23:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"13\" style=\"left: 1300px;\">00:00<\/div><div class=\"sched-h-content-scroll-time-value\" data-i=\"14\" style=\"left: 1400px;\">01:00<\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"sched-h-content-columns\">\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/www.reservaentradas.com\/sesiones\/valencia\/cinesbabel\/palmera-de-oro\/334?proximamente=true&amp;\" data-onclick=\"link\" data-color=\"#ef50b3\" title=\"PALMERA DE ORO\" data-event-id=\"558\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 200px; left: 700px;\" data-top=\"700\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/www.reservaentradas.com\/sesiones\/valencia\/cinesbabel\/palmera-de-oro\/334?proximamente=true&\"  data-onclick=\"link\" data-color=\"#ef50b3\" title=\"PALMERA DE ORO\" data-event-id=\"558\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 200px; top: 700px\" data-top=\"700\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ef50b3; \" data-event-background-image-url=\"\" data-event-id=\"558\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">PALMERA DE ORO<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"558\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/www.reservaentradas.com\/sesiones\/valencia\/cinesbabel\/palmera-de-bronce\/332?proximamente=true&amp;\" data-onclick=\"link\" data-color=\"#ef50b3\" title=\"PALMERA DE BRONCE\" data-event-id=\"559\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 200px; left: 900px;\" data-top=\"900\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/www.reservaentradas.com\/sesiones\/valencia\/cinesbabel\/palmera-de-bronce\/332?proximamente=true&\"  data-onclick=\"link\" data-color=\"#ef50b3\" title=\"PALMERA DE BRONCE\" data-event-id=\"559\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 200px; top: 900px\" data-top=\"900\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ef50b3; \" data-event-background-image-url=\"\" data-event-id=\"559\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">PALMERA DE BRONCE<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"559\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/www.reservaentradas.com\/sesiones\/valencia\/cinesbabel\/palmera-de-plata\/333\/\" data-onclick=\"link\" data-color=\"#ef50b3\" title=\"PALMERA DE PLATA\" data-event-id=\"557\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 200px; left: 1150px;\" data-top=\"1150\" data-size=\"1\" data-sort-index=\"2\"><!-- <a class=\"sched-event   \" href=\"https:\/\/www.reservaentradas.com\/sesiones\/valencia\/cinesbabel\/palmera-de-plata\/333\/\"  data-onclick=\"link\" data-color=\"#ef50b3\" title=\"PALMERA DE PLATA\" data-event-id=\"557\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 200px; top: 1150px\" data-top=\"1150\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #ef50b3; \" data-event-background-image-url=\"\" data-event-id=\"557\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">PALMERA DE PLATA<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"557\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"sched-h-row\" style=\"height: 110px; width: 1450px\">\n\t\t\t\t\t\t<div class=\"sched-h-row-events\">\n\t\t\t\t\t\t\t<a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-juego-de-ripley\/\" data-onclick=\"link\" data-color=\"#fa983a\" title=\"EL JUEGO DE RIPLEY 110&#039;\" data-event-id=\"561\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 700px;\" data-top=\"700\" data-size=\"1\" data-sort-index=\"0\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-juego-de-ripley\/\"  data-onclick=\"link\" data-color=\"#fa983a\" title=\"EL JUEGO DE RIPLEY 110&#039;\" data-event-id=\"561\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 700px\" data-top=\"700\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fa983a; \" data-event-background-image-url=\"\" data-event-id=\"561\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">EL JUEGO DE RIPLEY 110&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"561\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div><a class=\" sched-event sched-event-size-1\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/berlin-interior\/\" data-onclick=\"link\" data-color=\"#fa983a\" title=\"BERL\u00cdN INTERIOR 110&#039;\" data-event-id=\"560\" data-children=\"0\" data-children-match-color=\"1\" style=\"width: 175px; left: 925px;\" data-top=\"925\" data-size=\"1\" data-sort-index=\"1\"><!-- <a class=\"sched-event   \" href=\"https:\/\/lamostradevalencia.com\/peliculas\/berlin-interior\/\"  data-onclick=\"link\" data-color=\"#fa983a\" title=\"BERL\u00cdN INTERIOR 110&#039;\" data-event-id=\"560\" data-children=\"0\" data-children-match-color=\"1\" style=\"height: 175px; top: 925px\" data-top=\"925\"> -->\n\t\t<div class=\"sched-event-inner\" style=\"background-color: #fa983a; \" data-event-background-image-url=\"\" data-event-id=\"560\">\n\t\t<div class=\"sched-event-inner-bar\"><\/div>\n\t\t\t\t<div class=\"sched-event-title\">BERL\u00cdN INTERIOR 110&#039;<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"sched-event-description\" data-full=\"\"><\/div>\n\t\t\t<\/div>\n\t<\/a>\n\n<div class=\"sched-event-fulldescription\" data-event-id=\"560\" data-media-type=\"0\" data-media-link=\"\">\n\t<div class=\"sched-event-image-load\">\n\t\t\t\t<img decoding=\"async\" src=\"\" \/>\n\t\t\t<\/div>\n\t<div class=\"sched-meta sched-event-no-description\">\n\t\t\t<\/div>\n\t<p class=\"sched-popup-description-text sched-event-no-description\">\n\t\t\t<\/p>\n<\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n<\/div><div class=\" sched-list sched-hidden\" id=\"sched-schedule-4-2050182180-list\" data-id-schedule=\"sched-schedule-4-2050182180\" data-options=\" {&quot;am_pm&quot;:&quot;0&quot;,&quot;sidebar_width&quot;:&quot;90&quot;,&quot;sidebar_position&quot;:&quot;left&quot;,&quot;event_hover_color&quot;:&quot;lighten&quot;,&quot;event_box_text_align&quot;:&quot;center&quot;,&quot;event_box_time&quot;:&quot;0&quot;,&quot;event_hover_text_color&quot;:&quot;#FFFFFF&quot;,&quot;event_hover_background_color&quot;:&quot;#000000&quot;,&quot;event_box_truncate_title&quot;:&quot;0&quot;,&quot;event_tooltip&quot;:&quot;0&quot;,&quot;event_tooltip_title&quot;:&quot;1&quot;,&quot;event_tooltip_time&quot;:&quot;1&quot;,&quot;event_tooltip_description&quot;:&quot;1&quot;,&quot;event_tooltip_width_type&quot;:&quot;event&quot;,&quot;event_tooltip_width&quot;:&quot;150&quot;,&quot;event_tooltip_color_type&quot;:&quot;event&quot;,&quot;event_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;event_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;column_tooltip&quot;:&quot;0&quot;,&quot;column_tooltip_title&quot;:&quot;1&quot;,&quot;column_tooltip_description&quot;:&quot;1&quot;,&quot;column_tooltip_width_type&quot;:&quot;column&quot;,&quot;column_tooltip_width&quot;:&quot;150&quot;,&quot;column_tooltip_color_bg&quot;:&quot;#000000&quot;,&quot;column_tooltip_color_text&quot;:&quot;#FFFFFF&quot;,&quot;animations&quot;:&quot;1&quot;,&quot;animations_mobile&quot;:&quot;1&quot;,&quot;animations_speed&quot;:&quot;normal&quot;,&quot;animations_css3&quot;:&quot;1&quot;,&quot;tooltips_mobile&quot;:&quot;1&quot;,&quot;editor_bg&quot;:&quot;#F5F5F5&quot;,&quot;animations_editor&quot;:&quot;1&quot;,&quot;popup_max_width&quot;:&quot;560&quot;,&quot;popup_background_color&quot;:&quot;#ffffff&quot;,&quot;popup_text_color&quot;:&quot;#535353&quot;,&quot;popup_link_color&quot;:&quot;#ff4d00&quot;,&quot;autoplay_videos&quot;:&quot;1&quot;,&quot;column_color_bg&quot;:&quot;#e8e8e8&quot;,&quot;column_color_text&quot;:&quot;#3f3f3f&quot;,&quot;column_color_border&quot;:&quot;#ffffff&quot;,&quot;pattern_color_1&quot;:&quot;#ffffff&quot;,&quot;pattern_color_2&quot;:&quot;#e8e8e8&quot;,&quot;pattern_color_3&quot;:&quot;#ffffff&quot;,&quot;title_text_color&quot;:&quot;#3f3f3f&quot;,&quot;sidebar_text_color&quot;:&quot;#3f3f3f&quot;,&quot;event_box_text_color&quot;:&quot;#ffffff&quot;,&quot;title_attr&quot;:&quot;0&quot;,&quot;column_break&quot;:1,&quot;column_break_width&quot;:&quot;120&quot;,&quot;column_break_hide_sidebar&quot;:&quot;0&quot;,&quot;editor_custom_css&quot;:&quot;1&quot;,&quot;column_title&quot;:&quot;1&quot;,&quot;event_box_description_method&quot;:&quot;short&quot;,&quot;editor_quick_tooltips&quot;:&quot;1&quot;,&quot;editor_timepicker_increments&quot;:&quot;15&quot;,&quot;event_box_style&quot;:&quot;1&quot;,&quot;filter_position&quot;:&quot;right&quot;,&quot;filter_multiple&quot;:&quot;1&quot;,&quot;filter_hidden_events&quot;:&quot;hide&quot;,&quot;filter_hidden_events_opacity&quot;:&quot;30&quot;,&quot;filter_dropdown_width&quot;:&quot;100&quot;,&quot;filter_dropdown_hover_width&quot;:&quot;180&quot;,&quot;filter_dropdown_label&quot;:&quot;Secci\\u00f3n&quot;,&quot;filter_dropdown_show_all_label&quot;:&quot;Mostrar todo&quot;,&quot;hashtag_url&quot;:&quot;1&quot;,&quot;hide_popup_for_empty_events&quot;:&quot;1&quot;,&quot;event_box_padding_break&quot;:&quot;200&quot;,&quot;popup_arrows&quot;:&quot;1&quot;,&quot;filter_visible&quot;:&quot;1&quot;,&quot;column_break_action&quot;:&quot;list&quot;,&quot;list_view_column_title_color&quot;:&quot;#3f3f3f&quot;,&quot;list_view_event_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_hover_title_color&quot;:&quot;#ffffff&quot;,&quot;list_view_event_title_bold&quot;:&quot;1&quot;,&quot;list_view_event_bullets&quot;:&quot;2&quot;,&quot;list_view_event_short_description_method&quot;:&quot;short&quot;,&quot;list_view_event_description_color&quot;:&quot;#ffffff&quot;,&quot;list_view_hide_empty_columns&quot;:&quot;1&quot;,&quot;shortcodes_in_descriptions&quot;:&quot;1&quot;,&quot;columns_sticky_header&quot;:&quot;1&quot;,&quot;columns_sticky_header_offset&quot;:&quot;0&quot;,&quot;h_row_height&quot;:&quot;110&quot;,&quot;h_column_width&quot;:&quot;200&quot;,&quot;h_time_indicator&quot;:&quot;1&quot;,&quot;h_time_indicator_height&quot;:30,&quot;h_column_multiline&quot;:&quot;0&quot;,&quot;h_column_title_position&quot;:&quot;middle&quot;,&quot;h_column_title_align&quot;:&quot;center&quot;,&quot;h_break&quot;:&quot;0&quot;,&quot;h_width_break_point&quot;:&quot;200&quot;,&quot;h_bg_color&quot;:&quot;#f8f8f8&quot;,&quot;pdf_type&quot;:&quot;html&quot;,&quot;pdf_enable&quot;:&quot;0&quot;,&quot;pdf_enable_list&quot;:&quot;0&quot;,&quot;pdf_label&quot;:&quot;Download&quot;,&quot;pdf_css&quot;:&quot;&quot;,&quot;upcoming_type&quot;:&quot;current_datetime&quot;,&quot;upcoming_custom&quot;:&quot;2016-01-01 00:00&quot;,&quot;upcoming_limit&quot;:&quot;5&quot;,&quot;upcoming_title&quot;:&quot;timetable_title&quot;,&quot;upcoming_title_custom&quot;:&quot;Upcoming Events&quot;,&quot;upcoming_title_amount&quot;:&quot;1&quot;}\" data-start=\"11:00\" data-end=\"01:30\" data-timetable-id=\"4\" data-type=\"list\" data-layout=\"horizontal\">\t<div class=\"sched-list-top\">\n\t\t<div class=\"sched-list-title\">DOMINGO 3 DE NOVIEMBRE<\/div>\n\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">BABEL 4<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/www.reservaentradas.com\/sesiones\/valencia\/cinesbabel\/palmera-de-oro\/334?proximamente=true&amp;\" data-event-id=\"558\" style=\"background: #ef50b3;\" data-color=\"#ef50b3\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ef50b3;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tPALMERA DE ORO\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 20:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/www.reservaentradas.com\/sesiones\/valencia\/cinesbabel\/palmera-de-bronce\/332?proximamente=true&amp;\" data-event-id=\"559\" style=\"background: #ef50b3;\" data-color=\"#ef50b3\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ef50b3;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tPALMERA DE BRONCE\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:00 - 22:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/www.reservaentradas.com\/sesiones\/valencia\/cinesbabel\/palmera-de-plata\/333\/\" data-event-id=\"557\" style=\"background: #ef50b3;\" data-color=\"#ef50b3\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #ef50b3;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tPALMERA DE PLATA\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">22:30 - 00:30<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t\t<div class=\"sched-list-column\">\n\t\t<div class=\"sched-list-column-title\">FILMOTECA<\/div>\n\t\t<ul class=\"sched-list-column-events\">\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/el-juego-de-ripley\/\" data-event-id=\"561\" style=\"background: #fa983a;\" data-color=\"#fa983a\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fa983a;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tEL JUEGO DE RIPLEY 110&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">18:00 - 19:45<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t\t\t\t<li class=\"sched-list-event-li\">\n\t\t\t\t<a class=\" sched-list-event sched-list-event-has-background\" href=\"https:\/\/lamostradevalencia.com\/peliculas\/berlin-interior\/\" data-event-id=\"560\" style=\"background: #fa983a;\" data-color=\"#fa983a\">\t\t\t\t\t<div class=\"sched-list-event-color\" style=\"background: #fa983a;\"><\/div>\n\t\t\t\t\t<div class=\"sched-list-event-text\">\n\t\t\t\t\t\t<div class=\"sched-list-event-title\">\n\t\t\t\t\t\t\tBERL\u00cdN INTERIOR 110&#039;\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"sched-list-event-description\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"sched-list-event-time\">20:15 - 22:00<\/div>\n\t\t\t\t<\/a>\n\t\t\t<\/li>\n\t\t\t<!-- .sched-list-event-li -->\n\t\t<\/ul>\n\t<\/div>\n\t<!-- .sched-list-column -->\n\t\n<\/div>[\/vc_column][\/vc_row][vc_row disable_element=&#8221;yes&#8221; css=&#8221;.vc_custom_1600188434518{padding-right: 40px !important;padding-bottom: 50px !important;padding-left: 40px !important;}&#8221; anchor=&#8221;programa&#8221;][vc_column][vc_separator css=&#8221;.vc_custom_1539270997760{padding-bottom: 50px !important;}&#8221;][vc_column_text]<\/p>\n<h5>Si lo prefieres puedes descargar el folleto con la programaci\u00f3n aqu\u00ed<\/h5>\n<p>[\/vc_column_text][vc_single_image image=&#8221;6896&#8243; img_size=&#8221;full&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221; link=&#8221;https:\/\/lamostradevalencia.com\/graella-mostra-programa-mano\/&#8221;][\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"templatera_shortcode\"><style type=\"text\/css\" data-type=\"vc_shortcodes-default-css\">.vc_do_custom_heading{margin-bottom:0.625rem;margin-top:0;}<\/style><style type=\"text\/css\" data-type=\"vc_shortcodes-custom-css\">.vc_custom_1600184094996{padding-top: 100px !important;padding-bottom: 100px !important;}<\/style><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1600184094996\" ><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><h2 style=\"text-align: center\" class=\"vc_custom_heading vc_do_custom_heading\" >Coming soon...<\/h2><\/div><\/div><\/div><\/div><\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"Coming soon...","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"full-width.php","meta":{"_uag_custom_page_level_css":"","_jet_sm_ready_style":"","_jet_sm_style":"","_jet_sm_controls_values":"","_jet_sm_fonts_collection":"","_jet_sm_fonts_links":"","footnotes":""},"class_list":["post-6894","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0627\u0644\u0628\u0631\u0646\u0627\u0645\u062c - Mostra de Val\u00e8ncia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lamostradevalencia.com\/ar\/%d8%a7%d9%84%d8%a8%d8%b1%d9%86%d8%a7%d9%85%d8%ac\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0627\u0644\u0628\u0631\u0646\u0627\u0645\u062c - Mostra de Val\u00e8ncia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lamostradevalencia.com\/ar\/%d8%a7%d9%84%d8%a8%d8%b1%d9%86%d8%a7%d9%85%d8%ac\/\" \/>\n<meta property=\"og:site_name\" content=\"Mostra de Val\u00e8ncia\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-15T16:47:27+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u062f\u0642\u064a\u0642\u062a\u0627\u0646\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lamostradevalencia.com\\\/ar\\\/%d8%a7%d9%84%d8%a8%d8%b1%d9%86%d8%a7%d9%85%d8%ac\\\/\",\"url\":\"https:\\\/\\\/lamostradevalencia.com\\\/ar\\\/%d8%a7%d9%84%d8%a8%d8%b1%d9%86%d8%a7%d9%85%d8%ac\\\/\",\"name\":\"\u0627\u0644\u0628\u0631\u0646\u0627\u0645\u062c - Mostra de Val\u00e8ncia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lamostradevalencia.com\\\/ar\\\/#website\"},\"datePublished\":\"2018-10-03T16:24:38+00:00\",\"dateModified\":\"2020-09-15T16:47:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lamostradevalencia.com\\\/ar\\\/%d8%a7%d9%84%d8%a8%d8%b1%d9%86%d8%a7%d9%85%d8%ac\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lamostradevalencia.com\\\/ar\\\/%d8%a7%d9%84%d8%a8%d8%b1%d9%86%d8%a7%d9%85%d8%ac\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lamostradevalencia.com\\\/ar\\\/%d8%a7%d9%84%d8%a8%d8%b1%d9%86%d8%a7%d9%85%d8%ac\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/lamostradevalencia.com\\\/ar\\\/?page_id=30956\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0627\u0644\u0628\u0631\u0646\u0627\u0645\u062c\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lamostradevalencia.com\\\/ar\\\/#website\",\"url\":\"https:\\\/\\\/lamostradevalencia.com\\\/ar\\\/\",\"name\":\"Mostra de Val\u00e8ncia\",\"description\":\"Cinema del Mediterrani\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lamostradevalencia.com\\\/ar\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0627\u0644\u0628\u0631\u0646\u0627\u0645\u062c - Mostra de Val\u00e8ncia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lamostradevalencia.com\/ar\/%d8%a7%d9%84%d8%a8%d8%b1%d9%86%d8%a7%d9%85%d8%ac\/","og_locale":"ar_AR","og_type":"article","og_title":"\u0627\u0644\u0628\u0631\u0646\u0627\u0645\u062c - Mostra de Val\u00e8ncia","og_url":"https:\/\/lamostradevalencia.com\/ar\/%d8%a7%d9%84%d8%a8%d8%b1%d9%86%d8%a7%d9%85%d8%ac\/","og_site_name":"Mostra de Val\u00e8ncia","article_modified_time":"2020-09-15T16:47:27+00:00","twitter_card":"summary_large_image","twitter_misc":{"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631":"\u062f\u0642\u064a\u0642\u062a\u0627\u0646"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lamostradevalencia.com\/ar\/%d8%a7%d9%84%d8%a8%d8%b1%d9%86%d8%a7%d9%85%d8%ac\/","url":"https:\/\/lamostradevalencia.com\/ar\/%d8%a7%d9%84%d8%a8%d8%b1%d9%86%d8%a7%d9%85%d8%ac\/","name":"\u0627\u0644\u0628\u0631\u0646\u0627\u0645\u062c - Mostra de Val\u00e8ncia","isPartOf":{"@id":"https:\/\/lamostradevalencia.com\/ar\/#website"},"datePublished":"2018-10-03T16:24:38+00:00","dateModified":"2020-09-15T16:47:27+00:00","breadcrumb":{"@id":"https:\/\/lamostradevalencia.com\/ar\/%d8%a7%d9%84%d8%a8%d8%b1%d9%86%d8%a7%d9%85%d8%ac\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lamostradevalencia.com\/ar\/%d8%a7%d9%84%d8%a8%d8%b1%d9%86%d8%a7%d9%85%d8%ac\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/lamostradevalencia.com\/ar\/%d8%a7%d9%84%d8%a8%d8%b1%d9%86%d8%a7%d9%85%d8%ac\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lamostradevalencia.com\/ar\/?page_id=30956"},{"@type":"ListItem","position":2,"name":"\u0627\u0644\u0628\u0631\u0646\u0627\u0645\u062c"}]},{"@type":"WebSite","@id":"https:\/\/lamostradevalencia.com\/ar\/#website","url":"https:\/\/lamostradevalencia.com\/ar\/","name":"Mostra de Val\u00e8ncia","description":"Cinema del Mediterrani","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lamostradevalencia.com\/ar\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"cinerama_edge_image_square":false,"cinerama_edge_image_landscape":false,"cinerama_edge_image_portrait":false,"cinerama_edge_image_huge":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"Mostra de Val\u00e8ncia","author_link":"https:\/\/lamostradevalencia.com\/ar\/author\/mostravalencia\/"},"uagb_comment_info":0,"uagb_excerpt":null,"_links":{"self":[{"href":"https:\/\/lamostradevalencia.com\/ar\/wp-json\/wp\/v2\/pages\/6894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lamostradevalencia.com\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lamostradevalencia.com\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lamostradevalencia.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lamostradevalencia.com\/ar\/wp-json\/wp\/v2\/comments?post=6894"}],"version-history":[{"count":4,"href":"https:\/\/lamostradevalencia.com\/ar\/wp-json\/wp\/v2\/pages\/6894\/revisions"}],"predecessor-version":[{"id":7469,"href":"https:\/\/lamostradevalencia.com\/ar\/wp-json\/wp\/v2\/pages\/6894\/revisions\/7469"}],"wp:attachment":[{"href":"https:\/\/lamostradevalencia.com\/ar\/wp-json\/wp\/v2\/media?parent=6894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}